{"id":9003,"date":"2016-07-21T11:07:23","date_gmt":"2016-07-21T09:07:23","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=9003"},"modified":"2017-02-07T12:05:06","modified_gmt":"2017-02-07T10:05:06","slug":"bien-choisir-son-ile-en-thailande","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande","title":{"rendered":"Bien choisir son \u00eele en Tha\u00eflande"},"content":{"rendered":"<p>La Tha\u00eflande poss\u00e8de des centaines d&#8217;\u00eeles plus ou moins grandes, plus ou moins habit\u00e9es, plus ou moins touristiques. Les plus connues trustent souvent les premi\u00e8res places dans les classements des plus belles \u00eeles du monde. <strong>Mais comment choisir parmi\u00a0ce large choix<\/strong> ? Cela d\u00e9pend de ce que vous cherchez et de la m\u00e9t\u00e9o \u00e0 l&#8217;\u00e9poque o\u00f9 vous partez.<\/p>\n<figure id=\"attachment_4915\" aria-describedby=\"caption-attachment-4915\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4915\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan.jpg\" alt=\"Haad Rin Koh Phangan\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-4915\" class=\"wp-caption-text\">Koh Phangan<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Les \u00eeles pour faire la f\u00eate<\/h2>\n<p>La plus grande f\u00eate de Tha\u00eflande et une des plus importantes du monde, c&#8217;est la Full Moon Party qui se tient chaque mois sur l&#8217;\u00eele de <strong><a href=\"\/villes\/koh-phangan\">Koh Phangan<\/a><\/strong>. Organis\u00e9e en plein air sur la plage de Haad Rin, cette immense discoth\u00e8que en plein air rassemblent des milliers de f\u00eatards. Donc si vous aimez les grosses teufs, c&#8217;est l\u00e0 qu&#8217;il faut aller. Soyez tout de m\u00eame prudents, plus la nuit avance, plus les gens sont alcoolis\u00e9s et l\u2019ambiance moins bon enfant. Les 3-4 jours qui entourent l\u2019\u00e9v\u00e9nement, Koh Phangan est tr\u00e8s peupl\u00e9e et le reste du temps, l&#8217;\u00eele incroyablement\u00a0calme !<\/p>\n<p>Autre destination, pour faire la f\u00eate le soir sur la plage : <strong><a href=\"\/villes\/koh-phi-phi\">Koh Phi Phi<\/a><\/strong>. Chaque bar mets sa musique plus fort quand le soir approche et petit \u00e0 petit les deux plages qui entourent le village de Tonsa\u00ef se remplissent. On vient boire un coup, danser et nager en dansant. Et sur la plage de Loh Dalum, en fin d&#8217;apr\u00e8s-midi on peut observer de jolis couchers de soleil.<\/p>\n<p>Evidemment, il y a d&#8217;autres \u00eeles o\u00f9 l&#8217;on peut faire la f\u00eate, \u00e0 Koh Samui, surtout du c\u00f4t\u00e9 de Chaweng Beach\u00a0par exemple, sans oublier Phuket et sa rue tr\u00e8s anim\u00e9e \u00e0 Patong. Sinon, la plage de White Sands Beach \u00e0 Koh Chang est aussi sympathique le soir avec ses bars et restaurants sur la plage de m\u00eame que Sairee Beach \u00e0 Koh Tao qui s&#8217;anime chaque soir mais on y trouve moins de gens qui dansent sur la plage.<\/p>\n<p>&nbsp;<\/p>\n<h2>Les \u00eeles pour faire de la plong\u00e9e<\/h2>\n<p>Quand on parle de plong\u00e9e en Tha\u00eflande, le premier nom qui sort, c&#8217;est souvent\u00a0celui de Koh Tao. Et c&#8217;est vrai que l&#8217;\u00eele est d\u00e9di\u00e9e \u00e0 cette activit\u00e9 avec un nombre de clubs de plong\u00e9e au kilom\u00e8tre carr\u00e9 parmi les plus \u00e9lev\u00e9s de monde. C&#8217;est aussi son gros point faible. Id\u00e9ale pour les d\u00e9butants ou plongeurs peu exp\u00e9riment\u00e9s, Koh Tao plaira probablement moins aux pratiquants chevronn\u00e9s.<\/p>\n<p>Sa voisine Koh Phangan propose \u00e9galement des sorties plong\u00e9es int\u00e9ressantes notamment vers le parc marin de Ang Thong, un des plus beaux spots du pays (on peut aussi r\u00e9server cette sortie au d\u00e9part de Koh Samui ou Koh Tao).<\/p>\n<p>Sinon, <a href=\"\/villes\/koh-lanta\"><strong>Koh Lanta<\/strong><\/a> est aussi une destination plong\u00e9e en Tha\u00eflande int\u00e9ressante avec notamment un site exceptionnel pour les plongeurs exp\u00e9riment\u00e9s (car profond): <a href=\"\/a-voir\/plongee-a-koh-haa-koh-lanta-216\"><strong>Koh Haa et sa &#8220;cath\u00e9drale&#8221; sous-marine<\/strong><\/a>.<\/p>\n<p>A noter que ces derni\u00e8res ann\u00e9es, les autorit\u00e9s essaient de\u00a0cr\u00e9er des r\u00e9cifs artificiels notamment en coulant des navires comme c&#8217;est le cas \u00e0 <a href=\"\/villes\/koh-chang\">Koh Chang<\/a>. Cr\u00e9ant un site de plong\u00e9e hors du commun <em>(voir la vid\u00e9o ci-dessous)<\/em>.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/gvRwpSwHOlg?rel=0\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Bien s\u00fbr, on peut faire de la plong\u00e9e depuis beaucoup d&#8217;autres \u00eeles en Tha\u00eflande notamment \u00e0 Koh Phi Phi d&#8217;o\u00f9 l&#8217;on peut faire de superbes sorties snorkeling \u00e9galement.<\/p>\n<p>&nbsp;<\/p>\n<h2>Les \u00eeles peu d\u00e9velopp\u00e9es<\/h2>\n<p>Si vous cherchez \u00e0 vous couper un peu du monde lors de votre s\u00e9jour en Tha\u00eflande, il y a quelques \u00eeles que la modernit\u00e9 et les promoteurs touristiques ne sont pas encore venus d\u00e9ranger. Des \u00eeles o\u00f9 vous n&#8217;avez de l\u2019\u00e9lectricit\u00e9 que quelques heures le soir gr\u00e2ce aux panneaux solaires qui ont permis de l&#8217;accumuler dans la journ\u00e9e. Des \u00eeles, o\u00f9 il n&#8217;y a pas de 7 Eleven, oui, \u00e7a existe, pas d&#8217;ATM (distributeurs de billets), o\u00f9 internet est tr\u00e8s lent car par satellite et rarement propos\u00e9, o\u00f9 parfois m\u00eame par endroits, vous ne captez aucun r\u00e9seau t\u00e9l\u00e9phonique. Bref, des petits paradis pour qui veut\u00a0faire un break loin\u00a0du monde moderne. Parmi elles, se trouvent l&#8217;\u00eele de Koh Chang au large de Ranong (il y a 2 \u00eeles Koh Chang en Tha\u00eflande), <strong>Koh Jum<\/strong> au large de Krabi ou <strong>Koh Wa\u00ef<\/strong>, pr\u00e8s de l&#8217;autre Koh Chang, celles au large de Trang dont ma chouchoute <strong>Koh Sukorn<\/strong>.<\/p>\n<figure id=\"attachment_3976\" aria-describedby=\"caption-attachment-3976\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3976\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-chang-ranong-11.jpg\" alt=\"Iles peu touristique Tha\u00eflande\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-chang-ranong-11.jpg 700w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-chang-ranong-11-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-chang-ranong-11-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-3976\" class=\"wp-caption-text\">L&#8217;\u00eele de Koh Chang dans la province de Ranong<\/figcaption><\/figure>\n<p>Et dans une moindre mesure, car elle est un peu plus modernis\u00e9e, <strong>Koh Phayam<\/strong>\u00a0dans la province de Ranong, propose \u00e9galement une alternative sympathique mais avec un peu plus de &#8220;confort&#8221; que les 3 \u00eeles pr\u00e9c\u00e9demment cit\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<h2>Les \u00eeles proches de Bangkok<\/h2>\n<p>On peut \u00eatre \u00e0 Bangkok et avoir envie de partir rapidement pour une \u00eele aux eaux turquoises sans forc\u00e9ment partir trop loin. Pour \u00e7a, il y essentiellement 2 \u00eeles : <a href=\"\/villes\/koh-sichang\"><strong>Koh Sichang<\/strong><\/a> au large de Si Racha qui est une \u00eele encore assez sauvage, mais qui a le petit d\u00e9faut d&#8217;avoir souvent de grands porte-containers au large et <a href=\"\/villes\/koh-larn\"><strong>Koh Larn<\/strong><\/a> au large de <strong>Pattaya<\/strong> qui si on \u00e9vite la plage tr\u00e8s tr\u00e8s fr\u00e9quent\u00e9e de Tawaen, propose un cadre agr\u00e9able. Il faut compter 2 heures de route et 45 minutes de travers\u00e9e environ pour rejoindre chacune de ses \u00eeles. Enfin, un peu moins de route pour Koh Si Chang qui est plus pr\u00e8s.<\/p>\n<figure id=\"attachment_9007\" aria-describedby=\"caption-attachment-9007\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9007\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-larn-near-bangkok.jpg\" alt=\"koh larn\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-larn-near-bangkok.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-larn-near-bangkok-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-larn-near-bangkok-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-9007\" class=\"wp-caption-text\">Koh Larn<\/figcaption><\/figure>\n<p>Sinon, en poussant plus loin, on a <a href=\"\/villes\/koh-samet\">Koh Samet<\/a> au large de Rayong (3h de route) \u00a0et encore plus loin Koh Chang et notamment la charmante Koh Kood et ses voisines au large de Trang (5h de route).<\/p>\n<p>&nbsp;<\/p>\n<h2>Les \u00eeles pour les vacances d&#8217;\u00e9t\u00e9<\/h2>\n<p>Vous aurez peut-\u00eatre envie de profiter de vos vacances de juillet-ao\u00fbt pour partir en Tha\u00eflande et envie de <strong>profiter de la plage et des \u00eeles<\/strong>. A cette p\u00e9riode de l&#8217;ann\u00e9e, en pleine saison des pluies, les \u00eeles du Sud, dans la r\u00e9gion de Krabi, Trang et Phuket, sont plut\u00f4t d\u00e9conseill\u00e9es car souvent tr\u00e8s arros\u00e9es. Par contre, la m\u00e9t\u00e9o est bien plus favorable dans le Golfe de Tha\u00eflande. En juillet-ao\u00fbt, il est donc pr\u00e9f\u00e9rable d&#8217;aller \u00e0\u00a0<a href=\"\/villes\/koh-samui\"><strong>Koh Samui<\/strong><\/a>, Koh Phangan et Koh Tao.<\/p>\n<figure id=\"attachment_7511\" aria-describedby=\"caption-attachment-7511\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7511\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ko-samui-big-buddha-pier-1.jpg\" alt=\"plages koh samui\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ko-samui-big-buddha-pier-1.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ko-samui-big-buddha-pier-1-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ko-samui-big-buddha-pier-1-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-7511\" class=\"wp-caption-text\">Koh Samui<\/figcaption><\/figure>\n<p>Ces \u00eeles sont par contre \u00e0 leur tour assez arros\u00e9es en octobre-novembre-d\u00e9cembre.<\/p>\n<p>&nbsp;<\/p>\n<h2>Les petites \u00eeles charmantes de Trang<\/h2>\n<p>Moins connues, quoique leur popularit\u00e9 est grandissante, les \u00eeles au large de <strong>Trang, Koh Mook, Koh Libong, Koh Kradan ou Koh Ngai<\/strong>, offrent une alternative charmante et plus conviviale\u00a0aux \u00eeles tr\u00e8s touristiques des provinces voisines de Krabi et Phuket.<\/p>\n<p>&nbsp;<\/p>\n<h2>Comment rejoindre les \u00eeles ?<\/h2>\n<p>Au d\u00e9part de Bangkok, notamment depuis Khao San Road, il existe des formules bus + bateau vers les \u00eeles du Golfe de Tha\u00eflande. Vous pouvez notamment r\u00e9server en ligne via ce moteur de recherche.<\/p>\n<p><script src=\"http:\/\/agent.12go.asia\/tools\/form\/fr\/\" async=\"\" defer=\"defer\" data-one2go=\"1332\" data-hidelogo=\"1\" data-width=\"100%; w:0\" data-height=\"150\" data-border=\"1\" data-radius=\"10\" data-origin=\"Bangkok\" data-destination=\"Koh Samui\"><\/script><\/p>\n<p>Sinon, Air Asia et Nok Air propose des vols + ferry. Pour les \u00eeles du Sud mieux vaut prendre l&#8217;avion jusqu&#8217;\u00e0 Phuket, Krabi ou Trang.<\/p>\n<p>Evidemment, il s&#8217;agit de g\u00e9n\u00e9ralit\u00e9s, il y a bien d&#8217;autres \u00eeles comme la charmante mais de plus en plus touristique <strong>Koh Lipe<\/strong>, d&#8217;autres \u00eeles tr\u00e8s sympathiques dans la baie de Phang Nga, la petite Koh Talu, au large de Bang Saphan et m\u00eame une \u00eele \u00e0 c\u00f4t\u00e9 de Bangkok, si si ! L&#8217;\u00eele de <strong>Koh Kret<\/strong>, une bouff\u00e9e d&#8217;oxyg\u00e8ne d\u00e9paysante quand on veut s&#8217;\u00e9chapper de la capitale (mais pas une destination pour se baigner car autour c&#8217;est le fleuve Chao Phraya et pas la mer).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Tha\u00eflande poss\u00e8de des centaines d&#8217;\u00eeles plus ou moins grandes, plus ou moins habit\u00e9es, plus<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-9003","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bien choisir son \u00eele en Tha\u00eflande<\/title>\n<meta name=\"description\" content=\"Comment choisir sur quelle \u00eele s\u00e9journer lors de votre voyage en Tha\u00eflande. On vous donne quelques conseils selon vos go\u00fbts et selon la m\u00e9t\u00e9o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bien choisir son \u00eele en Tha\u00eflande\" \/>\n<meta property=\"og:description\" content=\"Comment choisir sur quelle \u00eele s\u00e9journer lors de votre voyage en Tha\u00eflande. On vous donne quelques conseils selon vos go\u00fbts et selon la m\u00e9t\u00e9o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-21T09:07:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-07T10:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bien choisir son \u00eele en Tha\u00eflande","description":"Comment choisir sur quelle \u00eele s\u00e9journer lors de votre voyage en Tha\u00eflande. On vous donne quelques conseils selon vos go\u00fbts et selon la m\u00e9t\u00e9o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande","og_locale":"fr_FR","og_type":"article","og_title":"Bien choisir son \u00eele en Tha\u00eflande","og_description":"Comment choisir sur quelle \u00eele s\u00e9journer lors de votre voyage en Tha\u00eflande. On vous donne quelques conseils selon vos go\u00fbts et selon la m\u00e9t\u00e9o.","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2016-07-21T09:07:23+00:00","article_modified_time":"2017-02-07T10:05:06+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Bien choisir son \u00eele en Tha\u00eflande","datePublished":"2016-07-21T09:07:23+00:00","dateModified":"2017-02-07T10:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande"},"wordCount":1328,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande","url":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande","name":"Bien choisir son \u00eele en Tha\u00eflande","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan.jpg","datePublished":"2016-07-21T09:07:23+00:00","dateModified":"2017-02-07T10:05:06+00:00","description":"Comment choisir sur quelle \u00eele s\u00e9journer lors de votre voyage en Tha\u00eflande. On vous donne quelques conseils selon vos go\u00fbts et selon la m\u00e9t\u00e9o.","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/haad-rin-phangan.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/9003-bien-choisir-son-ile-en-thailande#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Bien choisir son \u00eele en Tha\u00eflande"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=9003"}],"version-history":[{"count":6,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9003\/revisions"}],"predecessor-version":[{"id":10352,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9003\/revisions\/10352"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=9003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=9003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=9003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}