{"id":8982,"date":"2016-07-15T09:08:53","date_gmt":"2016-07-15T07:08:53","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=8982"},"modified":"2016-07-15T09:19:03","modified_gmt":"2016-07-15T07:19:03","slug":"bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain","title":{"rendered":"Bangkok &#8211; Chiang Mai: des trains express flambant neufs le mois prochain"},"content":{"rendered":"<p>Cela faisait\u00a0longtemps qu&#8217;on en entendait parler mais cette fois, \u00e7a y est, une partie des nouveaux trains express de fabrication chinoise a\u00a0\u00e9t\u00e9 livr\u00e9e \u00e0 la Tha\u00eflande. L&#8217;occasion de vous les faire d\u00e9couvrir en photos avant leur mise en circulation prochaine.<\/p>\n<figure style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train2.jpg\" alt=\"nouveaux trains thailande\" width=\"800\" height=\"532\" \/><figcaption class=\"wp-caption-text\">Les nouveaux trains tha\u00eelandais seront plus beaux, plus modernes, moins bruyants et plus&#8230; rouges<\/figcaption><\/figure>\n<p>\u00c0 partir du mois prochain (ao\u00fbt), les <a href=\"\/transports\/train-thailande\">trains en Tha\u00eflande<\/a> vont commencer \u00e0 se moderniser avec l&#8217;arriv\u00e9e de ces nouvelles rames sur la ligne la plus fr\u00e9quent\u00e9e du pays, celle qui relie Bangkok \u00e0 Chiang Mai. Ces nouveaux trains express, s&#8217;ils sont plus confortables, ne seront pas plus rapides que leurs homologues vieillissants (il faudrait probablement moderniser les voies).\u00a0<\/p>\n<p>En effet, la compagnie des\u00a0chemins de fer d&#8217;Etat de Tha\u00eflande (SRT) a annonc\u00e9 hier\u00a0qu&#8217;elle a re\u00e7u 39 des 115 nouvelles voitures chinoises destin\u00e9es\u00a0aux itin\u00e9raires des trains express reliant Bangkok \u00e0 Chiang Mai, Ubon Ratchathani, Nong Khai et Hat Yai.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train3.jpg\" alt=\"trains bangkok chiang mai\" \/><\/p>\n<p>Le moteur des locomotives sera moins bruyant et moins polluant, les toilettes, qui n&#8217;ont jamais \u00e9t\u00e9 le point fort des <strong>trains en Tha\u00eflande<\/strong>,\u00a0utiliseront le m\u00eame syst\u00e8me que ceux des avions.\u00a0Les voitures seront \u00e9galement \u00e9quip\u00e9es de cam\u00e9ras de s\u00e9curit\u00e9 et d&#8217;ascenseurs pour \u00e9lever des fauteuils roulants \u00e0 partir du quai. Le personnel aura aussi de nouveaux uniformes\u00a0assortis \u00e0 la d\u00e9coration int\u00e9rieure des nouveaux trains<\/p>\n<figure style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train5.jpg\" alt=\"trains thailande\" width=\"800\" height=\"531\" \/><figcaption class=\"wp-caption-text\">Les nouveaux uniformes (photos: <a href=\"http:\/\/www.khaosodenglish.com\/\">khaosodenglish.com<\/a>)<\/figcaption><\/figure>\n<p>L&#8217;achat de ces\u00a0nouvelles voitures a co\u00fbt\u00e9\u00a0environ 4 milliards de bahts.<\/p>\n<p>&nbsp;<\/p>\n<h2>R\u00e9server votre billet de train en Tha\u00eflande<\/h2>\n<p>Difficile de savoir si ces nouveaux trains vont entra\u00eener un engouement suppl\u00e9mentaire lors de leur lancement, attirant les curieux, mais si vous pr\u00e9voyez un trajet en <a href=\"\/transports\/train\/trains-de-bangkok-a-chiang-mai\">train de Bangkok \u00e0 Chiang Mai<\/a> en ao\u00fbt, il sera peut-\u00eatre pr\u00e9f\u00e9rable d&#8217;acheter vos billets un peu \u00e0 l&#8217;avance (ce qui est d\u00e9j\u00e0 conseill\u00e9 \u00e0 l&#8217;heure actuelle pour les trains de nuit) soit en gare, soit en r\u00e9servant en ligne <em>(voir ci-dessous)<\/em>.<\/p>\n<p><script src=\"http:\/\/agent.12go.asia\/tools\/form\/fr\/\" async=\"\" defer=\"defer\" data-one2go=\"1332\" data-hidelogo=\"1\" data-width=\"100%; w:0\" data-height=\"150\" data-border=\"1\" data-radius=\"10\" data-origin=\"Bangkok\" data-destination=\"Chiang Mai\"><\/script><\/p>\n<p>Bien que le porte-parole des chemins de fer de l&#8217;Etat a indiqu\u00e9\u00a0qu&#8217;il n&#8217;y avait pas de plan pr\u00e9cis, il esp\u00e8re que les 39 premi\u00e8res voitures circuleront sur\u00a0les rails de la<strong> route Bangkok-Chiang Mai au mois d&#8217;ao\u00fbt<\/strong>.\u00a0<\/p>\n<p>Attention, \u00e7a ne veut pas dire que si vous prenez le train de Bangkok \u00e0 Chiang Mai en ao\u00fbt, vous aurez forc\u00e9ment droit \u00e0 ces wagons modernes. Il faut encore avoir le bon billet, il ne s&#8217;agit que des trains express et rien ne dit que tous seront remplac\u00e9s tout de suite. Mais vous aurez peut-\u00eatre la surprise de vous retrouver dans un train flambant neuf.<\/p>\n<p>Bonne ou mauvaise surprise selon que vous \u00eates nostalgiques des anciens trains.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cela faisait\u00a0longtemps qu&#8217;on en entendait parler mais cette fois, \u00e7a y est, une partie des<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-8982","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bangkok - Chiang Mai: des trains express flambant neufs le mois prochain<\/title>\n<meta name=\"description\" content=\"Les nouveaux trains express vont \u00eatre mis en circulation au mois d&#039;ao\u00fbt sur la ligne Bangkok - Chiang Mai. Une modernisation des trains en Tha\u00eflande.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bangkok - Chiang Mai: des trains express flambant neufs le mois prochain\" \/>\n<meta property=\"og:description\" content=\"Les nouveaux trains express vont \u00eatre mis en circulation au mois d&#039;ao\u00fbt sur la ligne Bangkok - Chiang Mai. Une modernisation des trains en Tha\u00eflande.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-15T07:08:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-15T07:19:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train2.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bangkok - Chiang Mai: des trains express flambant neufs le mois prochain","description":"Les nouveaux trains express vont \u00eatre mis en circulation au mois d'ao\u00fbt sur la ligne Bangkok - Chiang Mai. Une modernisation des trains en Tha\u00eflande.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain","og_locale":"fr_FR","og_type":"article","og_title":"Bangkok - Chiang Mai: des trains express flambant neufs le mois prochain","og_description":"Les nouveaux trains express vont \u00eatre mis en circulation au mois d'ao\u00fbt sur la ligne Bangkok - Chiang Mai. Une modernisation des trains en Tha\u00eflande.","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2016-07-15T07:08:53+00:00","article_modified_time":"2016-07-15T07:19:03+00:00","og_image":[{"url":"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train2.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Bangkok &#8211; Chiang Mai: des trains express flambant neufs le mois prochain","datePublished":"2016-07-15T07:08:53+00:00","dateModified":"2016-07-15T07:19:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain"},"wordCount":483,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain#primaryimage"},"thumbnailUrl":"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train2.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain","url":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain","name":"Bangkok - Chiang Mai: des trains express flambant neufs le mois prochain","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain#primaryimage"},"thumbnailUrl":"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train2.jpg","datePublished":"2016-07-15T07:08:53+00:00","dateModified":"2016-07-15T07:19:03+00:00","description":"Les nouveaux trains express vont \u00eatre mis en circulation au mois d'ao\u00fbt sur la ligne Bangkok - Chiang Mai. Une modernisation des trains en Tha\u00eflande.","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain#primaryimage","url":"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train2.jpg","contentUrl":"http:\/\/www.khaosodenglish.com\/wp-content\/uploads\/2016\/07\/Train2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8982-bangkok-chiang-mai-des-trains-express-flambant-neufs-le-mois-prochain#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Bangkok &#8211; Chiang Mai: des trains express flambant neufs le mois prochain"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=8982"}],"version-history":[{"count":6,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8982\/revisions"}],"predecessor-version":[{"id":8988,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8982\/revisions\/8988"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=8982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=8982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=8982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}