{"id":8942,"date":"2016-07-09T09:18:33","date_gmt":"2016-07-09T07:18:33","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=8942"},"modified":"2016-07-09T09:21:40","modified_gmt":"2016-07-09T07:21:40","slug":"ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok","title":{"rendered":"O\u00f9 regarder la finale de l&#8217;Euro 2016 France &#8211; Portugal \u00e0 Bangkok ?"},"content":{"rendered":"<p>Demain, <strong>c&#8217;est la finale de l&#8217;Euro 2016 au Stade de France<\/strong> et si peu auraient mis\u00e9 sur une pr\u00e9sence de l&#8217;\u00e9quipe de France \u00e0 ce stade de la comp\u00e9tition, les joueurs de Didier Deschamps seront bien l\u00e0 et au vu de ce qu&#8217;ils ont montr\u00e9 lors des deux derniers matchs, tous les espoirs sont permis. Certains d&#8217;entre vous sont peut-\u00eatre \u00e0 Bangkok en ce moment et se demandent o\u00f9 aller voir le match pour avoir un peu plus d&#8217;ambiance que leur chambre d&#8217;h\u00f4tel ou leur condo ? Je vous fais quelques suggestions&#8230;<\/p>\n<figure id=\"attachment_8944\" aria-describedby=\"caption-attachment-8944\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8944\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal.jpg\" alt=\"euro 2016 france portugual\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-8944\" class=\"wp-caption-text\">La finale opposera la France au Portugal. Coup d&#8217;envoi 2h (heure tha\u00efe)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>Regarder la finale de l&#8217;Euro 2016 \u00e0 l&#8217;Alliance Frna\u00e7aise de Bangkok<\/h2>\n<p>L\u2019Alliance Fran\u00e7aise de Bangkok sera exceptionnellement ouverte dans la nuit de dimanche \u00e0 lundi et projettera le match en direct \u00e0 2h du matin (heure locale du coup d&#8217;envoi) . Entr\u00e9e libre.<\/p>\n<figure id=\"attachment_8943\" aria-describedby=\"caption-attachment-8943\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8943\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/france-portugal-finale-euro-2016-bangkok-750x278.jpg\" alt=\"finale euro 2016 france\" width=\"750\" height=\"278\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/france-portugal-finale-euro-2016-bangkok-750x278.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/france-portugal-finale-euro-2016-bangkok-624x231.jpg 624w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/france-portugal-finale-euro-2016-bangkok.jpg 851w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-8943\" class=\"wp-caption-text\">Venez vivre la finale de l&#8217;Euro 2016 \u00e0 l\u2019Alliance Fran\u00e7aise de Bangkok<\/figcaption><\/figure>\n<p>Vous pourrez \u00e9galement acheter \u00e0 manger et \u00e0 boire, un menu sera propos\u00e9 par le caf\u00e9 de l&#8217;Alliance, le Caf\u00e9 1912.\u00a0<\/p>\n<p><em>N&#8217;h\u00e9sitez pas \u00e0 vous inscrire sur Facebook :\u00a0<a href=\"https:\/\/www.facebook.com\/events\/262024300856072\/\" target=\"_blank\" rel=\"nofollow\">https:\/\/www.facebook.com\/events\/262024300856072\/<\/a><\/em><\/p>\n<p>Pour rappel, voici l&#8217;adresse de l&#8217;Alliance Fran\u00e7aise de Bangkok (proche du parc Lumphini):<br \/><em>179 Thanon Witthayu, Lumpini, Pathum Wan, Bangkok 10330<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Regarder le match au\u00a0Novotel Bangkok Sukhumvit<\/h2>\n<p>L&#8217;h\u00f4tel Novotel de Sukhumvit propose \u00e9galement une projection de la finale en direct. L&#8217;entr\u00e9e est gratuite (il est conseill\u00e9 de venir \u00e0 partir d&#8217;1h30). Il y aura de la bi\u00e8re (payante) pour vous d\u00e9salt\u00e9rer lorsque vous aurez la gorge s\u00e8che \u00e0 force de crier pour encourager les Bleus (ou les Portugais).<\/p>\n<p><em>Le <a href=\"http:\/\/www.booking.com\/hotel\/th\/novotel-bangkok-sukhumvit-20.fr.html?aid=370734\" target=\"_blank\" rel=\"nofollow\">Novotel Bangkok Sukhumvit<\/a> se trouve sur\u00a0Sukhumvit Soi 20 \u00a0station BTS Phrom Phong\u00a0ou\u00a0MRT Asok (<a href=\"http:\/\/www.booking.com\/hotel\/th\/novotel-bangkok-sukhumvit-20.fr.html?aid=370734\" target=\"_blank\" rel=\"nofollow\">voir lur la carte<\/a>)<\/em><\/p>\n<p>Il semble que le Novotel Ploenchit propose aussi de suivre la finale dans son Dee lounge.<\/p>\n<p>&nbsp;<\/p>\n<p>Evidemment de nombreux bars et pubs de Bangkok diffuseront cette finale en live. Tous ferment exceptionnellement plus tard que leur horaire habituel (2h du matin) pour accueillir les fans de foot.<\/p>\n<p>On esp\u00e8re que ce sera un grand match, avec un grand Antoine Griezmann et un grand Christiano Ronaldo et que le meilleur gagne. M\u00eame si \u00e9videmment, je supporte les Bleus \ud83d\ude09<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Demain, c&#8217;est la finale de l&#8217;Euro 2016 au Stade de France et si peu auraient<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-8942","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O\u00f9 regarder la finale de l&#039;Euro 2016 France - Portugal \u00e0 Bangkok ?<\/title>\n<meta name=\"description\" content=\"Certains d&#039;entre vous sont peut-\u00eatre \u00e0 Bangkok en ce moment et se demandent o\u00f9 aller voir la finale de l&#039;Euro 2016 qui opposera la France au Portugual ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O\u00f9 regarder la finale de l&#039;Euro 2016 France - Portugal \u00e0 Bangkok ?\" \/>\n<meta property=\"og:description\" content=\"Certains d&#039;entre vous sont peut-\u00eatre \u00e0 Bangkok en ce moment et se demandent o\u00f9 aller voir la finale de l&#039;Euro 2016 qui opposera la France au Portugual ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-09T07:18:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-09T07:21:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O\u00f9 regarder la finale de l'Euro 2016 France - Portugal \u00e0 Bangkok ?","description":"Certains d'entre vous sont peut-\u00eatre \u00e0 Bangkok en ce moment et se demandent o\u00f9 aller voir la finale de l'Euro 2016 qui opposera la France au Portugual ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok","og_locale":"fr_FR","og_type":"article","og_title":"O\u00f9 regarder la finale de l'Euro 2016 France - Portugal \u00e0 Bangkok ?","og_description":"Certains d'entre vous sont peut-\u00eatre \u00e0 Bangkok en ce moment et se demandent o\u00f9 aller voir la finale de l'Euro 2016 qui opposera la France au Portugual ?","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2016-07-09T07:18:33+00:00","article_modified_time":"2016-07-09T07:21:40+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"O\u00f9 regarder la finale de l&#8217;Euro 2016 France &#8211; Portugal \u00e0 Bangkok ?","datePublished":"2016-07-09T07:18:33+00:00","dateModified":"2016-07-09T07:21:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok"},"wordCount":401,"commentCount":2,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok","url":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok","name":"O\u00f9 regarder la finale de l'Euro 2016 France - Portugal \u00e0 Bangkok ?","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal.jpg","datePublished":"2016-07-09T07:18:33+00:00","dateModified":"2016-07-09T07:21:40+00:00","description":"Certains d'entre vous sont peut-\u00eatre \u00e0 Bangkok en ce moment et se demandent o\u00f9 aller voir la finale de l'Euro 2016 qui opposera la France au Portugual ?","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/finale-euro-2016-france-portugal.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8942-ou-regarder-la-finale-euro-2016-france-portugal-a-bangkok#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"O\u00f9 regarder la finale de l&#8217;Euro 2016 France &#8211; Portugal \u00e0 Bangkok ?"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=8942"}],"version-history":[{"count":2,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8942\/revisions"}],"predecessor-version":[{"id":8946,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8942\/revisions\/8946"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=8942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=8942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=8942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}