{"id":8390,"date":"2016-03-27T15:24:50","date_gmt":"2016-03-27T13:24:50","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=8390"},"modified":"2016-03-27T15:36:07","modified_gmt":"2016-03-27T13:36:07","slug":"faut-pas-rever-thailande","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande","title":{"rendered":"Faut pas r\u00eaver en Tha\u00eflande, le 1er avril sur France 3"},"content":{"rendered":"<p>Voil\u00e0 qui va nous changer des reportages de M6. France 3 consacrera le\u00a0prochain num\u00e9ro de\u00a0son \u00e9mission &#8220;Faut par r\u00eaver&#8221; \u00e0 la Tha\u00eflande avec Philippe Gougler aux manettes. Le teaser a \u00e9t\u00e9 d\u00e9voil\u00e9 il y a quelques jours et \u00e7a donne envie !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8392\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande.jpg\" alt=\"faut pas rever thailande\" width=\"747\" height=\"421\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande.jpg 747w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande-600x338.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande-624x352.jpg 624w\" sizes=\"auto, (max-width: 747px) 100vw, 747px\" \/><\/p>\n<h2>Voici le descriptif de l&#8217;\u00e9mission par France 3<\/h2>\n<p><em>R\u00e9put\u00e9e pour ses plages paradisiaques, la Tha\u00eflande offre plein d\u2019autres surprises. Philippe Gougler nous emm\u00e8ne hors des sentiers battus d\u00e9couvrir un pays \u00e0 la nature extravagante, \u00e0 la rencontre d\u2019habitants fiers de leur culture et de leur patrimoine fortement influenc\u00e9s par les dynasties royales successives.<\/em><\/p>\n<p><em>Au cours de ses rencontres, Philippe Gougler nous fait d\u00e9couvrir Bangkok, capitale gigantesque, moderne et traditionnelle \u00e0 la fois. Puis dans le nord du pays, c\u2019est avec une famille de l\u2019ethnie Karen qu\u2019il nous entra\u00eene dans une chasse insolite : la capture de grillons qui termineront en fricass\u00e9e, sp\u00e9cialit\u00e9 gastronomique locale ! Dans un temple non loin de l\u00e0, moines et fid\u00e8les nous initient \u00e0 une c\u00e9r\u00e9monie insolite : le \u00ab nettoyage de karma \u00bb.<\/em><\/p>\n<p>&nbsp;<\/p>\n<div class=\"fb-video\" data-href=\"https:\/\/www.facebook.com\/emission.fautpasrever\/videos\/1020764828005139\/\" data-width=\"750\">\n<div class=\"fb-xfbml-parse-ignore\">\n<blockquote cite=\"https:\/\/www.facebook.com\/emission.fautpasrever\/videos\/1020764828005139\/\"><p><a href=\"https:\/\/www.facebook.com\/emission.fautpasrever\/videos\/1020764828005139\/\">Faut pas r\u00eaver en Tha\u00eflande &#8211; Teaser<\/a><\/p>\n<\/blockquote>\n<\/div>\n<\/div>\n<p><em>Les reportages mettent l\u2019accent sur la beaut\u00e9 des paysages et l\u2019engagement des habitants. Une passionn\u00e9e d\u2019oiseaux sillonne le pays et ses nombreuses \u00eeles, \u00e0 la recherche d\u2019esp\u00e8ces rares. Les habitants du Parc national de Khao Sok d\u00e9voilent fi\u00e8rement ce tr\u00e9sor naturel, un des lieux les plus extraordinaires et sauvages de Tha\u00eflande. Dans les khlongs, canaux paisibles au c\u0153ur de Bangkok, la vie se d\u00e9roule au fil de l\u2019eau, \u00e0 l\u2019abri de la fr\u00e9n\u00e9sie de la capitale. Dans ce pays o\u00f9 l\u2019\u00e9l\u00e9phant est l\u2019embl\u00e8me de la royaut\u00e9, une femme tr\u00e8s engag\u00e9e se bat pour am\u00e9liorer les conditions de vie des pachydermes. Enfin \u00e0 Chiang Mai, nous assistons \u00e0 un spectacle \u00e9blouissant : le plus grand l\u00e2cher de lanternes de toute l\u2019Asie.<\/em><\/p>\n<p>Vous avez d&#8217;autres extraits sur le <a href=\"http:\/\/www.france3.fr\/emissions\/faut-pas-rever\/diffusions\/01-04-2016_465015\" target=\"_blank\">site de France 3.<\/a><\/p>\n<p><em><strong>Faut pas r\u00eaver<\/strong><\/em><br \/><em>France 3<\/em><br \/><em>Vendredi 1er avril 2016 \u00e0 20h55<\/em><\/p>\n<p><script src=\"https:\/\/www.hotelscombined.fr\/SearchBox\/322101\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voil\u00e0 qui va nous changer des reportages de M6. France 3 consacrera le\u00a0prochain num\u00e9ro de\u00a0son<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-8390","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faut pas r\u00eaver en Tha\u00eflande, le 1er avril sur France 3<\/title>\n<meta name=\"description\" content=\"Teaser de l&#039;\u00e9mission &quot;Faut pas r\u00eaver&quot; du 1er avril qui sera consacr\u00e9e \u00e0 la Tha\u00eflande\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faut pas r\u00eaver en Tha\u00eflande, le 1er avril sur France 3\" \/>\n<meta property=\"og:description\" content=\"Teaser de l&#039;\u00e9mission &quot;Faut pas r\u00eaver&quot; du 1er avril qui sera consacr\u00e9e \u00e0 la Tha\u00eflande\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-27T13:24:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-27T13:36:07+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faut pas r\u00eaver en Tha\u00eflande, le 1er avril sur France 3","description":"Teaser de l'\u00e9mission \"Faut pas r\u00eaver\" du 1er avril qui sera consacr\u00e9e \u00e0 la Tha\u00eflande","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande","og_locale":"fr_FR","og_type":"article","og_title":"Faut pas r\u00eaver en Tha\u00eflande, le 1er avril sur France 3","og_description":"Teaser de l'\u00e9mission \"Faut pas r\u00eaver\" du 1er avril qui sera consacr\u00e9e \u00e0 la Tha\u00eflande","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2016-03-27T13:24:50+00:00","article_modified_time":"2016-03-27T13:36:07+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Faut pas r\u00eaver en Tha\u00eflande, le 1er avril sur France 3","datePublished":"2016-03-27T13:24:50+00:00","dateModified":"2016-03-27T13:36:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande"},"wordCount":362,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande","url":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande","name":"Faut pas r\u00eaver en Tha\u00eflande, le 1er avril sur France 3","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande.jpg","datePublished":"2016-03-27T13:24:50+00:00","dateModified":"2016-03-27T13:36:07+00:00","description":"Teaser de l'\u00e9mission \"Faut pas r\u00eaver\" du 1er avril qui sera consacr\u00e9e \u00e0 la Tha\u00eflande","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/faut-pas-rever-thailande.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8390-faut-pas-rever-thailande#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Faut pas r\u00eaver en Tha\u00eflande, le 1er avril sur France 3"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=8390"}],"version-history":[{"count":4,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8390\/revisions"}],"predecessor-version":[{"id":8395,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8390\/revisions\/8395"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=8390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=8390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=8390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}