{"id":8269,"date":"2016-03-09T10:09:37","date_gmt":"2016-03-09T08:09:37","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=8269"},"modified":"2016-03-09T13:09:53","modified_gmt":"2016-03-09T11:09:53","slug":"grand-canyon-snow-moutain-chonburi-thailand","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand","title":{"rendered":"Le Grand Canyon et la Montagne de Neige (Snow Mountain) de Chonburi"},"content":{"rendered":"<p>Il y a des endroits en Tha\u00eflande, dont on entend pas parler dans les guides\u00a0et dont\u00a0m\u00eame la plupart\u00a0des Tha\u00eflandais ignorent l&#8217;existence. Le <strong>Grand Canyon<\/strong> et la <strong>Montagne de Neige<\/strong> (<em>Snow Mountain<\/em>) de Chonburi, pr\u00e8s de <a href=\"http:\/\/www.thailandee.com\/villes\/pattaya\" target=\"_blank\">Pattaya<\/a> en font partie.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-8270\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi.jpg\" alt=\"montagne de neige thailande\" width=\"750\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi.jpg 960w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi-600x344.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi-624x358.jpg 624w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi-900x516.jpg 900w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>C&#8217;est un couple de blogueurs pakistanais et indien, qui m&#8217;a fait d\u00e9couvrir\u00a0ces lieux\u00a0o\u00f9 je ne suis pas encore all\u00e9 personnellement. Il a bien voulu \u00e9crire un article pour <em><a href=\"http:\/\/www.thailandee.com\/\" target=\"_blank\" rel=\"nofollow\">Thailandee.com<\/a><\/em> pour vous faire d\u00e9couvrir ces deux endroits \u00e9tonnants.<\/p>\n<p>Cach\u00e9 dans le disctrict Khiri de la province de Chonburi, le Grand Canyon a \u00e9t\u00e9 un peu dur \u00e0 trouver car il n&#8217;\u00e9tait indiqu\u00e9 nulle part sur la carte et pour de bonnes raisons. Quand nous sommes arriv\u00e9s finalement apr\u00e8s avoir demand\u00e9 \u00e0 quelques habitants, nous avons vite r\u00e9alis\u00e9 que c&#8217;est une propri\u00e9t\u00e9 priv\u00e9e &#8211; peut-\u00eatre un site minier abandonn\u00e9. Tout \u00e9tait \u00e9crit en tha\u00ef sur le site, nous ne pouvons donc pas \u00eatre trop s\u00fbr.<\/p>\n<p>Apr\u00e8s avoir pay\u00e9 une redevance de 10 bahts par personne, nous sommes pass\u00e9s\u00a0\u00e0 travers une entr\u00e9e semi-barricad\u00e9e et nous sommes dirig\u00e9s vers le Grand Canyon. En arrivant nous avons d\u00e9couvert\u00a0un grand ravin avec une \u00e9tendu d&#8217;eau. Un r\u00e9servoir ? Un barrage ? Nous ne sommes pas s\u00fbrs. Tout ce qui n&#8217;a pas d&#8217;importance. La vue imprenable en vaut la peine.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-8271\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chonburi-grand-canyon.jpg\" alt=\"grand canyon thailande\" width=\"750\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chonburi-grand-canyon.jpg 960w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chonburi-grand-canyon-600x344.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chonburi-grand-canyon-624x358.jpg 624w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chonburi-grand-canyon-900x516.jpg 900w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>Dans le canyon se trouve\u00a0une voie ferr\u00e9e. Ce n&#8217;est pas une voie abandonn\u00e9e, le klaxon d&#8217;une locomotive, nous le fit rapidement comprendre.<\/p>\n<p>Nous sommes ensuite partis\u00a0\u00e0 la recherche de\u00a0Snow Mountain. Forc\u00e9ment\u00a0intrigu\u00e9s parce qu&#8217;il ne peut\u00a0pas y avoir une montagne de neige en Tha\u00eflande vu le climat.<\/p>\n<p>A\u00a0quelques 100 m\u00e8tres de l\u00e0, nous avons pu voir une petite montagne, plut\u00f4t une colline culminant derri\u00e8re des buissons. Nous avons commenc\u00e9 \u00e0 marcher vers elle\u00a0et\u00a0avons r\u00e9alis\u00e9 ce qu&#8217;elle \u00e9tait r\u00e9ellement: une colline rocheuse.<\/p>\n<p>Elle\u00a0avait l&#8217;air assez int\u00e9ressante et cool. Nous sommes mont\u00e9s dessus\u00a0et avons\u00a0commenc\u00e9 \u00e0 nous\u00a0sentir comme sur la surface de la lune avec des crevasses et des ouvertures partout.<\/p>\n<p>Bien s\u00fbr, il n&#8217;a pas de neige, mais c&#8217;\u00e9tait int\u00e9ressant et \u00e9tonnant. Ce n&#8217;est pas quelque chose que vous verrez\u00a0tous les jours et\u00a0apr\u00e8s vous pourrez\u00a0presque dire \u00abJ&#8217;ai march\u00e9 surr\u00a0la lune&#8221;.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-8272\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailand-snow-mountain-chonburi.jpg\" alt=\"chonburi de montagne de neige\" width=\"750\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailand-snow-mountain-chonburi.jpg 960w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailand-snow-mountain-chonburi-600x344.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailand-snow-mountain-chonburi-624x358.jpg 624w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailand-snow-mountain-chonburi-900x516.jpg 900w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p><strong>Il faut compter une bonne\u00a0demie journ\u00e9e pour venir visiter le Grand Canyon et la Snow Mountain\u00a0depuis Bangkok<\/strong>\u00a0(1h30 de route). A notre connaissance, il n&#8217;existe aucun transport local pour vous rendre sur ces sites. Il faudra embaucher un tuk-tuk ou un taxi ou bien louer une voiture.<\/p>\n<p>Vous pouvez m\u00eame faire un voyage d&#8217;une journ\u00e9e et ajouter le\u00a0Wang Saen Hell Garden\u00a0au programme et finir par un peu de d\u00e9tente sur\u00a0la plage de Bang Saen. Un tierc\u00e9 gagnant parfait pour le week-end !<\/p>\n<hr \/>\n<p><em>Cet article a \u00e9t\u00e9 \u00e9crit en collaboration avec Shayan de\u00a0<a href=\"http:\/\/www.doseoflife.com\/\" target=\"_blank\">www.doseoflife.com<\/a><\/em><br \/><em><a href=\"http:\/\/www.facebook.com\/doseoflifecom\" target=\"_blank\" rel=\"nofollow\">www.facebook.com\/doseoflifecom<\/a><\/em><br \/><em><a href=\"http:\/\/www.instagram.com\/doseoflifecom\/\" target=\"_blank\" rel=\"nofollow\">www.instagram.com\/doseoflifecom\/<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a des endroits en Tha\u00eflande, dont on entend pas parler dans les guides\u00a0et<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-8269","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Grand Canyon et la Montagne de Neige (Snow Mountain) de Chonburi<\/title>\n<meta name=\"description\" content=\"Vous connaissez la Montagne de Neige (Snow Mountain) et le Grand Canyon de Chonburi en Tha\u00eflande. On vous les fait d\u00e9couvrir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Grand Canyon et la Montagne de Neige (Snow Mountain) de Chonburi\" \/>\n<meta property=\"og:description\" content=\"Vous connaissez la Montagne de Neige (Snow Mountain) et le Grand Canyon de Chonburi en Tha\u00eflande. On vous les fait d\u00e9couvrir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-09T08:09:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-09T11:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Grand Canyon et la Montagne de Neige (Snow Mountain) de Chonburi","description":"Vous connaissez la Montagne de Neige (Snow Mountain) et le Grand Canyon de Chonburi en Tha\u00eflande. On vous les fait d\u00e9couvrir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand","og_locale":"fr_FR","og_type":"article","og_title":"Le Grand Canyon et la Montagne de Neige (Snow Mountain) de Chonburi","og_description":"Vous connaissez la Montagne de Neige (Snow Mountain) et le Grand Canyon de Chonburi en Tha\u00eflande. On vous les fait d\u00e9couvrir.","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2016-03-09T08:09:37+00:00","article_modified_time":"2016-03-09T11:09:53+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Le Grand Canyon et la Montagne de Neige (Snow Mountain) de Chonburi","datePublished":"2016-03-09T08:09:37+00:00","dateModified":"2016-03-09T11:09:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand"},"wordCount":524,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand","url":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand","name":"Le Grand Canyon et la Montagne de Neige (Snow Mountain) de Chonburi","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi.jpg","datePublished":"2016-03-09T08:09:37+00:00","dateModified":"2016-03-09T11:09:53+00:00","description":"Vous connaissez la Montagne de Neige (Snow Mountain) et le Grand Canyon de Chonburi en Tha\u00eflande. On vous les fait d\u00e9couvrir.","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/swow-mountain-chonburi.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8269-grand-canyon-snow-moutain-chonburi-thailand#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Le Grand Canyon et la Montagne de Neige (Snow Mountain) de Chonburi"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=8269"}],"version-history":[{"count":7,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8269\/revisions"}],"predecessor-version":[{"id":8279,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8269\/revisions\/8279"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=8269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=8269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=8269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}