{"id":8064,"date":"2016-02-11T10:57:56","date_gmt":"2016-02-11T08:57:56","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=8064"},"modified":"2016-02-11T10:57:56","modified_gmt":"2016-02-11T08:57:56","slug":"thailande-le-nouveau-paradis-des-francais","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais","title":{"rendered":"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais"},"content":{"rendered":"<p>M6 pas vraiment connue pour ses reportages montrant la richesse culturelle, les belles traditions et les tr\u00e9sors de la nature de la Tha\u00eflande,\u00a0va \u00e0 nouveau parler du Pays du Sourire sur son antenne. Un sujet intitul\u00e9 <em>&#8220;Tha\u00eflande, le nouveau paradis des Fran\u00e7ais&#8221;<\/em> sera diffus\u00e9 dans l&#8217;\u00e9mission <strong><em>Zone interdite<\/em> du 28 f\u00e9vrier prochain<\/strong> pr\u00e9sent\u00e9e par Wendy Bouchard.<\/p>\n<figure id=\"attachment_8065\" aria-describedby=\"caption-attachment-8065\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-8065\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande.jpg\" alt=\"zone interdite m6 thailande\" width=\"750\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande.jpg 842w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande-600x337.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande-624x351.jpg 624w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><figcaption id=\"caption-attachment-8065\" class=\"wp-caption-text\">L&#8217;\u00e9mission Zone interdite du 28 f\u00e9vrier consacrera un sujet aux Frana\u00e7ais en Tha\u00eflande<\/figcaption><\/figure>\n<p>Comme je n&#8217;ai pas encore vu le reportage, je ne peux que reprendre ce qu&#8217;en dit la cha\u00eene sur son site.<\/p>\n<p><em>&#8220;C&#8217;est l&#8217;une des destinations pr\u00e9f\u00e9r\u00e9es des Fran\u00e7ais. Chaque ann\u00e9e, ils sont entre 500 000 et 600 000 \u00e0 se rendre en Tha\u00eflande pendant les vacances. Ils y vont en famille pour profiter des eaux turquoises et de la douceur du pays, ou partent s&#8217;\u00e9clater entre copains lors des fameuses \u00ab Full moon party \u00bb sur les plages de <a href=\"\/villes\/koh-phangan\">Ko Pha Ngan<\/a>, dans les bars \u00e0 chicha ou les boites de nuit de Phuket.<\/em><\/p>\n<p><em>Gr\u00e2ce aux vols low-cost, le pays est devenu une destination tr\u00e8s accessible, et une fois sur place, c&#8217;est la vie de pacha pour pas cher. Nous suivrons les vacances de Kamel et de ses 3 amis. Vir\u00e9es en grosses cylindr\u00e9es lou\u00e9es 30 euros par jour, farniente sur les plages priv\u00e9es et soir\u00e9es d\u00e9jant\u00e9es : ils font r\u00eaver leurs copains rest\u00e9s dans les cit\u00e9s de Nanterre.<\/em><\/p>\n<p><em>Loin de la fr\u00e9n\u00e9sie nocturne, Richard et Brigitte commencent, eux, une nouvelle vie sous le soleil de Tha\u00eflande. Ces deux retrait\u00e9s ont d\u00e9cid\u00e9 de tout plaquer pour s&#8217;installer \u00e0 180 km de la capitale Bangkok, dans le Deauville tha\u00eflandais. Ils y font construire la villa de leurs r\u00eaves pour le prix d&#8217;un studio sur la c\u00f4te normande.<\/em><\/p>\n<p><em>S\u00e9duits par le pays, certains Fran\u00e7ais d\u00e9cident d&#8217;y chercher fortune. Comme le chef de cuisine \u00e9toil\u00e9 Jean-Michel Lorrain, \u00e0 la t\u00eate d&#8217;un relais et ch\u00e2teaux en France. Avec sa fille et son gendre, ils ont ouvert un nouveau restaurant \u00e0 Bangkok. Cadre raffin\u00e9, cuisine \u00e0 la fran\u00e7aise, la famille va d\u00e9couvrir que diriger un \u00e9tablissement en Tha\u00eflande ne ressemble en rien \u00e0 ce qu&#8217;ils ont connu jusqu&#8217;\u00e0 pr\u00e9sent.<\/em><\/p>\n<p><em>Yann, lui, est boucher-charcutier. Il s&#8217;est install\u00e9 dans la grande \u00eele de <a href=\"\/villes\/koh-samui\">Koh Samui<\/a> o\u00f9 il a ouvert plusieurs boucheries. \u00c9paul\u00e9 par sa nouvelle famille tha\u00eflandaise &#8211; parfois un peu trop pr\u00e9sente &#8211; il arpente les campagnes les plus recul\u00e9es du pays, bien d\u00e9cid\u00e9 \u00e0 transformer les vaches locales en belles et grasses charolaises ! Un pari un peu fou qui pourrait bien r\u00e9volutionner la production de viande en Tha\u00eflande\u2026&#8221;<\/em><\/p>\n<p>Reste \u00e0 voir si pour une fois, M6 sortira un peu des clich\u00e9s racoleurs et r\u00e9ducteurs que la cha\u00eene v\u00e9hicule depuis des ann\u00e9es sur la Tha\u00eflande&#8230;<\/p>\n<p><em><strong>Zone interdite<\/strong><\/em><br \/><em>Tha\u00eflande, le nouveau paradis des Fran\u00e7ais<\/em><br \/><em>Dimanche 28\/02\/2016 \u00e0 20h50<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M6 pas vraiment connue pour ses reportages montrant la richesse culturelle, les belles traditions et<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8064","post","type-post","status-publish","format-standard","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tha\u00eflande, le nouveau paradis des Fran\u00e7ais<\/title>\n<meta name=\"description\" content=\"Un sujet intitul\u00e9 &quot;Tha\u00eflande, le nouveau paradis des Fran\u00e7ais&quot; sera diffus\u00e9 dans l&#039;\u00e9mission Zone interdite du 28 f\u00e9vrier 2016 pr\u00e9sent\u00e9e par Wendy Bouchard.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais\" \/>\n<meta property=\"og:description\" content=\"Un sujet intitul\u00e9 &quot;Tha\u00eflande, le nouveau paradis des Fran\u00e7ais&quot; sera diffus\u00e9 dans l&#039;\u00e9mission Zone interdite du 28 f\u00e9vrier 2016 pr\u00e9sent\u00e9e par Wendy Bouchard.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-11T08:57:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais","description":"Un sujet intitul\u00e9 \"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais\" sera diffus\u00e9 dans l'\u00e9mission Zone interdite du 28 f\u00e9vrier 2016 pr\u00e9sent\u00e9e par Wendy Bouchard.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais","og_locale":"fr_FR","og_type":"article","og_title":"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais","og_description":"Un sujet intitul\u00e9 \"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais\" sera diffus\u00e9 dans l'\u00e9mission Zone interdite du 28 f\u00e9vrier 2016 pr\u00e9sent\u00e9e par Wendy Bouchard.","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2016-02-11T08:57:56+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais","datePublished":"2016-02-11T08:57:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais"},"wordCount":515,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande.jpg","articleSection":["G\u00e9n\u00e9ral"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais","url":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais","name":"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande.jpg","datePublished":"2016-02-11T08:57:56+00:00","description":"Un sujet intitul\u00e9 \"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais\" sera diffus\u00e9 dans l'\u00e9mission Zone interdite du 28 f\u00e9vrier 2016 pr\u00e9sent\u00e9e par Wendy Bouchard.","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/zone-interdite-thailande.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/8064-thailande-le-nouveau-paradis-des-francais#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Tha\u00eflande, le nouveau paradis des Fran\u00e7ais"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=8064"}],"version-history":[{"count":1,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8064\/revisions"}],"predecessor-version":[{"id":8066,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/8064\/revisions\/8066"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=8064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=8064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=8064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}