{"id":6692,"date":"2015-07-07T11:53:29","date_gmt":"2015-07-07T09:53:29","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=6692"},"modified":"2015-07-07T12:04:03","modified_gmt":"2015-07-07T10:04:03","slug":"les-pires-avis-de-voyageurs-sur-bangkok","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok","title":{"rendered":"Les pires avis de voyageurs sur Bangkok"},"content":{"rendered":"<p>La magie d&#8217;internet c&#8217;est que tout le monde peut donner son avis sur tout. En fouillant sur TripAdvisor, l\u2019h\u00e9g\u00e9monique site de commentaires et appr\u00e9ciations de tout ce qui touche au voyage, les <strong>monuments les plus marquants de Bangkok<\/strong> en prennent pour leur grade. Des avis tr\u00e8s minoritaires et tr\u00e8s \u00e9tonnants.<\/p>\n<h2>\u00a0<\/h2>\n<h2>Le\u00a0<a href=\"http:\/\/www.thailandee.com\/a-voir\/wat-po-bangkok-1\" target=\"_blank\">Wat Pho<\/a> et son Bouddha couch\u00e9<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6695\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor.jpg\" alt=\"avis wat pho bangkok\" width=\"675\" height=\"450\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor.jpg 675w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor-624x416.jpg 624w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/p>\n<p><em>Le\u00a0Bouddha doit \u00eatre\u00a0en fait une statue en plastique made in China. Il fallait bien l&#8217;oeil d&#8217;une connaisseuse de l&#8217;Asie pour le d\u00e9celer, on s&#8217;\u00e9tait tous faits avoir ! \ud83d\ude09<\/em><\/p>\n<h2>\u00a0<\/h2>\n<h2>Le temple de la Montagne Dor\u00e9e (Wat Saket)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6696\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/golden-mountain-wat-saket1.jpg\" alt=\"Avis Golden Mount Bangkok\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/golden-mountain-wat-saket1.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/golden-mountain-wat-saket1-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/golden-mountain-wat-saket1-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6697\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/golden-mount-bad-review.jpg\" alt=\"avis wat Saket\" width=\"573\" height=\"146\" border=\"1\" \/><\/p>\n<p><em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Wat_Saket\" target=\"_blank\">Ce lien<\/a>\u00a0raconte probablement une histoire mensong\u00e8re de\u00a0cette colline certes artificielle et de son temple.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Le <a href=\"http:\/\/www.thailandee.com\/a-voir\/wat-phra-kaew-bangkok-4\" target=\"_blank\">Wat Phra Kaew<\/a> et le Grand Palais<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6693\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phra-kaew-temple-royal2.jpg\" alt=\"Avis Wat Phra Kaew\" width=\"750\" height=\"501\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phra-kaew-temple-royal2.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phra-kaew-temple-royal2-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phra-kaew-temple-royal2-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6694\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phra-kaew-tripadvisor.jpg\" alt=\"Wat Phra Kaew\" width=\"554\" height=\"143\" border=\"1\" \/><\/p>\n<p><em>Il est certes interdit de photographier le\u00a0Bouddha d&#8217;\u00e9meraude mais pour tout le reste du temple, on peut photographier et filmer \u00e0 profusion et il y a de quoi faire !<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6698\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/grand-palais-review.jpg\" alt=\"Avis grand palais Bangkok\" width=\"538\" height=\"100\" \/><\/p>\n<p><em>Y a quand m\u00eame beaucoup moins de man\u00e8ges et de vendeurs de hot dogs !<\/em><\/p>\n<p>C&#8217;est marrant comme Disney revient souvent&#8230; Apr\u00e8s, oui, ce sont des endroits o\u00f9 les touristes sont nombreux, tr\u00e8s nombreux et on pr\u00e9f\u00e9rerait tous les avoir pour nous tous seuls. Et bien, je le dis, \u00e0 ces \u00e9ternels d\u00e9\u00e7us, c&#8217;est possible ! Il faut juste vous faire \u00e9lire pr\u00e9sident des Etats-Unis. Barack Obama, lors de sa visite\u00a0en 2012,\u00a0a pu visiter le Wat Pho accompagn\u00e9 seulement de sa d\u00e9l\u00e9gation. Vous savez donc ce qu&#8217;il vous reste \u00e0 faire&#8230;<\/p>\n<p>Evidemment, <strong>ces avis sont tr\u00e8s minoritaires <\/strong>et ces monuments ont des avis tr\u00e8s largements favorables mais lire ces commentaires quand conna\u00eet les lieux en questions est \u00e9tonnant et parfois vraiment risible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La magie d&#8217;internet c&#8217;est que tout le monde peut donner son avis sur tout. En<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6692","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les pires avis de voyageurs sur Bangkok<\/title>\n<meta name=\"description\" content=\"Petite s\u00e9lection des pires avis sur Bangkok trouv\u00e9s sur TripAdvisor. C&#039;est souvent dr\u00f4le et parfois path\u00e9tique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les pires avis de voyageurs sur Bangkok\" \/>\n<meta property=\"og:description\" content=\"Petite s\u00e9lection des pires avis sur Bangkok trouv\u00e9s sur TripAdvisor. C&#039;est souvent dr\u00f4le et parfois path\u00e9tique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-07T09:53:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-07T10:04:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les pires avis de voyageurs sur Bangkok","description":"Petite s\u00e9lection des pires avis sur Bangkok trouv\u00e9s sur TripAdvisor. C'est souvent dr\u00f4le et parfois path\u00e9tique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok","og_locale":"fr_FR","og_type":"article","og_title":"Les pires avis de voyageurs sur Bangkok","og_description":"Petite s\u00e9lection des pires avis sur Bangkok trouv\u00e9s sur TripAdvisor. C'est souvent dr\u00f4le et parfois path\u00e9tique.","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2015-07-07T09:53:29+00:00","article_modified_time":"2015-07-07T10:04:03+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Les pires avis de voyageurs sur Bangkok","datePublished":"2015-07-07T09:53:29+00:00","dateModified":"2015-07-07T10:04:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok"},"wordCount":298,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok","url":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok","name":"Les pires avis de voyageurs sur Bangkok","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor.jpg","datePublished":"2015-07-07T09:53:29+00:00","dateModified":"2015-07-07T10:04:03+00:00","description":"Petite s\u00e9lection des pires avis sur Bangkok trouv\u00e9s sur TripAdvisor. C'est souvent dr\u00f4le et parfois path\u00e9tique.","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-po-tripadvisor.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6692-les-pires-avis-de-voyageurs-sur-bangkok#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Les pires avis de voyageurs sur Bangkok"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=6692"}],"version-history":[{"count":5,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6692\/revisions"}],"predecessor-version":[{"id":6702,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6692\/revisions\/6702"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=6692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=6692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=6692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}