{"id":6436,"date":"2015-07-22T09:17:29","date_gmt":"2015-07-22T07:17:29","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=6436"},"modified":"2015-07-22T09:18:23","modified_gmt":"2015-07-22T07:18:23","slug":"le-parc-historique-de-sri-thep","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep","title":{"rendered":"Le Parc Historique de Sri Thep"},"content":{"rendered":"<p>Situ\u00e9 dans la province de la province de <strong>Phetchabun<\/strong>, le\u00a0<strong>Sri Thep Historical Park<\/strong> est l&#8217;un des parcs historiques les moins connus de Tha\u00eflande. C&#8217;est vrai que compar\u00e9 \u00e0 Sukhotha\u00ef, Ayutthaya, <a href=\"http:\/\/www.thailandee.com\/villes\/kamphaeng-phet\" target=\"_blank\">Kamphaeng Phet<\/a> ou Si Satchanala\u00ef, il est moins bien conserv\u00e9 ou restaur\u00e9 et surtout il est un peu au milieu de nulle part. On vous pr\u00e9sente ce m\u00e9connu&#8230;\u00a0<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/inter.tourismthailand.org\/fileadmin\/upload_img\/Attraction\/4889\/%E0%B8%AD%E0%B8%B8%E0%B8%97%E0%B8%A2%E0%B8%B2%E0%B8%99%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%A7%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%A8%E0%B8%B2%E0%B8%AA%E0%B8%95%E0%B8%A3%E0%B9%8C%E0%B8%A8%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%97%E0%B8%9E.jpg\" alt=\"Sri THep Tha\u00eflande\" \/><\/p>\n<p>Le<strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Parc_historique_de_Sri_Thep\" target=\"_blank\"> Parc Historique de Sri Thep<\/a>\u00a0<\/strong>se situe\u00a0\u00e0 \u00a0130 kilom\u00e8tres environ\u00a0au sud de Phetchabun, sur la route num\u00e9ro 21. Si Thep est une ancienne ville o\u00f9 de nombreuses structures architecturales aujourd&#8217;hui en ruine t\u00e9moignent de sa prosp\u00e9rit\u00e9 pass\u00e9e du\u00a011\u00e8me au\u00a018\u00e8me si\u00e8cle bouddhiste. C&#8217;\u00e9tait autrefois le centre de contact entre les Dvarravati Unis dans le bassin de la plaine centrale et les Khmers Unis dans le Nord.\u00a0Il y a plus d&#8217;une centaine de sites construits en\u00a0briques et lat\u00e9rite\u00a0maintenant\u00a0en ruines.<\/p>\n<figure style=\"width: 640px\" class=\"wp-caption alignnone\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/e\/ed\/Khao_Khlang_Nak-1-HDR-pano.jpg\/1920px-Khao_Khlang_Nak-1-HDR-pano.jpg\" alt=\"Sri Thep Historical Park\" width=\"640\" \/><figcaption class=\"wp-caption-text\">Khao Khlang Nak<\/figcaption><\/figure>\n<p>La ville historique de Sri Thep \u00e9tait constitu\u00e9e de deux parties jointes couvrant environ 4,7 km2. La partie la plus interne de la ville (Muang Nai) \u00e9tait entour\u00e9e de murs et de douves.\u00a0<\/p>\n<p>La partie int\u00e9rieure de la ville compte pr\u00e8s de\u00a070 \u00e9tangs\u00a0et abritent trois\u00a0monuments importants: le Prang Sithep, le Prang Song Phi Nong et le Khao Khlang Nai\u00a0ainsi que 45 sites arch\u00e9ologiques restaur\u00e9s par le Fine Arts Department de Tha\u00eflande. La partie externe de la ville (Muang Nok) est \u00e9galement entour\u00e9e de murs et douves et comporte des monuments en ruines non restaur\u00e9s. Cette partie comporte 7 entr\u00e9es, 54 sites arch\u00e9ologiques mineurs et 30 \u00e9tangs.<\/p>\n<p>En dehors de la ville historique, on trouve encore une cinquantaien de sites arch\u00e9ologiques, les plus importants \u00e9tant le Khao Khlang Nok et le Prang Reussi\u00a0et la grotte de Khao Thamorat.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/zyvuaCA1J1Q\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2>Trouver le\u00a0Parc Historique de Sri Thep \u00a0sur la carte<\/h2>\n<p>[google-map-v3 shortcodeid=&#8221;TO_BE_GENERATED&#8221; width=&#8221;600&#8243; height=&#8221;400&#8243; zoom=&#8221;16&#8243; maptype=&#8221;roadmap&#8221; mapalign=&#8221;center&#8221; directionhint=&#8221;false&#8221; language=&#8221;fr&#8221; poweredby=&#8221;false&#8221; maptypecontrol=&#8221;true&#8221; pancontrol=&#8221;true&#8221; zoomcontrol=&#8221;true&#8221; scalecontrol=&#8221;true&#8221; streetviewcontrol=&#8221;true&#8221; scrollwheelcontrol=&#8221;false&#8221; draggable=&#8221;true&#8221; tiltfourtyfive=&#8221;false&#8221; enablegeolocationmarker=&#8221;false&#8221; enablemarkerclustering=&#8221;false&#8221; addmarkermashup=&#8221;false&#8221; addmarkermashupbubble=&#8221;false&#8221; addmarkerlist=&#8221;15.467506, 101.135990{}1-default.png{}March\u00e9 Flottant&#8221; bubbleautopan=&#8221;true&#8221; distanceunits=&#8221;miles&#8221; showbike=&#8221;false&#8221; showtraffic=&#8221;false&#8221; showpanoramio=&#8221;false&#8221;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situ\u00e9 dans la province de la province de Phetchabun, le\u00a0Sri Thep Historical Park est l&#8217;un<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6436","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Parc Historique de Sri Thep<\/title>\n<meta name=\"description\" content=\"Situ\u00e9 dans la province de la province de Phetchabun, le parc historique Sri Thep est l&#039;un des parcs historiques les moins connus de Tha\u00eflande.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Parc Historique de Sri Thep\" \/>\n<meta property=\"og:description\" content=\"Situ\u00e9 dans la province de la province de Phetchabun, le parc historique Sri Thep est l&#039;un des parcs historiques les moins connus de Tha\u00eflande.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-22T07:17:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-22T07:18:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/inter.tourismthailand.org\/fileadmin\/upload_img\/Attraction\/4889\/%E0%B8%AD%E0%B8%B8%E0%B8%97%E0%B8%A2%E0%B8%B2%E0%B8%99%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%A7%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%A8%E0%B8%B2%E0%B8%AA%E0%B8%95%E0%B8%A3%E0%B9%8C%E0%B8%A8%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%97%E0%B8%9E.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Parc Historique de Sri Thep","description":"Situ\u00e9 dans la province de la province de Phetchabun, le parc historique Sri Thep est l'un des parcs historiques les moins connus de Tha\u00eflande.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep","og_locale":"fr_FR","og_type":"article","og_title":"Le Parc Historique de Sri Thep","og_description":"Situ\u00e9 dans la province de la province de Phetchabun, le parc historique Sri Thep est l'un des parcs historiques les moins connus de Tha\u00eflande.","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2015-07-22T07:17:29+00:00","article_modified_time":"2015-07-22T07:18:23+00:00","og_image":[{"url":"http:\/\/inter.tourismthailand.org\/fileadmin\/upload_img\/Attraction\/4889\/%E0%B8%AD%E0%B8%B8%E0%B8%97%E0%B8%A2%E0%B8%B2%E0%B8%99%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%A7%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%A8%E0%B8%B2%E0%B8%AA%E0%B8%95%E0%B8%A3%E0%B9%8C%E0%B8%A8%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%97%E0%B8%9E.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Le Parc Historique de Sri Thep","datePublished":"2015-07-22T07:17:29+00:00","dateModified":"2015-07-22T07:18:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep#primaryimage"},"thumbnailUrl":"http:\/\/inter.tourismthailand.org\/fileadmin\/upload_img\/Attraction\/4889\/%E0%B8%AD%E0%B8%B8%E0%B8%97%E0%B8%A2%E0%B8%B2%E0%B8%99%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%A7%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%A8%E0%B8%B2%E0%B8%AA%E0%B8%95%E0%B8%A3%E0%B9%8C%E0%B8%A8%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%97%E0%B8%9E.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep","url":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep","name":"Le Parc Historique de Sri Thep","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep#primaryimage"},"thumbnailUrl":"http:\/\/inter.tourismthailand.org\/fileadmin\/upload_img\/Attraction\/4889\/%E0%B8%AD%E0%B8%B8%E0%B8%97%E0%B8%A2%E0%B8%B2%E0%B8%99%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%A7%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%A8%E0%B8%B2%E0%B8%AA%E0%B8%95%E0%B8%A3%E0%B9%8C%E0%B8%A8%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%97%E0%B8%9E.jpg","datePublished":"2015-07-22T07:17:29+00:00","dateModified":"2015-07-22T07:18:23+00:00","description":"Situ\u00e9 dans la province de la province de Phetchabun, le parc historique Sri Thep est l'un des parcs historiques les moins connus de Tha\u00eflande.","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep#primaryimage","url":"http:\/\/inter.tourismthailand.org\/fileadmin\/upload_img\/Attraction\/4889\/%E0%B8%AD%E0%B8%B8%E0%B8%97%E0%B8%A2%E0%B8%B2%E0%B8%99%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%A7%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%A8%E0%B8%B2%E0%B8%AA%E0%B8%95%E0%B8%A3%E0%B9%8C%E0%B8%A8%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%97%E0%B8%9E.jpg","contentUrl":"http:\/\/inter.tourismthailand.org\/fileadmin\/upload_img\/Attraction\/4889\/%E0%B8%AD%E0%B8%B8%E0%B8%97%E0%B8%A2%E0%B8%B2%E0%B8%99%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%A7%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%A8%E0%B8%B2%E0%B8%AA%E0%B8%95%E0%B8%A3%E0%B9%8C%E0%B8%A8%E0%B8%A3%E0%B8%B5%E0%B9%80%E0%B8%97%E0%B8%9E.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/6436-le-parc-historique-de-sri-thep#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Le Parc Historique de Sri Thep"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=6436"}],"version-history":[{"count":3,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6436\/revisions"}],"predecessor-version":[{"id":6756,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6436\/revisions\/6756"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=6436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=6436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=6436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}