{"id":521,"date":"2013-09-03T07:13:06","date_gmt":"2013-09-03T07:13:06","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?page_id=521"},"modified":"2013-09-22T11:23:25","modified_gmt":"2013-09-22T09:23:25","slug":"la-full-moon-party-de-koh-phangan-se-met-a-l-eau","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau","title":{"rendered":"La Full Moon Party de Koh Phangan se met \u00e0  l&#8217;eau"},"content":{"rendered":"<p>Alors qu&#8217;on apprenait il y a 2 jours que les travaux de l&#8217;a\u00e9roport de Koh Phangan ont pris du retard et que le tarmac de l&#8217;\u00eele ne sera pr\u00eat \u00e0 accueillir ses premiers coucous, enfin ces premiers petits avions, que courant 2014 (c&#8217;\u00e9tait pr\u00e9vu pour la fin de cette ann\u00e9e au d\u00e9part), le Minist\u00e8re du Tourisme et des Sports tha\u00eflandais, annonce vouloir mettre plus de <em>&#8220;water fun&#8221;<\/em> dans les f\u00eates mensuelles qui se tiennent sur la plage d&#8217;Haad Rin.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"Koh Phangan Full Moon Party\" src=\"http:\/\/www.thailandee.com\/villes\/koh-phangan\/koh-phangan-full-moon.jpg\" \/><br \/>\n<span style=\"font-size: xx-small;\">La Full Moon Party attire chaque mois des milliers de f\u00eatards<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Non, la vente d&#8217;alcool n&#8217;y sera pas interdite, l&#8217;\u00e9conomie de l&#8217;\u00eele ne s&#8217;en rel\u00e8verait pas. Il s&#8217;agit en fait d&#8217;ajouter des comp\u00e9titions de sports nautiques \u00e0 la plus grande surboum en plein air de Tha\u00eflande. Avec des troph\u00e9es \u00e0 la cl\u00e9. Le but du ministre Somsak Pureesrisak qui a annonc\u00e9 la nouvelle lundi est de changer un peu l&#8217;\u00e9tat d&#8217;esprit d&#8217;une f\u00eate dont la <em>&#8220;consommation excessive d&#8217;alcool, la danse et la drogue ne sont pas en ad\u00e9quation avec la culture locale&#8221;<\/em>. Et de rappeler que l&#8217;immense majorit\u00e9 des 6 000 \u00e0 14 000 danseurs plagistes, attir\u00e9s chaque mois par l&#8217;astre lunaire plein et qui essaient souvent de l&#8217;imiter et d&#8217;\u00eatre pleins \u00e0 leur tour, sont des occidentaux. Des mesures pour renforcer la s\u00e9curit\u00e9 des participants vont \u00e9galement \u00eatre prises. Et \u00e0 voir le nombre de petites cliniques et m\u00eame de cabinets de radiologie dont la concentration au m\u00e8tre carr\u00e9 est la plus \u00e9lev\u00e9e du pays \u00e0 Haad Rin o\u00f9 viennent s&#8217;\u00e9clater les<em> Full mooners<\/em>, ce n&#8217;est pas un mal. Reste \u00e0 voir si les comp\u00e9titions de sports nautiques qui d\u00e9buteront le mois prochain auront du succ\u00e8s et si elles inciteront les f\u00eatards \u00e0 moins boire, (attention, il fait chaud en Tha\u00eflande, il faut donc bien se d\u00e9shydrater mais \u00e0 Koh Phangan, on trouve aussi de l&#8217;eau min\u00e9rale \u00e0 ce qu&#8217;il para\u00eet). Car \u00e0 part les concurrents qui eux resteront probablement plus sobres que les autres, m&#8217;est d&#8217;avis que \u00e7a ne changera pas grand chose. Ceux qui viennent \u00e0 Koh Phangan les soirs de pleine lune ne sont pas l\u00e0 pour regarder des planches \u00e0 voile se tremousser sur les vagues mais pour se tr\u00e9mousser eux-m\u00eame sur la musique et faire la f\u00eate jusqu&#8217;au petit matin, payer un lit dans un dortoir \u00e0 3 francs 6 sous et se r\u00e9veiller sur le douillet sable de la plage avec un bouteille de Chang comme doudou. Evidemment, je caricature. Quoique&#8230; Il y a quand m\u00eame quelques comas \u00e9thyliques \u00e0 chaque fois et de nombreux accidents de scooters. Mais bon, tout le monde le sait, l&#8217;abus d&#8217;alcool est dangereux pour la sant\u00e9, fumer tue, la drogue c&#8217;est de la merde*, il faut manger 5 fruits et l\u00e9gumes par jour&#8230; tout \u00e7a, tout \u00e7a.<br \/>\n<em>* mentions obligatoires sur tout article sur la Full Moon Party de Koh Phangan<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors qu&#8217;on apprenait il y a 2 jours que les travaux de l&#8217;a\u00e9roport de Koh<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-521","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Full Moon Party de Koh Phangan se met \u00e0 l&#039;eau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Full Moon Party de Koh Phangan se met \u00e0 l&#039;eau\" \/>\n<meta property=\"og:description\" content=\"Alors qu&#8217;on apprenait il y a 2 jours que les travaux de l&#8217;a\u00e9roport de Koh\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-03T07:13:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-09-22T09:23:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/villes\/koh-phangan\/koh-phangan-full-moon.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Full Moon Party de Koh Phangan se met \u00e0 l'eau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau","og_locale":"fr_FR","og_type":"article","og_title":"La Full Moon Party de Koh Phangan se met \u00e0 l'eau","og_description":"Alors qu&#8217;on apprenait il y a 2 jours que les travaux de l&#8217;a\u00e9roport de Koh","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2013-09-03T07:13:06+00:00","article_modified_time":"2013-09-22T09:23:25+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/villes\/koh-phangan\/koh-phangan-full-moon.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"La Full Moon Party de Koh Phangan se met \u00e0 l&#8217;eau","datePublished":"2013-09-03T07:13:06+00:00","dateModified":"2013-09-22T09:23:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau"},"wordCount":500,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/villes\/koh-phangan\/koh-phangan-full-moon.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau","url":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau","name":"La Full Moon Party de Koh Phangan se met \u00e0 l'eau","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/villes\/koh-phangan\/koh-phangan-full-moon.jpg","datePublished":"2013-09-03T07:13:06+00:00","dateModified":"2013-09-22T09:23:25+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau#primaryimage","url":"http:\/\/www.thailandee.com\/villes\/koh-phangan\/koh-phangan-full-moon.jpg","contentUrl":"http:\/\/www.thailandee.com\/villes\/koh-phangan\/koh-phangan-full-moon.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/521-la-full-moon-party-de-koh-phangan-se-met-a-l-eau#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"La Full Moon Party de Koh Phangan se met \u00e0 l&#8217;eau"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=521"}],"version-history":[{"count":3,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/521\/revisions"}],"predecessor-version":[{"id":784,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/521\/revisions\/784"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}