{"id":511,"date":"2013-08-29T07:11:35","date_gmt":"2013-08-29T07:11:35","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?page_id=511"},"modified":"2013-09-22T11:23:33","modified_gmt":"2013-09-22T09:23:33","slug":"pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois","title":{"rendered":"Pas de visa gratuit pour la Tha\u00eflande pour les Chinois"},"content":{"rendered":"<p>Dans sa qu\u00eate de toujours plus de touristes, la Tha\u00eflande avait lanc\u00e9 l&#8217;id\u00e9e d&#8217;\u00e9tendre l&#8217;exemption de visa \u00e0 laquelle ont droit les ressortissants de 42 pays du monde (dont la France) \u00e0 la Chine. Une id\u00e9e qui vient d&#8217;\u00eatre officiellement abandonn\u00e9e, le risque d&#8217;\u00eatre d\u00e9bord\u00e9 par un nombre de visiteurs trop important par rapport aux capacit\u00e9s d&#8217;accueil a \u00e9t\u00e9 jug\u00e9 trop grand.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"Lost in Thailand\" src=\"http:\/\/www.thailandee.com\/blog\/images\/lost_in_thailand_a_l.jpg\" width=\"560\" \/><br \/>\n<span style=\"font-size: xx-small;\">Le succ\u00e8s du film <em>Lost in Thailand<\/em> a fait exploser le nombre de touristes chinois en Tha\u00eflande<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Une d\u00e9cision rassurante, il faut bien le dire. La Tha\u00eflande a accueilli plus de 22 millions de touristes en 2012, les pr\u00e9visions indiquent que cette ann\u00e9e ils seront au moins 25 millions. Les businessmen pourrait se frotter les mains mais les autorit\u00e9s vont plut\u00f4t se gratter la t\u00eate pour trouver des solutions. En effet, la capacit\u00e9 d&#8217;accueil du pays est estim\u00e9 \u00e0 30 millions de visiteurs. Un chiffre dont on s&#8217;approche inexorablement. Et il n&#8217;est pas s\u00fbr que le d\u00e9veloppement des possibilit\u00e9s d&#8217;h\u00e9bergements notamment aille aussi vite que la progression du nombre d&#8217;entr\u00e9es sur le territoire. Accorder un visa gratuit au pays le plus peupl\u00e9 du monde qui occupe d\u00e9j\u00e0 la t\u00eate du classement des nations qui visitent la Tha\u00eflande (en 2012, il y a eu pr\u00e8s de 2,8 millions de Chinois qui ont s\u00e9journ\u00e9 au Royaume de Siam), c&#8217;\u00e9tait voir monter sensiblement le nombre de touristes sans l&#8217;assurance de pouvoir les accueillir dans de bonnes conditions. D&#8217;autant plus que la r\u00e9partition des arriv\u00e9es sur l&#8217;ann\u00e9e n&#8217;est \u00e9videmment pas homog\u00e8ne et certaines destinations attirent plus que d&#8217;autres. Ainsi pr\u00e8s de la moiti\u00e9 de ceux qui viennent en Tha\u00eflande s\u00e9journent \u00e0 un moment ou \u00e0 un autre \u00e0 Phuket, un tiers \u00e0 Pattaya. Il faudrait essayer de donner envie aux voyageurs de voir autre chose. C&#8217;est ce qu&#8217;on essaie de faire sur ce site. Car il y a foultitude d&#8217;endroits bien plus int\u00e9ressants et agr\u00e9ables en Tha\u00eflande !<br \/>\nCe n&#8217;est que partie remise. Le visa gratuit pour les Chinois reviendra probablement sur le tapis dans les ann\u00e9es avenir. Mais la Tha\u00eflande est \u00e0 un tournant. Ses a\u00e9roports, Suvarnabhumi, Don Muang et l&#8217;a\u00e9roport de Phuket en particulier ont tous largement d\u00e9pass\u00e9 les capacit\u00e9s pour lesquelles ils ont \u00e9t\u00e9 pr\u00e9vus. Des travaux sont en cours ou en projet pour les agrandir. La capacit\u00e9 maximale d&#8217;accueil du pays sera probablement atteinte dans les 2-3 prochaines ann\u00e9es. Certaines destinations sont tellement livr\u00e9es au tourisme qu&#8217;elles n&#8217;ont plus grand chose de local. Il va falloir faire des choix&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans sa qu\u00eate de toujours plus de touristes, la Tha\u00eflande avait lanc\u00e9 l&#8217;id\u00e9e d&#8217;\u00e9tendre l&#8217;exemption<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-511","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pas de visa gratuit pour la Tha\u00eflande pour les Chinois<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pas de visa gratuit pour la Tha\u00eflande pour les Chinois\" \/>\n<meta property=\"og:description\" content=\"Dans sa qu\u00eate de toujours plus de touristes, la Tha\u00eflande avait lanc\u00e9 l&#8217;id\u00e9e d&#8217;\u00e9tendre l&#8217;exemption\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-29T07:11:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-09-22T09:23:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/images\/lost_in_thailand_a_l.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pas de visa gratuit pour la Tha\u00eflande pour les Chinois","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois","og_locale":"fr_FR","og_type":"article","og_title":"Pas de visa gratuit pour la Tha\u00eflande pour les Chinois","og_description":"Dans sa qu\u00eate de toujours plus de touristes, la Tha\u00eflande avait lanc\u00e9 l&#8217;id\u00e9e d&#8217;\u00e9tendre l&#8217;exemption","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2013-08-29T07:11:35+00:00","article_modified_time":"2013-09-22T09:23:33+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/images\/lost_in_thailand_a_l.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Pas de visa gratuit pour la Tha\u00eflande pour les Chinois","datePublished":"2013-08-29T07:11:35+00:00","dateModified":"2013-09-22T09:23:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/images\/lost_in_thailand_a_l.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois","url":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois","name":"Pas de visa gratuit pour la Tha\u00eflande pour les Chinois","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/images\/lost_in_thailand_a_l.jpg","datePublished":"2013-08-29T07:11:35+00:00","dateModified":"2013-09-22T09:23:33+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/images\/lost_in_thailand_a_l.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/images\/lost_in_thailand_a_l.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/511-pas-de-visa-gratuit-pour-la-thailande-pour-les-chinois#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Pas de visa gratuit pour la Tha\u00eflande pour les Chinois"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=511"}],"version-history":[{"count":3,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/511\/revisions"}],"predecessor-version":[{"id":979,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/511\/revisions\/979"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}