{"id":505,"date":"2013-08-20T07:21:39","date_gmt":"2013-08-20T07:21:39","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?page_id=505"},"modified":"2013-09-22T11:23:50","modified_gmt":"2013-09-22T09:23:50","slug":"les-toilettes-bientot-gratuites-dans-les-gares-de-thailande","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande","title":{"rendered":"Les toilettes bient\u00f4t gratuites dans les gares de Tha\u00eflande ?"},"content":{"rendered":"<p>En Tha\u00eflande, l&#8217;utilisation des toilettes dans les lieux publiques est souvent payante, le prix en g\u00e9n\u00e9ral de 3 bahts (moins de 10 centimes d&#8217;euro). Il y a m\u00eame parfois un petit tourniquet comme dans le m\u00e9tro \u00e0 l&#8217;entr\u00e9e. Cela pourrait bient\u00f4t changer. Le Ministre des Transports, Chadchart Sittipunt, vient d&#8217;annoncer son intention de rendre l&#8217;acc\u00e8s aux toilettes gratuit dans les gares et terminaux de bus en Tha\u00eflande.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"Toilettes en Thailande\" src=\"http:\/\/www.thailandee.com\/blog\/images\/toilets-thailand.jpg\" \/><br \/>\n<span style=\"font-size: xx-small;\">Les toilettes en Tha\u00eflande sont souvent payantes<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Pour lui, ces services doivent \u00eatre gratuits. Le gouverneur de la compagnie nationale des chemins de fer tha\u00eflandais, la State Railway of Thailand (SRT), Prapat Chongsanguan a quant \u00e0 lui d\u00e9clar\u00e9 qu&#8217;il avait fait appel \u00e0 des entreprises pour entretenir les toilettes dans les gares en leur permettant de percevoir des redevances en retour. Rendre ce service gratuit inciterait la SRT \u00e0 demander un budget sp\u00e9cifique de l&#8217;Etat pour g\u00e9rer les toilettes, a-t-il poursuivi. Wutthichart Kalayanamit, directeur g\u00e9n\u00e9ral de Transport Co, la compagnie des bus publics de Tha\u00eflande, a indiqu\u00e9 qu&#8217;il \u00e9tait pr\u00eat \u00e0 suivre les instructions du ministre, mais devra d&#8217;abord \u00e9tudier les d\u00e9tails des contrats avec les op\u00e9rateurs qui g\u00e8rent les toilettes des stations de bus. Si l&#8217;id\u00e9e est lanc\u00e9e, la gratuit\u00e9 des commodit\u00e9s dans les gares et stations de bus de Tha\u00eflande n&#8217;est pas encore acquise. Et pour tout vous dire plus que le fait qu&#8217;aller uriner soit payant, surtout que le prix est tr\u00e8s raisonnable pour le pouvoir d&#8217;achat d&#8217;un touriste, c&#8217;est la propret\u00e9 qu&#8217;on est en droit d&#8217;attendre si le service est payant et qui est rarement au rendez-vous qui rend la non gratuit\u00e9 contestable. Une remise \u00e0 neuf de certaines toilettes seraient aussi bienvenue. Le chantier \u00e0 r\u00e9aliser serait peut-\u00eatre de faire le tour des toilettes et d&#8217;en r\u00e9nover certaines (beaucoup). Il sera toujours temps ensuite de les rendre gratuites. Sinon, nul doute que la qualit\u00e9 des installations va encore se d\u00e9grader.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Tha\u00eflande, l&#8217;utilisation des toilettes dans les lieux publiques est souvent payante, le prix en<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-505","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les toilettes bient\u00f4t gratuites dans les gares de Tha\u00eflande ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les toilettes bient\u00f4t gratuites dans les gares de Tha\u00eflande ?\" \/>\n<meta property=\"og:description\" content=\"En Tha\u00eflande, l&#8217;utilisation des toilettes dans les lieux publiques est souvent payante, le prix en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-20T07:21:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-09-22T09:23:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/images\/toilets-thailand.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les toilettes bient\u00f4t gratuites dans les gares de Tha\u00eflande ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande","og_locale":"fr_FR","og_type":"article","og_title":"Les toilettes bient\u00f4t gratuites dans les gares de Tha\u00eflande ?","og_description":"En Tha\u00eflande, l&#8217;utilisation des toilettes dans les lieux publiques est souvent payante, le prix en","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2013-08-20T07:21:39+00:00","article_modified_time":"2013-09-22T09:23:50+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/images\/toilets-thailand.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Les toilettes bient\u00f4t gratuites dans les gares de Tha\u00eflande ?","datePublished":"2013-08-20T07:21:39+00:00","dateModified":"2013-09-22T09:23:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande"},"wordCount":346,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/images\/toilets-thailand.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande","url":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande","name":"Les toilettes bient\u00f4t gratuites dans les gares de Tha\u00eflande ?","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/images\/toilets-thailand.jpg","datePublished":"2013-08-20T07:21:39+00:00","dateModified":"2013-09-22T09:23:50+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/images\/toilets-thailand.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/images\/toilets-thailand.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/505-les-toilettes-bientot-gratuites-dans-les-gares-de-thailande#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Les toilettes bient\u00f4t gratuites dans les gares de Tha\u00eflande ?"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=505"}],"version-history":[{"count":3,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/505\/revisions"}],"predecessor-version":[{"id":819,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/505\/revisions\/819"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}