{"id":504,"date":"2013-08-20T06:37:05","date_gmt":"2013-08-20T06:37:05","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?page_id=504"},"modified":"2013-09-22T11:23:55","modified_gmt":"2013-09-22T09:23:55","slug":"les-thailandais-derniers-de-la-classe-en-anglais","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais","title":{"rendered":"Les Tha\u00eflandais derniers de la classe en Anglais"},"content":{"rendered":"<p>Quand on voyage en Tha\u00eflande, on trouve assez facilement des interlocuteurs parlant Anglais dans les zones touristiques et aux points strat\u00e9giques que sont les terminaux de bus et dans les h\u00f4tels et guesthouses sans parler des chauffeurs de tuk-tuks. C&#8217;est un british souvent approximatif mais suffisant pour installer un dialogue. L&#8217;apprentissage de l&#8217;Anglais est un des d\u00e9fis de demain pour le Royaume o\u00f9 les professeurs d&#8217;Anglais manquent cruellement. Prof d&#8217;Anglais, c&#8217;est d&#8217;ailleurs le m\u00e9tier o\u00f9 les \u00e9trangers sont les plus appr\u00e9ci\u00e9s et demand\u00e9s alors qu&#8217;un certain nombre d&#8217;emplois sont interdits aux non-tha\u00eflandais. Une opportunit\u00e9 pour ceux qui cherchent \u00e0 s&#8217;expatrier. Un r\u00e9cent test r\u00e9alis\u00e9 aupr\u00e8s de 1,5 million de salari\u00e9s d&#8217;Asie du Sud-Est par le site <em>JobStreet.com<\/em> montre que les Tha\u00eflandais sont les derniers de la classe en Anglais.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"Les thailandais mauvais en Anglais\" src=\"http:\/\/www.thailandee.com\/blog\/images\/thailand-bad-at-english.jpg\" width=\"450\" \/><br \/>\n<span style=\"font-size: xx-small;\">Les Tha\u00eflandais dernier d&#8217;Asie du Sud-est en Anglais<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Le site de e-recrutement qui met en relation 7 millions de demandeurs d&#8217;emploi et 60.000 entreprises clientes, a test\u00e9 le niveau d&#8217;Anglais des salari\u00e9s de plusieurs pays d&#8217;Asie du Sud-Est: Singapour, les Philippines, la Malaisie, l&#8217;Indon\u00e9sie et la Tha\u00eflande. Plus de 1,5 million de salari\u00e9s ont r\u00e9pondu \u00e0 40 questions. Les r\u00e9sultats pour les Tha\u00eflandais sont assez mauvais. Alors que les Singapouriens ont un taux de bonnes r\u00e9ponses de 81% contre 73% pour les Malaisiens, 72% pour les Philippins et 60% pour les Indon\u00e9siens, les Tha\u00eflandais arrivent \u00e0 55% de r\u00e9ponses correctes. Les employ\u00e9s qui ont r\u00e9pondu au questionnaire de <em>JobStreet.com<\/em> occupent des postes de cadres ou cadres sup\u00e9rieurs dans les secteurs de la communication, du marketing, des ressources humaines ou de la finance. S&#8217;ils avaient interrog\u00e9 les bar girls, gr\u00e0\u00a2ce \u00e0 l&#8217;ouvrage <em><a href=\"\/blog\/index.php\/203-get-rich-quick-english-for-bar-girls\" hreflang=\"fr\">Get Rich Quick English for Bar Girls<\/a><\/em>, les r\u00e9sultats auraient peut-\u00eatre \u00e9t\u00e9 meilleurs \ud83d\ude09<br \/>\nLe Minist\u00e8re de l&#8217; Education de la Tha\u00eflande est pleinement conscient des lacunes de ses \u00e9tudiants dans la langue de Shakespeare et essaie de faire de gros efforts pour redresser la barre. Il serait int\u00e9ressant de faire passer le m\u00eame test en France. Quand on voit notre classe politique parler Anglais, on peut se poser des questions&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand on voyage en Tha\u00eflande, on trouve assez facilement des interlocuteurs parlant Anglais dans les<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-504","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Tha\u00eflandais derniers de la classe en Anglais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Tha\u00eflandais derniers de la classe en Anglais\" \/>\n<meta property=\"og:description\" content=\"Quand on voyage en Tha\u00eflande, on trouve assez facilement des interlocuteurs parlant Anglais dans les\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-20T06:37:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-09-22T09:23:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/images\/thailand-bad-at-english.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Tha\u00eflandais derniers de la classe en Anglais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais","og_locale":"fr_FR","og_type":"article","og_title":"Les Tha\u00eflandais derniers de la classe en Anglais","og_description":"Quand on voyage en Tha\u00eflande, on trouve assez facilement des interlocuteurs parlant Anglais dans les","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2013-08-20T06:37:05+00:00","article_modified_time":"2013-09-22T09:23:55+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/images\/thailand-bad-at-english.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Les Tha\u00eflandais derniers de la classe en Anglais","datePublished":"2013-08-20T06:37:05+00:00","dateModified":"2013-09-22T09:23:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais"},"wordCount":375,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/images\/thailand-bad-at-english.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais","url":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais","name":"Les Tha\u00eflandais derniers de la classe en Anglais","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/images\/thailand-bad-at-english.jpg","datePublished":"2013-08-20T06:37:05+00:00","dateModified":"2013-09-22T09:23:55+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/images\/thailand-bad-at-english.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/images\/thailand-bad-at-english.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/504-les-thailandais-derniers-de-la-classe-en-anglais#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Les Tha\u00eflandais derniers de la classe en Anglais"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=504"}],"version-history":[{"count":3,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/504\/revisions"}],"predecessor-version":[{"id":821,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/504\/revisions\/821"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}