{"id":484,"date":"2013-08-02T06:07:11","date_gmt":"2013-08-02T06:07:11","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?page_id=484"},"modified":"2013-09-22T11:28:13","modified_gmt":"2013-09-22T09:28:13","slug":"maree-noire-en-thailande-rayong","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong","title":{"rendered":"Mar\u00e9e noire en Tha\u00eflande: 90% de la nappe nettoy\u00e9e"},"content":{"rendered":"<p>L&#8217;Autorit\u00e9 Touristique de Tha\u00eflande (T.A.T) vient de publier un communiqu\u00e9 officiel sur la mar\u00e9e noire indiquant qu&#8217;il ne resterait que 10% de la nappe de p\u00e9trole qui s&#8217;est \u00e9chapp\u00e9e en mer samedi dernier au large de Rayong. Ainsi en une semaine l&#8217;essentiel, des 50 000 litres de brut aura \u00e9t\u00e9 enlev\u00e9 tandis que le nettoyage de la plage d&#8217;Ao Phrao sur l&#8217;\u00eele tr\u00e8s touristique de Koh Samet, la seule que la mar\u00e9e noire a atteinte, continue et progresse bien, toujours selon la T.A.T qui, photo satellite \u00e0 l&#8217;appui, montre l&#8217;\u00e9volution de la situation. L&#8217;agence en charge du Tourisme dans le Royaume qui publie aussi des photos prises hier pour bien montrer que toutes les autres plages sont indemnes.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"Maree noire Koh Samet Thailande\" src=\"http:\/\/www.thailandee.com\/blog\/images\/oil-spill-koh-samet.jpg\" \/><br \/>\n<span style=\"font-size: xx-small;\">Photo satellite de la mar\u00e9e noire prise le 1er Ao\u00fbt \u00e0 6h<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Cela devrait prendre environ encore 1 \u00e0 2 jours pour finir de nettoyer la plage d&#8217;Ao Phrao. La nappe de p\u00e9trole ne devrait pas atteindre les \u00eeles environnantes de Koh Pla Teen, Koh Kham and Koh Kudi, comme on aurait pu le craindre \u00e0 une moment. Mais il restera des traces de la catastrophe. Des traces sur l&#8217;\u00e9cologie. Ainsi les autorit\u00e9s locales rapportent que la majorit\u00e9 des r\u00e9cifs coralliens \u00e0 proximit\u00e9 de Ao Phrao ont vir\u00e9 au noir. Sumet Saithong, chef du Khao Laem Ya-Mu Ko Samet National Park dont Koh Samet fait partie indique que les plongeurs et les biologistes marins qui ont inspect\u00e9 les r\u00e9cifs pr\u00e8s de cette plage ont rapport\u00e9 que plus de 70 pour cent des coraux ont noirci. M. Sumet a d\u00e9pos\u00e9 une plainte aupr\u00e8s de la police locale pour les dommages environnementaux caus\u00e9s par la fuite de p\u00e9trole. Les op\u00e9rateurs touristiques de l&#8217;\u00eele de Samet ont \u00e9t\u00e9 durement touch\u00e9s. Baisse de 50% dans les r\u00e9servations d&#8217;excursions de plong\u00e9e, par exemple. Et comme l&#8217;un des sites de plong\u00e9e les plus populaires est justement situ\u00e9 \u00e0 c\u00f4t\u00e9 de Ao Phrao, un certain nombre de touristes se sont d\u00e9j\u00e0 tourn\u00e9s vers d&#8217;autres destinations. De son c\u00f4t\u00e9, la Thailand Hotels Association estime que les h\u00f4teliers de Koh Samed vont souffrir des cons\u00e9quences de la mar\u00e9e noire et voir leur taux de remplissage baisser siginificativement pour au moins un an. L&#8217;information \u00e9tant pour l&#8217;instant \u00e9t\u00e9 peu reprise dans les m\u00e9dias, surtout t\u00e9l\u00e9visuels, hors Asie, on peut penser que la fr\u00e9quentation des touristes \u00e9trangers, elle, ne baissera pas pour tr\u00e8s longtemps. Mais les Tha\u00eflandais repr\u00e9sentent une grosse part des visiteurs de l&#8217;\u00eele o\u00f9 ils aiment \u00e0 venir pour le week-end ou les jours f\u00e9ri\u00e9s et eux sont bien inform\u00e9s du probl\u00e8me que conna\u00eet le secteur.<\/p>\n<p>Le ministre du Tourisme et des Sports, Somsak Pureesrisak, s&#8217;est rendu sur Koh Samet et tiendra une r\u00e9union avec les op\u00e9rateurs locaux de tourisme pour assurer le suivi des probl\u00e8mes et discuter des plans d&#8217;aide aux entreprises affect\u00e9es par les annulations. Diverses r\u00e9ductions d&#8217;imp\u00f4ts et des efforts marketing sont susceptibles d&#8217;\u00eatre mis en oeuvre. Les succursales bancaires locales sont \u00e9galement pr\u00eates \u00e0 intervenir, selon des m\u00e9dias locaux. Le ministre du Tourisme et des Sports a d\u00e9clar\u00e9 que le Cabinet avait d\u00e9cid\u00e9 que PTT Global Chemical d\u00e9dommagera les h\u00f4tels qui doivent faire face \u00e0 une perte financi\u00e8re suite aux annulations de clients.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Autorit\u00e9 Touristique de Tha\u00eflande (T.A.T) vient de publier un communiqu\u00e9 officiel sur la mar\u00e9e noire<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-484","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mar\u00e9e noire en Tha\u00eflande: 90% de la nappe nettoy\u00e9e<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mar\u00e9e noire en Tha\u00eflande: 90% de la nappe nettoy\u00e9e\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Autorit\u00e9 Touristique de Tha\u00eflande (T.A.T) vient de publier un communiqu\u00e9 officiel sur la mar\u00e9e noire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-02T06:07:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-09-22T09:28:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/images\/oil-spill-koh-samet.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mar\u00e9e noire en Tha\u00eflande: 90% de la nappe nettoy\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong","og_locale":"fr_FR","og_type":"article","og_title":"Mar\u00e9e noire en Tha\u00eflande: 90% de la nappe nettoy\u00e9e","og_description":"L&#8217;Autorit\u00e9 Touristique de Tha\u00eflande (T.A.T) vient de publier un communiqu\u00e9 officiel sur la mar\u00e9e noire","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2013-08-02T06:07:11+00:00","article_modified_time":"2013-09-22T09:28:13+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/images\/oil-spill-koh-samet.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Mar\u00e9e noire en Tha\u00eflande: 90% de la nappe nettoy\u00e9e","datePublished":"2013-08-02T06:07:11+00:00","dateModified":"2013-09-22T09:28:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong"},"wordCount":587,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/images\/oil-spill-koh-samet.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong","url":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong","name":"Mar\u00e9e noire en Tha\u00eflande: 90% de la nappe nettoy\u00e9e","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/images\/oil-spill-koh-samet.jpg","datePublished":"2013-08-02T06:07:11+00:00","dateModified":"2013-09-22T09:28:13+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/images\/oil-spill-koh-samet.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/images\/oil-spill-koh-samet.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/484-maree-noire-en-thailande-rayong#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Mar\u00e9e noire en Tha\u00eflande: 90% de la nappe nettoy\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=484"}],"version-history":[{"count":2,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/484\/revisions"}],"predecessor-version":[{"id":986,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/484\/revisions\/986"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}