{"id":3489,"date":"2014-06-15T07:47:07","date_gmt":"2014-06-15T05:47:07","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=3489"},"modified":"2014-07-08T10:56:21","modified_gmt":"2014-07-08T08:56:21","slug":"revue-de-presse-thailande-7-14-juin-2014","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014","title":{"rendered":"Revue de presse Tha\u00eflande 7-14 juin 2014"},"content":{"rendered":"<p>Cette semaine on inaugure une nouvelle s\u00e9rie d&#8217;articles, la revue de presse hebdomadaire dans laquelle, je compilerai tous les articles int\u00e9ressants trouv\u00e9s dans la semaine (et pas abord\u00e9s sur le blog). C&#8217;est parti !<\/p>\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1\" style=\"max-width: 750px;\">\n<tbody>\n<tr class=\"row-1\">\n<td class=\"column-1\"><a href=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-3491\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-560x202.jpg\" alt=\"metroLogo\" width=\"200\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-560x202.jpg 560w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-624x225.jpg 624w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo.jpg 834w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/td>\n<td class=\"column-2\" valign=\"middle\">\n<p>\u00a0<a href=\"http:\/\/journalmetro.com\/monde\/510603\/thailande-gouvernement-interimaire-en-septembre\/\" target=\"_blank\" rel=\"nofollow\"><strong>Tha\u00eflande: gouvernement int\u00e9rimaire en septembre<\/strong><\/a><br \/><em>\u00abUn gouvernement sera probablement mis sur pied en ao\u00fbt ou au d\u00e9but septembre, a-t-il dit. Quand (\u2026) nous aurons un gouvernement, nous irons de l\u2019avant. Le comit\u00e9 de r\u00e9forme pourra alors commencer ses travaux.\u00bb<\/em><b><a href=\"http:\/\/www.cambodee.com\/visiter-cambodge\/angkor-siem-reap-10\"><br \/><\/a><\/b><\/p>\n<\/td>\n<\/tr>\n<tr class=\"row-2\">\n<td class=\"column-1\"><a href=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/lemondefr.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-3492\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/lemondefr.jpg\" alt=\"lemondefr\" width=\"200\" \/><\/a><\/td>\n<td class=\"column-2\" valign=\"middle\">\n<p><a href=\"http:\/\/www.lemonde.fr\/asie-pacifique\/article\/2014\/06\/11\/l-arriere-gout-d-esclavage-de-la-crevette-thailandaise_4436055_3216.html\" target=\"_blank\" rel=\"nofollow\"><strong>L&#8217;arri\u00e8re-go\u00fbt d&#8217;esclavage de la crevette tha\u00eflandaise<\/strong><\/a><br \/>La crevette tha\u00eflandaise n&#8217;est pas ch\u00e8re. Mais gr\u00e2ce au Guardian, on comprend d\u00e9sormais mieux pourquoi. Selon une enqu\u00eate du quotidien britannique, les crevettes vendues dans les plus grands supermarch\u00e9s am\u00e9ricains et europ\u00e9ens sont nourries de poissons p\u00each\u00e9s par des migrants r\u00e9duits en esclavage.<\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr class=\"row-2\">\n<td class=\"column-1\"><a href=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rfi.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-3493\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rfi.jpg\" alt=\"rfi\" width=\"200\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rfi.jpg 225w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rfi-150x150.jpg 150w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/td>\n<td class=\"column-2\" valign=\"middle\">\n<p><a href=\"http:\/\/www.rfi.fr\/asie-pacifique\/20140612-thailande-travailleurs-immigres-illegaux-cibles-junte\/\" target=\"_blank\" rel=\"nofollow\"><strong>Tha\u00eflande: les travailleurs immigr\u00e9s ill\u00e9gaux cibl\u00e9s par la junte<\/strong><\/a><br \/>Tha\u00eflande: les travailleurs immigr\u00e9s ill\u00e9gaux cibl\u00e9s par la junteLa junte tha\u00eflandaise menace d\u2019arr\u00eater tous les travailleurs immigr\u00e9s clandestins sur le territoire et de les renvoyer dans leur pays. Des milliers de Cambodgiens ont d\u00e9j\u00e0 retravers\u00e9 la fronti\u00e8re par peur d\u2019\u00eatre arr\u00eat\u00e9s. Beaucoup d\u2019entre eux se trouvent dans la zone fronti\u00e8re, sans avoir les moyens financiers pour rentrer chez eux.<\/p>\n<\/td>\n<\/tr>\n<tr class=\"row-4\">\n<td class=\"column-1\"><img decoding=\"async\" src=\"http:\/\/www.arcinfo.ch\/multimedia\/images\/img_structures\/logo_arcinfo.png\" alt=\"\" width=\"200\" \/><\/td>\n<td class=\"column-2\" valign=\"middle\">\n<p><strong><a href=\"http:\/\/www.arcinfo.ch\/fr\/monde\/thailande-la-junte-au-pouvoir-veut-offrir-les-matchs-du-mondial-a-la-population-577-1306996\" target=\"_blank\" rel=\"nofollow\">Tha\u00eflande: la junte au pouvoir veut offrir les matchs du Mondial \u00e0 la population<\/a><br \/><\/strong>Les militaires au pouvoir en Tha\u00eflande veulent &#8220;rendre le bonheur au peuple&#8221;. L&#8217;op\u00e9ration passe notamment par une tentative rat\u00e9e de rachat des droits t\u00e9l\u00e9vis\u00e9s de la Coupe du monde de football<\/p>\n<\/td>\n<\/tr>\n<tr class=\"row-3\">\n<td class=\"column-1\">\u00a0<\/td>\n<td class=\"column-2\" valign=\"middle\">\u00a0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Cette semaine on inaugure une nouvelle s\u00e9rie d&#8217;articles, la revue de presse hebdomadaire dans laquelle,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3489","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revue de presse Tha\u00eflande 7-14 juin 2014<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revue de presse Tha\u00eflande 7-14 juin 2014\" \/>\n<meta property=\"og:description\" content=\"Cette semaine on inaugure une nouvelle s\u00e9rie d&#8217;articles, la revue de presse hebdomadaire dans laquelle,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-15T05:47:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-07-08T08:56:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-560x202.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revue de presse Tha\u00eflande 7-14 juin 2014","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014","og_locale":"fr_FR","og_type":"article","og_title":"Revue de presse Tha\u00eflande 7-14 juin 2014","og_description":"Cette semaine on inaugure une nouvelle s\u00e9rie d&#8217;articles, la revue de presse hebdomadaire dans laquelle,","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2014-06-15T05:47:07+00:00","article_modified_time":"2014-07-08T08:56:21+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-560x202.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Revue de presse Tha\u00eflande 7-14 juin 2014","datePublished":"2014-06-15T05:47:07+00:00","dateModified":"2014-07-08T08:56:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014"},"wordCount":290,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-560x202.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014","url":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014","name":"Revue de presse Tha\u00eflande 7-14 juin 2014","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-560x202.jpg","datePublished":"2014-06-15T05:47:07+00:00","dateModified":"2014-07-08T08:56:21+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-560x202.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/metroLogo-560x202.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3489-revue-de-presse-thailande-7-14-juin-2014#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Revue de presse Tha\u00eflande 7-14 juin 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3489"}],"version-history":[{"count":6,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3489\/revisions"}],"predecessor-version":[{"id":3729,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3489\/revisions\/3729"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}