{"id":3400,"date":"2014-06-06T11:18:42","date_gmt":"2014-06-06T09:18:42","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=3400"},"modified":"2014-06-06T11:18:42","modified_gmt":"2014-06-06T09:18:42","slug":"vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus","title":{"rendered":"Vers une lev\u00e9e du couvre-feu en Tha\u00eflande dans 8 destinations de plus ?"},"content":{"rendered":"<p>Alors que la confirmation officielle est tomb\u00e9e: pas de couvre-feu sur Koh Phangan pour la prochaine <a href=\"http:\/\/en.wikipedia.org\/wiki\/Full_Moon_Party\" target=\"_blank\">Full Moon Party, <\/a>et apr\u00e8s le lev\u00e9e du couvre-feu \u00e0 Pattaya, Phuket et Samui, le Minist\u00e8re du Tourisme esp\u00e8rent obtenir la fin de ce dernier dans d&#8217;autres destinations.<\/p>\n<figure style=\"width: 600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" title=\"Plus de couvre-feu Hua Hin ?\" alt=\"Hua Hin\" src=\"http:\/\/www.thailandee.com\/villes\/hua-hin\/hua-hin-train-station.jpg\" width=\"600\" height=\"400\" \/><figcaption class=\"wp-caption-text\">Bient\u00f4t Plus de couvre-feu \u00e0 Hua Hin ?<\/figcaption><\/figure>\n<p>Le Minist\u00e8re du Tourisme et des Sports veut proposer parmi les plus c\u00e9l\u00e8bres du pays o\u00f9 les visiteurs aiment profiter de la vie nocturne anim\u00e9e. Le couvre-feu s\u00e9vit actuellement de minuit \u00e0 4h du matin dans toute la Tha\u00eflande <a href=\"http:\/\/www.thailandee.com\/blog\/index.php\/3364-thailande-levee-du-couvre-feu-a-pattaya-koh-samui-et-phuket\" target=\"_blank\">sauf 3 destinations<\/a> (plus Haad Rin \u00e0 Koh Phang du 9 au 13 juin). <strong>Les lieux susceptibles de voir la libert\u00e9 de mouvement la nuit rendu \u00e0 ces habitants et visteurs sont: Krabi, Phang Nga, Trang, Hat Yai, <a href=\"http:\/\/www.thailandee.com\/villes\/koh-chang.php\">Koh Chang<\/a>, Cha-am, Hua Hin et Chiang Mai<\/strong>.\u00a0Il\u00a0a \u00e9t\u00e9 jug\u00e9 peu probable que des violences politiques y aient lieu.<\/p>\n<p>Rien ne dit que cela sera accept\u00e9 par la junte, surtout en ce qui concerne Chiang Mai, qui est plut\u00f4t un territoire des &#8220;rouges&#8221; et a vu quelques manifestations anti-coup avoir lieu. Affaire \u00e0 suivre&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que la confirmation officielle est tomb\u00e9e: pas de couvre-feu sur Koh Phangan pour la<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3400","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vers une lev\u00e9e du couvre-feu en Tha\u00eflande dans 8 destinations de plus ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vers une lev\u00e9e du couvre-feu en Tha\u00eflande dans 8 destinations de plus ?\" \/>\n<meta property=\"og:description\" content=\"Alors que la confirmation officielle est tomb\u00e9e: pas de couvre-feu sur Koh Phangan pour la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-06T09:18:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/villes\/hua-hin\/hua-hin-train-station.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vers une lev\u00e9e du couvre-feu en Tha\u00eflande dans 8 destinations de plus ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus","og_locale":"fr_FR","og_type":"article","og_title":"Vers une lev\u00e9e du couvre-feu en Tha\u00eflande dans 8 destinations de plus ?","og_description":"Alors que la confirmation officielle est tomb\u00e9e: pas de couvre-feu sur Koh Phangan pour la","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2014-06-06T09:18:42+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/villes\/hua-hin\/hua-hin-train-station.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Vers une lev\u00e9e du couvre-feu en Tha\u00eflande dans 8 destinations de plus ?","datePublished":"2014-06-06T09:18:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus"},"wordCount":207,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/villes\/hua-hin\/hua-hin-train-station.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus","url":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus","name":"Vers une lev\u00e9e du couvre-feu en Tha\u00eflande dans 8 destinations de plus ?","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/villes\/hua-hin\/hua-hin-train-station.jpg","datePublished":"2014-06-06T09:18:42+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus#primaryimage","url":"http:\/\/www.thailandee.com\/villes\/hua-hin\/hua-hin-train-station.jpg","contentUrl":"http:\/\/www.thailandee.com\/villes\/hua-hin\/hua-hin-train-station.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/3400-vers-une-levee-du-couvre-feu-en-thailande-dans-8-destinations-de-plus#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Vers une lev\u00e9e du couvre-feu en Tha\u00eflande dans 8 destinations de plus ?"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3400"}],"version-history":[{"count":2,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3400\/revisions"}],"predecessor-version":[{"id":3402,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3400\/revisions\/3402"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}