{"id":14613,"date":"2019-01-29T12:45:03","date_gmt":"2019-01-29T10:45:03","guid":{"rendered":"https:\/\/www.thailandee.com\/blog\/?p=14613"},"modified":"2020-01-18T07:21:39","modified_gmt":"2020-01-18T05:21:39","slug":"celebrations-du-nouvel-an-chinois-2019-en-thailande","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande","title":{"rendered":"C\u00e9l\u00e9brations du Nouvel An chinois 2019 en Tha\u00eflande"},"content":{"rendered":"<p><strong>Le Nouvel An Chinois, c&#8217;est dans une semaine<\/strong> et les c\u00e9l\u00e9brations en Tha\u00eflande sont nombreuses, la communaut\u00e9 sino-tha\u00eflandaise repr\u00e9sentant une part importante de la population. Je ne pourrai \u00e9videmment pas \u00eatre exhaustif car des festivit\u00e9s il y en aura un peu partout, plus ou moins grandes mais voici les plus importantes.<\/p>\n<figure id=\"attachment_14614\" aria-describedby=\"caption-attachment-14614\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14614\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019.jpg\" alt=\"nouvel an chinois 2019 thailande\" width=\"750\" height=\"423\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019-711x401.jpg 711w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019-624x352.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-14614\" class=\"wp-caption-text\">Le Nouvel An Chinois 2019 sera c\u00e9l\u00e9br\u00e9 le 5 f\u00e9vrier<\/figcaption><\/figure>\n<h2>\u00a03 villes choisies par la TAT<\/h2>\n<p>L&#8217;Autorit\u00e9 du Tourisme de Tha\u00eflande (TAT) organise les c\u00e9l\u00e9brations du Nouvel An chinois 2019 dans trois lieux principaux, <strong>Bangkok \u00e0 Siam Square et Yaowarat Road, Chiang Mai au centre commercial Maya Lifestyle et Phuket \u00e0 Central Phuket Floresta<\/strong>.<\/p>\n<h2>Les principales c\u00e9l\u00e9brations en Tha\u00eflande<\/h2>\n<p>La plupart des c\u00e9l\u00e9brations du Nouvel An chinois 2019 auront lieu du 4 au 10 f\u00e9vrier parfois plus tard.<\/p>\n<h3>Nouvel An \u00e0 Chinatown \u00e0 Bangkok (5-6 f\u00e9vrier)<\/h3>\n<p>Le lieu principal des c\u00e9l\u00e9brations sera la Grande Porte Chinoise sur Yaowarat Road (en face du Wat Traimit).<\/p>\n<p>Son Altesse Royale la princesse Maha Chakri Sirindhorn pr\u00e9sidera le Bangkok Chinatown Festival 2019. La c\u00e9l\u00e9bration, qui dure deux jours, pr\u00e9sentera des spectacles culturels chinois, des d\u00e9fil\u00e9s de dragons et danses de lion, des stands de rue vendant de la nourriture chinoise, des d\u00e9corations de lanternes, une exposition racontant l\u2019histoire de la communaut\u00e9 de Yaowarat et des spectacles d\u2019artistes renomm\u00e9s et de pop stars.<\/p>\n<p><em>Vous retrouverez le programme d\u00e9taill\u00e9 des c\u00e9l\u00e9brations ici dans mon article d\u00e9di\u00e9 au <a href=\"\/blog\/index.php\/14634-programme-du-nouvel-an-chinois-2019-a-bangkok\"><strong>Nouvel An Chinois 2019 \u00e0 Bangkok<\/strong><\/a>.<br \/>\n<\/em><\/p>\n<h3>Bangkok Siam Square (4-6 f\u00e9vrier)<\/h3>\n<p>Les festivit\u00e9s seront organis\u00e9es au Siam Square 5-7.<\/p>\n<p>Des repr\u00e9sentants des gouvernements de la Chine et de la Tha\u00eflande pr\u00e9senteront leurs salutations pour c\u00e9l\u00e9brer l\u2019ann\u00e9e propice du cochon. Cet \u00e9v\u00e9nement de deux jours comprend une s\u00e9rie de spectacles culturels en provenance de Chine et de Tha\u00eflande, des d\u00e9monstrations de diverses formes d&#8217;art chinois, notamment du d\u00e9coupage du papier (Jianzhi) et de la calligraphie, une vente de produits \u00e9quitables et de la bonne nourriture, ainsi que des performances d&#8217;artistes et de pop c\u00e9l\u00e8bres. \u00e9toiles.<\/p>\n<h3>Pak Nam Pho Nouvel An chinois \u00e0 Nakhon Sawan (29 jan-9 f\u00e9v)<\/h3>\n<p>Les festivit\u00e9s auront lieu essentiellement \u00e0 la &#8220;plage&#8221; au bord de la rivi\u00e8re au d\u00e9but de la rivi\u00e8re Chao Phraya (Paknam Pho). il est consid\u00e9r\u00e9 par certains comme le plus important festival du Nouvel An Chinois de Tha\u00eflande.<\/p>\n<p>Il y aura des processions notamment celles de Chao Pho-Chao, Mae Paknam Pho et Chao Mae Kuan-im (Guan Yin) et\u00a0 une s\u00e9rie de rituels superstitieux et de tirages au sort. Au programme aussi des spectacles acrobatiques, les d\u00e9fil\u00e9s de dragons et danses du lion, les d\u00e9fil\u00e9s d&#8217;anges et des spectacles culturels en provenance de Chine. L&#8217;\u00e9clairage et la d\u00e9coration festifs du Nouvel An ainsi qu&#8217;un spectacle de son et lumi\u00e8re compl\u00e8teront les performances d&#8217;artistes et de stars de la pop renomm\u00e9s.<\/p>\n<h3>Festival du Nouvel An chinois \u00e0 Chiang Mai (5-6 f\u00e9vrier)<\/h3>\n<p>Les c\u00e9l\u00e9brations les plus int\u00e9ressantes auront lieu dans le quartier chinois de Chiang Mai qui se\u00a0 trouve autour du march\u00e9 Warorot. Il y aura une sc\u00e8ne install\u00e9e entre le 7 Eleven et le march\u00e9 qui accueillera chaque soir des performances de danses et th\u00e9\u00e2tre cultuel chinois ainsi que des concours d&#8217;enfants et de miss. Alors que Lao Zhou Alley sera le rue la plus anim\u00e9e pour l&#8217;occasion. il y aura aussi une parade du dragon nocturne chaque soir.<\/p>\n<p><em>J&#8217;ai r\u00e9ussi \u00e0 r\u00e9cup\u00e9rer un programme pr\u00e9cis et d\u00e9taill\u00e9 que j&#8217;ai compil\u00e9 dans mon article sur le <a href=\"\/blog\/index.php\/14616-programme-du-nouvel-an-chinois-2019-a-chiang-mai\"><strong>Nouvel An Chinois \u00e0 Chiang Mai.<\/strong><\/a><\/em><\/p>\n<p>Le centre commercial Maya Lifestyle proposera quant \u00e0 lui aussi des spectacles culturels en provenance de Chine et de Tha\u00eflande et des spectacles d&#8217;artistes c\u00e9l\u00e8bres et de stars de la pop, ainsi qu&#8217;un un salon vendant de la nourriture, des produits et des articles de mode chinois.<\/p>\n<h3>Nouvel An chinois d&#8217;Udon Thani (5-7 f\u00e9vrier)<\/h3>\n<p>Les festivit\u00e9s seront essentiellement concentr\u00e9es sur Prajak Sillapakom Road.<\/p>\n<p>Il y aura une s\u00e9rie de rituels superstitieux de bonne fortune<strong> au temple chinois Wat Sunthorn Pradit <\/strong>mais c&#8217;est toute une partie de la ville qui va s&#8217;animer. Parmi les autres activit\u00e9s: un d\u00e9fil\u00e9 spectaculaire de danses du lion, le concours de talents de China Town Kids, le concours de beaut\u00e9 Miss Udon Thani China Town et des stands de rue vendant de la nourriture chinoise.<\/p>\n<h3>Nouvel an chinois \u00e0 Korat (5-7 f\u00e9vrier)<\/h3>\n<p>Korat est l&#8217;autre nom de Nakhon Ratchasima. Le coeur des festivit\u00e9s sera\u00a0 Chomphon Road (de la porte de Chompho au bazar nocturne de Suanmak).<\/p>\n<p>Avec le Festival international d&#8217;art et de culture de Korat qui se tient du 4 au 7 f\u00e9vrier, des activit\u00e9s suppl\u00e9mentaires incluent des spectacles d&#8217;art et de culture locaux et internationaux, des d\u00e9monstrations de diverses formes d&#8217;art chinois comme la peinture et la calligraphie traditionnelles chinoises. Profitez du d\u00e9fi de cuisine chinoise, du concours de talents de China Town Kids et d&#8217;une foire gastronomique de restaurants chinois c\u00e9l\u00e8bres.<\/p>\n<h3>Nouvel an chinois \u00e0 Ratchaburi (4-7 f\u00e9vrier)<\/h3>\n<p>Le lieu principal des festivit\u00e9s sera le barrage Raj Pracha Pattana dans la municipalit\u00e9 de Ratchaburi.<\/p>\n<p>Vous pourrez assister \u00e0 des spectacles culturels,\u00a0 un spectacle son et lumi\u00e8re et un feu d&#8217;artifice, au concours de beaut\u00e9 Mister et Miss China Town, au concours Little Mister et \u00e0 Mlle China Town Kids, \u00e0 la spectaculaire procession du Nouvel An chinois et \u00e0 une cuisine de bienfaisance compos\u00e9e de nouilles chinoises de bon augure.<\/p>\n<h3>Le miracle du Nouvel An chinois \u00e0 Ayutthaya (6-11 f\u00e9vrier)<\/h3>\n<p>les festivit\u00e9s auront essentiellement lieu sur Naresuan Road.<\/p>\n<p>Vous verrez un hommage aux esprits gardiens d&#8217;<a href=\"\/villes\/ayutthaya\">Ayutthaya<\/a> dans 108 sanctuaires, un concours de d\u00e9fil\u00e9 de sanctuaires de 16 districts, concours de d\u00e9coration de lanterne, une procession spectaculaire de danses du lion, danses du dragon et acrobates, les concours de Miss China Town et Little Miss China Town, des spectacles culturels et spectacles de groupes et de chanteurs renomm\u00e9s.<\/p>\n<h3>Nouvel An chinois \u00e0 Phetchaburi (5-6 f\u00e9vrier)<\/h3>\n<p>Ce sera sur Surin Ruechai Road (route 18) que se tiendront les principales c\u00e9l\u00e9brations.<\/p>\n<p>Vous y verrez un hommage aux dieux chinois et aux esprits gardiens de <a href=\"\/villes\/phetchaburi\">Phetchaburi<\/a> et pourrez savourer une cuisine de bienfaisance compos\u00e9e de nouilles chinoises de bon augure dans une danse g\u00e9ante \u00e0 la casserole, des danses du lion et du dragon, des acrobates et danses traditionnelles chinoises, ainsi que de repr\u00e9sentations de jeunes et de groupes et chanteurs renomm\u00e9s.<\/p>\n<h3>Nouvel An chinois \u00e0 Suphanburi (5-7 f\u00e9vrier)<\/h3>\n<p>C&#8217;est le Dragon Descendants Museum et ses alentours qui accueilleront les festivit\u00e9s et c\u00e9l\u00e9brations.<\/p>\n<p>Il y aura un hommage aux esprits gardiens de la province au sanctuaire du pilier de la ville de Suphanburi, des repr\u00e9sentations de \u00abDragon Descendants\u00bb, qui comprennent des danses du lion, des danses de tambour, des danses du dragon, des spectacles d&#8217;art martial, des danses de Guan Yin et des spectacles d&#8217;op\u00e9ra chinois (bian lian) ainsi qu&#8217;une foire locale.<\/p>\n<h3>Nouvel An Chinois \u00e0 Pattaya (5 f\u00e9vrier)<\/h3>\n<p>Festivit\u00e9s au Central Pattaya Beach et dans la Walking Street.<\/p>\n<p>J&#8217;ai plus d&#8217;infos sur ces c\u00e9l\u00e9brations, je vous les partagerai bient\u00f4t mais vous pourrez profiter de spectacles culturels tha\u00ef-chinois, de danses du lion et du dragon, d&#8217;une exposition sur le nouvel an chinois et de concerts en direct de groupes et chanteurs c\u00e9l\u00e8bres.<\/p>\n<p><em>Article \u00e0 venir avec plus d&#8217;infos.<\/em><\/p>\n<h3>Nouvel An chinois \u00e0 Hat Yai (5-8 f\u00e9vrier)<\/h3>\n<p>A l&#8217;\u00e9cole Nakhon Foundation School.<\/p>\n<p>Au programme, des d\u00e9fil\u00e9s de dragons avec un dragon g\u00e9ant de 20 m\u00e8tres de long et des danses du lion, des repr\u00e9sentations culturelles en Chine, un concours de talents de China Town Kids, un concours de beaut\u00e9 de Miss Hatyai Chinese New Year et une authentique foire de la cuisine chinoisesans oublier les \u00e9corations de lanternes chinoises et remise de 999 fruits propices (p\u00eache chinoise) au bonheur et \u00e0 la prosp\u00e9rit\u00e9.<\/p>\n<h3>Festival du Nouvel An chinois \u00e0 Phuket (5-12 f\u00e9vrier)<\/h3>\n<p>Au Central Phuket Floresta, vous pourrez assister \u00e0 des spectacles culturels en provenance de Chine et de Tha\u00eflande, des spectacles d&#8217;artistes c\u00e9l\u00e8bres et de stars de la pop, et \u00e0 un salon vendant de la nourriture, des produits et des articles de mode chinois (5 et 6 f\u00e9vrier)<\/p>\n<p><strong>Dans la vieille ville de Phuket, <\/strong>les c\u00e9l\u00e9brations se tiendront du 10-12 f\u00e9vrier avec une procession spectaculaire, des d\u00e9corations des lanternes, spectacles culturels et d&#8217;une foire gastronomique locale \u00e0 Phuket.<\/p>\n<h3>Nouvel An chinois \u00e0 Trang (3-5 f\u00e9vrier)<\/h3>\n<p>Lieu principal: cercle de la tour de l&#8217;horloge de Trang.<\/p>\n<p>Vous pourrez d\u00e9guster une grande vari\u00e9t\u00e9 de mets chinois de bon augure et une collation, essayer des ateliers de bricolage et de d\u00e9coupage de fruits&#8230;<\/p>\n<p>Ce n&#8217;est bien \u00e9videmment pas complet, beaucoup de sanctuaires chinois et de communaut\u00e9s chinoises organiseront des c\u00e9l\u00e9brations pour l&#8217;occasion.<\/p>\n<h2>Nouvel An Chinois \u00e0 Koh Samui<\/h2>\n<p>A Koh Samui, il semble que les c\u00e9l\u00e9brations les plus grandes auront lieu \u00e0 Nathon. Au Hainan Temple, en ville et au port <em>(<a href=\"https:\/\/zonesamui.com\/2019\/01\/les-festivites-du-nouvel-an-chinois-a-koh-samui\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">voir cet article<\/a>). <\/em>Il y aura aussi des c\u00e9l\u00e9bration au temple chinois de Maenam et au grand Guan Yu Shrine mais je n&#8217;ai pas le d\u00e9tail et les horaires.<\/p>\n<p><em>N&#8217;oubliez pas de consulter r\u00e9guli\u00e8rement la page <a href=\"\/evenements-thailande\/\"><strong>\u00e9v\u00e9nements en Tha\u00eflande<\/strong><\/a> du site pour conna\u00eetre les dates des festivals \u00e0 venir.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Nouvel An Chinois, c&#8217;est dans une semaine et les c\u00e9l\u00e9brations en Tha\u00eflande sont nombreuses,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-14613","post","type-post","status-publish","format-standard","hentry","category-festivals-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e9l\u00e9brations du Nouvel An chinois 2019 en Tha\u00eflande<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e9l\u00e9brations du Nouvel An chinois 2019 en Tha\u00eflande\" \/>\n<meta property=\"og:description\" content=\"Le Nouvel An Chinois, c&#8217;est dans une semaine et les c\u00e9l\u00e9brations en Tha\u00eflande sont nombreuses,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-29T10:45:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-18T05:21:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e9l\u00e9brations du Nouvel An chinois 2019 en Tha\u00eflande","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande","og_locale":"fr_FR","og_type":"article","og_title":"C\u00e9l\u00e9brations du Nouvel An chinois 2019 en Tha\u00eflande","og_description":"Le Nouvel An Chinois, c&#8217;est dans une semaine et les c\u00e9l\u00e9brations en Tha\u00eflande sont nombreuses,","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2019-01-29T10:45:03+00:00","article_modified_time":"2020-01-18T05:21:39+00:00","og_image":[{"url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"C\u00e9l\u00e9brations du Nouvel An chinois 2019 en Tha\u00eflande","datePublished":"2019-01-29T10:45:03+00:00","dateModified":"2020-01-18T05:21:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande"},"wordCount":1617,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019.jpg","articleSection":["Ev\u00e9nements et Festivals"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande","url":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande","name":"C\u00e9l\u00e9brations du Nouvel An chinois 2019 en Tha\u00eflande","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019.jpg","datePublished":"2019-01-29T10:45:03+00:00","dateModified":"2020-01-18T05:21:39+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande#primaryimage","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nouvel-anchinis-thailande-2019.jpg","width":750,"height":423,"caption":"Le Nouvel An Chinois 2019 sera c\u00e9l\u00e9br\u00e9 le 5 f\u00e9vrier"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14613-celebrations-du-nouvel-an-chinois-2019-en-thailande#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"C\u00e9l\u00e9brations du Nouvel An chinois 2019 en Tha\u00eflande"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/14613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=14613"}],"version-history":[{"count":3,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/14613\/revisions"}],"predecessor-version":[{"id":16006,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/14613\/revisions\/16006"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=14613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=14613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=14613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}