{"id":14124,"date":"2018-10-29T07:15:05","date_gmt":"2018-10-29T05:15:05","guid":{"rendered":"https:\/\/www.thailandee.com\/blog\/?p=14124"},"modified":"2018-10-29T07:15:05","modified_gmt":"2018-10-29T05:15:05","slug":"chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde","title":{"rendered":"Chiang Mai parmi  les 20 meilleures petites villes du monde"},"content":{"rendered":"<p>Dans la famille des bons classements touristiques de la Tha\u00eflande, je demande, <a href=\"\/villes\/chiang-mai\"><strong>Chiang Mai<\/strong><\/a>. La Rose du Nord a r\u00e9cemment \u00e9t\u00e9 <strong>class\u00e9e parmi les 20 meilleures petites villes du monde<\/strong> par les <em>\u00ab\u00a0Readers Choice Awards\u00a0\u00bb<\/em> du magazine <em>Cond\u00e9 Nast Traveller UK<\/em>. Un classement logique pour une ville riche tant historiquement que culturellement, architecturalement et gastronomiquement\u00a0qui a mont\u00e9 un dossier cette ann\u00e9e pour \u00eatre class\u00e9e au Patrimoine mondial de l&rsquo;UNESCO.<\/p>\n<figure id=\"attachment_13204\" aria-describedby=\"caption-attachment-13204\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13204\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10.jpg\" alt=\"chiang mai doi suthep\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-13204\" class=\"wp-caption-text\">Temple Wat Phra That Doi Suthep qui domine Chiang Mai sur sa montagne<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Chiang Mai, 15\u00e8me meilleure \u00ab\u00a0petite ville\u00a0\u00bb du monde<\/h2>\n<p>Les lecteurs de\u00a0<em>Conde Nast Traveler UK<\/em> dans leur palmar\u00e8s 2018 avaient d\u00e9j\u00e0 class\u00e9 la Tha\u00eflande 3\u00e8me dans la cat\u00e9gorie Meilleur pays du monde. Ils ont \u00e9galement plac\u00e9 Chiang Mai quinzi\u00e8me meilleure petite ville du monde 2018.<\/p>\n<p>M. Yuthasak Supasorn, Gouverneur de l&rsquo;Office du tourisme de Tha\u00eflande (TAT), ravi, a d\u00e9clar\u00e9: <em>\u00abChiang Mai, avec sa charmante culture de l&rsquo;ancienne capitale Lanna, son climat agr\u00e9able et ses belles collines, a toujours \u00e9t\u00e9 populaire aupr\u00e8s des touristes locaux et internationaux. J&rsquo;aimerais remercier les lecteurs de Cond\u00e9 Nast Traveller d&rsquo;avoir d\u00e9sign\u00e9 Chiang Mai comme l&rsquo;une des 20 meilleures petites villes du monde 2018 \u00bb.<\/em><\/p>\n<figure id=\"attachment_12062\" aria-describedby=\"caption-attachment-12062\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12062 size-full\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/yee-peng-festival-chiangmai-1-1.jpg\" alt=\"yi peng festival\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/yee-peng-festival-chiangmai-1-1.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/yee-peng-festival-chiangmai-1-1-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/yee-peng-festival-chiangmai-1-1-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-12062\" class=\"wp-caption-text\">Chiang Mai est aussi une des villes avec le plus des festivals en Tha\u00eflande<\/figcaption><\/figure>\n<p>Pr\u00e8s d&rsquo;un demi-million de lecteurs du magazine Cond\u00e9 Nast Traveler ont soumis un nombre record de r\u00e9ponses \u00e9valuant leurs exp\u00e9riences de voyage afin d&rsquo;\u00e9tablir les diff\u00e9rents classements de leurs <em>\u00ab\u00a0Readers Choice Awards\u00a0\u00bb<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<h2>Les atouts de Chiang Mai<\/h2>\n<p>Selon Cond\u00e9 Nast Traveler , <em>\u00abil y a une raison pour laquelle tant de voyageurs se rendent \u00e0 Chiang Mai lorsqu&rsquo;ils visitent la Tha\u00eflande: la ville est sans aucun doute la capitale culturelle du pays.[&#8230;] Ensuite, il y a les march\u00e9s comme celui de Warorot, la richesse esth\u00e9tique des temples et de la nature&#8230;\u00a0\u00bb<br \/>\n<\/em><\/p>\n<p>Ajoutez la Street Food, les tr\u00e8s nombreux \u00e9v\u00e9nements dans une des villes qui est probablement parmi celles qui organisent le plus de <a href=\"\/evenements-thailande\/\">festivals en Tha\u00eflande<\/a>, ses temples, sa forte culture et ses traditions, ses restaurants et caf\u00e9s aux superbes d\u00e9cors et aux odeurs et saveurs gourmandes, ses centres commerciaux, ses montagnes proches, ses paysages de rizi\u00e8res qui c\u00f4toient la ville, sa fra\u00eecheur en hiver (enfin par rapport au reste du pays) et vous avez tout ce qui explique cet engouement.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12956\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/makha-bucha-chiang-mai-246.jpg\" alt=\"makha bucha wat chedi luang\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/makha-bucha-chiang-mai-246.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/makha-bucha-chiang-mai-246-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/makha-bucha-chiang-mai-246-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Mais dans tout \u00e7a il y a un hic, souvent pass\u00e9 sous silence: la pollution ! Elev\u00e9e en temps normal mais pour quelques jours de vacances, ce n&rsquo;est pas si grave, irrespirable pendant les \u00e9cobuages qui durent de g\u00e9n\u00e9ral de mi-f\u00e9vrier \u00e0 avril avec des pics r\u00e9guliers pendant lesquels le port d&rsquo;un masque anti-particules est conseill\u00e9.<\/p>\n<p><em>Vous retrouverez sur le site toutes les informations sur les transports pour venir, les visites \u00e0 faire, les h\u00f4tels, les moyens de transports, les festivals&#8230; sur <a href=\"\/villes\/chiang-mai\" target=\"_blank\" rel=\"nofollow noopener\">la page consacr\u00e9e \u00e0 Chiang Mai<\/a>. Et n&rsquo;oubliez pas de pousser votre route un peu plus loin, jusqu&rsquo;\u00e0 <a href=\"\/villes\/chiang-rai\"><strong>Chiang Rai<\/strong><\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans la famille des bons classements touristiques de la Tha\u00eflande, je demande, Chiang Mai. La<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-14124","post","type-post","status-publish","format-standard","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiang Mai parmi les 20 meilleures petites villes du monde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiang Mai parmi les 20 meilleures petites villes du monde\" \/>\n<meta property=\"og:description\" content=\"Dans la famille des bons classements touristiques de la Tha\u00eflande, je demande, Chiang Mai. La\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-29T05:15:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde\"},\"author\":{\"name\":\"Mike Thailandee\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#\\\/schema\\\/person\\\/81de2c00b06eafce517ef9c7ce602274\"},\"headline\":\"Chiang Mai parmi les 20 meilleures petites villes du monde\",\"datePublished\":\"2018-10-29T05:15:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde\"},\"wordCount\":531,\"publisher\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/doi-suthep-matinal-10.jpg\",\"articleSection\":[\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde\",\"name\":\"Chiang Mai parmi les 20 meilleures petites villes du monde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/doi-suthep-matinal-10.jpg\",\"datePublished\":\"2018-10-29T05:15:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#primaryimage\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/doi-suthep-matinal-10.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/doi-suthep-matinal-10.jpg\",\"width\":750,\"height\":500,\"caption\":\"Temple Wat Phra That Doi Suthep qui domine Chiang Mai sur sa montagne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.thailandee.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiang Mai parmi les 20 meilleures petites villes du monde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/\",\"name\":\"Le blog de Thailandee.com\",\"description\":\"voyage, conseils et informations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#organization\",\"name\":\"Le blog de Thailandee.com\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/voyage-thailande.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/voyage-thailande.jpg\",\"width\":450,\"height\":248,\"caption\":\"Le blog de Thailandee.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ThailandeeFR\\\/\",\"https:\\\/\\\/x.com\\\/Thailandee_com\",\"http:\\\/\\\/instagram.com\\\/mikethailandee\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtClWMihNeyM_LhAXloywZQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#\\\/schema\\\/person\\\/81de2c00b06eafce517ef9c7ce602274\",\"name\":\"Mike Thailandee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g\",\"caption\":\"Mike Thailandee\"},\"description\":\"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.\",\"sameAs\":[\"http:\\\/\\\/www.thailandee.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/ThailandeeFR\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/twitter.com\\\/Thailandee_com\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtClWMihNeyM_LhAXloywZQ\"],\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/author\\\/asianmike\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiang Mai parmi les 20 meilleures petites villes du monde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde","og_locale":"fr_FR","og_type":"article","og_title":"Chiang Mai parmi les 20 meilleures petites villes du monde","og_description":"Dans la famille des bons classements touristiques de la Tha\u00eflande, je demande, Chiang Mai. La","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2018-10-29T05:15:05+00:00","og_image":[{"url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Chiang Mai parmi les 20 meilleures petites villes du monde","datePublished":"2018-10-29T05:15:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde"},"wordCount":531,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10.jpg","articleSection":["G\u00e9n\u00e9ral"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde","url":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde","name":"Chiang Mai parmi les 20 meilleures petites villes du monde","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10.jpg","datePublished":"2018-10-29T05:15:05+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#primaryimage","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/doi-suthep-matinal-10.jpg","width":750,"height":500,"caption":"Temple Wat Phra That Doi Suthep qui domine Chiang Mai sur sa montagne"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/14124-chiang-mai-parmi-les-20-meilleures-petites-villes-du-monde#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Chiang Mai parmi les 20 meilleures petites villes du monde"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/14124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=14124"}],"version-history":[{"count":2,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/14124\/revisions"}],"predecessor-version":[{"id":14149,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/14124\/revisions\/14149"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=14124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=14124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=14124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}