{"id":11665,"date":"2017-09-27T05:05:48","date_gmt":"2017-09-27T03:05:48","guid":{"rendered":"https:\/\/www.thailandee.com\/blog\/?p=11665"},"modified":"2022-10-02T09:18:23","modified_gmt":"2022-10-02T07:18:23","slug":"koh-samui-hors-des-sentiers-battus","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus","title":{"rendered":"Koh Samui hors des sentiers battus"},"content":{"rendered":"<p>Quand on pense \u00e0 <a href=\"\/villes\/koh-samui\"><strong>Koh Samui<\/strong><\/a>, on pense plage, cocotiers, Big Buddha mais on ne s&#8217;imagine pas forc\u00e9ment qu&#8217;on peut aller y crapahuter dans la montagne, faire des treks, trouver des petites cascades perdues, des plantations de fruits en tout genre et notamment du fameux durian ni m\u00eame que l&#8217;\u00eele est une des plus grosses productrices de noix de coco ou de caoutchouc du pays. C&#8217;est cette facette de Koh Samui, la <em>&#8220;Samui de l&#8217;int\u00e9rieur&#8221;<\/em>, on va dire, que j&#8217;ai eu envie de d\u00e9couvrir hier avec une agence fran\u00e7aise <a href=\"\/excursions-activites\/compagnie-samui-insolite-2\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><em>Samui Insolite<\/em><\/strong><\/a> et de vous faire d\u00e9couvrir dans cet article. La m\u00e9t\u00e9o n&#8217;\u00e9tait pas des plus favorables mais \u00e7a vous donne une id\u00e9e\u2026 et quand vous viendrez ce sera encore plus beau ! \ud83d\ude09<\/p>\n<figure id=\"attachment_11666\" aria-describedby=\"caption-attachment-11666\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11666\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile.jpg\" alt=\"sommet koh samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile-713x401.jpg 713w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11666\" class=\"wp-caption-text\">Vue du sommet de Koh Samui<\/figcaption><\/figure>\n<h1>Des fruits et des cascades<\/h1>\n<p>Premi\u00e8re \u00e9tape de cette journ\u00e9e, mont\u00e9e dans les montagnes en 4&#215;4 \u00e0 travers les plantations de fruits et surtout de durians, le fruit le plus populaire en Tha\u00eflande, ils le surnomment le <em>&#8220;roi des fruits&#8221;<\/em>, alors que nous les occidentaux, on a plus tendance \u00e0 en parler comme &#8216;le fruit qui pue &#8221; ;).<\/p>\n<figure id=\"attachment_11667\" aria-describedby=\"caption-attachment-11667\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11667\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-durian.jpg\" alt=\"durian fruit\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-durian.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-durian-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-durian-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11667\" class=\"wp-caption-text\">Le durian est le fruit le plus populaire en Tha\u00eflande&#8230; et aussi le plus cher<\/figcaption><\/figure>\n<p>Bananes, fruits du dragon, Jack fruits, ramboutans, arbres \u00e0 mangoustans (mais sans mangoustans, c&#8217;est pas la saison)\u2026, cette balade permet de se familiariser avec ces fruits vraiment typiques de cette r\u00e9gion du monde et qu&#8217;on voit tr\u00e8s peu voire pas du tout en France et aussi de voir l&#8217;arbre qui les produit. On peut \u00eatre \u00e9tonn\u00e9 notamment sur l&#8217;arbre \u00e0 dragon fruits.<\/p>\n<figure id=\"attachment_11668\" aria-describedby=\"caption-attachment-11668\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11668\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/fruits-dragon.jpg\" alt=\"Un fruit du dragon sur les hauteurs de Samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/fruits-dragon.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/fruits-dragon-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/fruits-dragon-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11668\" class=\"wp-caption-text\">Un fruit du dragon sur les hauteurs de Samui<\/figcaption><\/figure>\n<p>On stoppe le 4X4 qui m\u00e9rite bien une pause apr\u00e8s cette ascension. Le chauffeur, L\u00e9andre, aussi mais pour lui pas de repos, il nous guide pour\u00a0la petite marche dans la for\u00eat jusqu&#8217;\u00e0 la Khun Si Waterfall, petite cascade sans personne, rien que pour nous.<\/p>\n<figure id=\"attachment_11669\" aria-describedby=\"caption-attachment-11669\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11669\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/samui-khun-si-waterfall.jpg\" alt=\"samui waterfall\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/samui-khun-si-waterfall.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/samui-khun-si-waterfall-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/samui-khun-si-waterfall-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11669\" class=\"wp-caption-text\">Khun Si Waterfall, un peu perdue dans les montagnes de Samui<\/figcaption><\/figure>\n<p>J&#8217;enfile mon maillot de bain et plouf dans l&#8217;eau fra\u00eeche. Et je suis \u00e9tonn\u00e9 que dans ce petit bassin, il y ait de la profondeur et notamment un endroit o\u00f9 je n&#8217;ai pas pieds. Le d\u00e9bit de la cascade n&#8217;est lui pas \u00e0 son maximum, c&#8217;est \u00e0 la fin de la saison des pluies \u00e0 Samui en janvier qu&#8217;il est le plus impressionnant.<\/p>\n<p>On reprend le chemin, on s&#8217;arr\u00eate dans une maison en construction dont la plateforme offre une jolie vue sur la mer et <a href=\"\/villes\/koh-phangan\">Koh Phangan<\/a> en face, on voit m\u00eame Koh Tao au fond, pour se restaurer de bananes <em>&#8220;du jardin&#8221;\u00a0<\/em>et boire.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11670\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur.jpg\" alt=\"vue samui phangan\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Mais question vue dominante \u00e0 Koh Samui, on peut faire beaucoup mieux et on va faire beaucoup mieux ! C&#8217;est la prochaine \u00e9tape\u2026<\/p>\n<p>En chemin on croise des singes dress\u00e9s \u00e0 monter sur les cocotiers et d\u00e9crocher les noix. Probablement pas les singes les plus heureux du monde mais c&#8217;est encore beaucoup comme \u00e7a que la r\u00e9colte se fait.<\/p>\n<figure id=\"attachment_11671\" aria-describedby=\"caption-attachment-11671\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11671\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-suite-2.jpg\" alt=\"singe noix coco samui\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-suite-2.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-suite-2-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-suite-2-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11671\" class=\"wp-caption-text\">Singe cueilleur de noix de coco<\/figcaption><\/figure>\n<h2>Sur le to\u00eet de Samui<\/h2>\n<p>On redescend sur Maenam puis on reprend une route vers les hauteurs, direction de le sommet de Koh Samui. La mont\u00e9e est sportive, il faut \u00eatre un conducteur aguerri et avoir un bon v\u00e9hicule pour monter. Franchement ne vous aventurez par ici en scooter que si vous \u00eates un motard exp\u00e9riment\u00e9 et avez l&#8217;habitude des routes de montagnes difficiles. Et encore\u2026<br \/>\nBref, moi, je suis conduit \u00e0 bord d&#8217;un 4&#215;4 et je peux profiter du paysage et c&#8217;est tant mieux, je n&#8217;aurais jamais pu mener un scooter ou m\u00eame une voiture ici.<\/p>\n<figure id=\"attachment_11684\" aria-describedby=\"caption-attachment-11684\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11684\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/22052672_10155543446437530_1352114714_n.jpg\" alt=\"Voici le 4x4 qui nous a emmen\u00e9 toute la journ\u00e9e \u00e0 la d\u00e9couverte de l'int\u00e9rieur de l'\u00eele\" width=\"750\" height=\"563\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/22052672_10155543446437530_1352114714_n.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/22052672_10155543446437530_1352114714_n-534x401.jpg 534w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/22052672_10155543446437530_1352114714_n-624x468.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11684\" class=\"wp-caption-text\">Voici le 4&#215;4 qui nous a emmen\u00e9 toute la journ\u00e9e \u00e0 la d\u00e9couverte de l&#8217;int\u00e9rieur de l&#8217;\u00eele<\/figcaption><\/figure>\n<p>Car oui, vous voil\u00e0 au sommet. Il y a un temple, le Wat Hip Angkorn en construction avec notamment une grande plateforme avec un Bouddha debout et une vue sur Lama\u00ef.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11672\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-16.jpg\" alt=\"vue koh samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-16.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-16-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-16-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>J&#8217;ai vu d&#8217;autres touristes venir, faire un tour devant le Buddha pour regarder le panorama et repartir. Dommage, car en face, il y a un petit mus\u00e9e et au dernier \u00e9tage du mus\u00e9e, une vue \u00e0 360\u00b0 sur Koh Samui. Quand on vient seuls, on pa<\/p>\n<p>sse \u00e0 c\u00f4t\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11675\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-10.jpg\" alt=\"ko samui\" width=\"750\" height=\"265\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-10.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-10-624x220.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11673\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/22053294_10155543555752530_1053784296_n.jpg\" alt=\"vue sommet koh samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/22053294_10155543555752530_1053784296_n.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/22053294_10155543555752530_1053784296_n-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/22053294_10155543555752530_1053784296_n-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>J&#8217;aurais aim\u00e9 un beau ciel bleu avec quelques nuages blanc plus photog\u00e9nique que celui qui se pr\u00e9sente devant moi mais \u00e7a reste une magnifique vue. Il commence \u00e0 pleuvoir et il se fait faim comme on dit.<\/p>\n<p>Ca tombe bien, pas tr\u00e8s loin du temple apr\u00e8s la statue de Ganesh, vous avez un petit restaurant local, c&#8217;est l\u00e0 qu&#8217;on a mang\u00e9, tr\u00e8s bien mang\u00e9 !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11674\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-21.jpg\" alt=\"cuisine thaie samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-21.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-21-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-21-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>H\u00e9v\u00e9as et cocotiers<\/h2>\n<p>Le repas fini, le ciel est encore plus couvert. On r\u00e9embarque \u00e0 l&#8217;arri\u00e8re du pickup et on retour dans la vall\u00e9e dans la partie &#8220;campagnarde&#8221; de Lamai avec ses cocoteraies.<\/p>\n<p>L&#8217;\u00eele de Koh Samui n&#8217;est pas qu&#8217;une \u00eele touristique, c&#8217;est aussi une grosse productrice de noix de coco export\u00e9es ensuite sur le continent soit telle quelle, soit transform\u00e9es en huile notamment. On visite une exploitation, qui fabrique de l&#8217;huile et forc\u00e9ment, on est accueillis avec un cocktail de bienvenu, une noix de coco avec une paille \ud83d\ude09<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11676\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-22.jpg\" alt=\"noix coco samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-22.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-22-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-22-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>On remonte en voiture puis un peu plus loin, on traverse la plus longue for\u00eat d&#8217;h\u00e9v\u00e9as de Koh Samui. Le caoutchouc est l&#8217;autre production phare de l&#8217;\u00eele. On s&#8217;arr\u00eate regarder comment le latex est r\u00e9colt\u00e9 et un peu plus loin aux rouleaux qui servent \u00e0 l&#8217;aplatir en longs rectangles que l&#8217;on fait ensuite s\u00e9cher.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11677\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-25.jpg\" alt=\"h\u00e9v\u00e9s samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-25.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-25-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-25-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>Bang Kao et le Khao Chedi<\/h2>\n<p>S\u00e9cher, c&#8217;est ce dont on aurait bien besoin 10 minutes plus tard quand une grosse averse nous tombe dessus. On continue sur une petite route c\u00f4ti\u00e8re, le long de la plage de Bang Kao qui doit vraiment \u00eatre magnifique, on le devine malgr\u00e9 la pluie qui ternit ses couleurs, et est encore assez sauvage.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11678\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/laem-sor-pagoda-samui.jpg\" alt=\"laem sor pagoda\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/laem-sor-pagoda-samui.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/laem-sor-pagoda-samui-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/laem-sor-pagoda-samui-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Un petit tour \u00e0 la Laem Sor Pagoda alors que la pluie se fait plus discr\u00e8te avant de monter au Khao Chedi ou Rattanakosin Chedi, c&#8217;est comme vous voulez.<\/p>\n<p>Ce joli petit temple avec un petit chedi blanc, d&#8217;o\u00f9 son nom est un peu en hauteur et offre un jolie vue sur la baie de Bang Khao et sur la petite \u00eele de Koh Taen et sa voisine Koh Matsum.<br \/>\nVous avez aussi quelques statues de Bouddha dont un couch\u00e9 et surtout de jolis petit Boudhas blancs assis tout autour du chedi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11680\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/khao-chedi-koh-samii.jpg\" alt=\"khao chedi samui\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/khao-chedi-koh-samii.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/khao-chedi-koh-samii-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/khao-chedi-koh-samii-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<figure id=\"attachment_11679\" aria-describedby=\"caption-attachment-11679\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11679\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vue-koh-taen-khao-chedi-samui.jpg\" alt=\"koh taen samui\" width=\"750\" height=\"560\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vue-koh-taen-khao-chedi-samui.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vue-koh-taen-khao-chedi-samui-537x401.jpg 537w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vue-koh-taen-khao-chedi-samui-624x466.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11679\" class=\"wp-caption-text\">La petite ile de Koh Taen en face (bon spot de snorkeling)<\/figcaption><\/figure>\n<figure id=\"attachment_11681\" aria-describedby=\"caption-attachment-11681\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11681\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vue-khao-chedi-bang-kao.jpg\" alt=\"bang kao khao chedi\" width=\"750\" height=\"560\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vue-khao-chedi-bang-kao.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vue-khao-chedi-bang-kao-537x401.jpg 537w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vue-khao-chedi-bang-kao-624x466.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11681\" class=\"wp-caption-text\">Et la baie de Bang Kao en bas<\/figcaption><\/figure>\n<p>Voil\u00e0 qui ach\u00e8ve ma journ\u00e9e d\u00e9couverte de l&#8217;int\u00e9rieur de <strong>Koh Samui en dehors des sentiers battus<\/strong>.<\/p>\n<p>Je publierai dans quelques jours une vid\u00e9o de cette journ\u00e9e sur <a href=\"https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ\"><strong>ma cha\u00eene Youtube<\/strong><\/a>.<\/p>\n<h2>Samui insolite<\/h2>\n<p>Pour cette journ\u00e9e, j&#8217;ai \u00e9t\u00e9 invit\u00e9 par la petite agence <em><strong>Samui Insolite<\/strong><\/em> (coordonn\u00e9es \u00e0 la fin de l&#8217;article), cr\u00e9\u00e9e par Joss et L\u00e9andre, deux fran\u00e7ais qui connaissent l&#8217;\u00eele comme leur poche et qui se sont justement sp\u00e9cialis\u00e9s dans les tours \u00e0 la d\u00e9couverte d&#8217;une Samui moins touristique, plus authentique. Ils s&#8217;adaptent \u00e0 vos envies discutent avec vous pour d\u00e9finir le programme de la journ\u00e9e. C&#8217;est l&#8217;avantage d&#8217;\u00eatre en petit groupe car ils n&#8217;acceptent que jusqu&#8217;\u00e0 10 personnes maximum. Votre tour \u00e0 vous sera donc peut-\u00eatre un peu diff\u00e9rent car personnalis\u00e9.<\/p>\n<p><strong>Les sorties sont en Fran\u00e7ais,<\/strong> ils proposent plusieurs formules. Celle que j&#8217;ai faite, c&#8217;est la d\u00e9couverte en 4X4, mais ils proposent aussi <strong><a href=\"\/excursions-activites\/koh-tan-et-koh-matsum-en-bateau-traditionnel-150\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">une journ\u00e9e \u00e0 Koh Taen et Koh Matsum<\/a>,<\/strong> deux petites \u00eeles au Sud de Samui (snorkeling masque et tuba au milieu des poissons multicolores, p\u00eache et ap\u00e9ro dans un lagon avant de manger chez un habitant, d\u00e9couverte de la grotte aux chauve\u00a0 souris) qui a l&#8217;air vraiment sympa surtout en comparaison de ce que moi j&#8217;ai fait la veille en allant sur ces \u00eeles par mes propres moyens. Si n&#8217;avez qu&#8217;une journ\u00e9e \u00e0 faire avec eux, vous avez une sortie qui mixe les deux avec l&#8217;essentiel de ce que j&#8217;ai fait (cascade, sommet de l&#8217;\u00eele, cocoteraie) et ensuite direction la petite \u00eele de Koh Taen pour du snorkeling, de la p\u00eache, ap\u00e9ro dans un beau lagoon et un repas. La journ\u00e9e compl\u00e8te \u00e0 Koh Taen\u00a0a l&#8217;air vraiment sympa. Je la ferai s\u00fbrement la prochaine fois que je viens \u00e0 Samui<\/p>\n<figure id=\"attachment_11682\" aria-describedby=\"caption-attachment-11682\" style=\"width: 667px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11682\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-tean-snorkeling-5.jpg\" alt=\"snorkeling koh samui\" width=\"667\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-tean-snorkeling-5.jpg 667w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-tean-snorkeling-5-535x401.jpg 535w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-tean-snorkeling-5-624x468.jpg 624w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><figcaption id=\"caption-attachment-11682\" class=\"wp-caption-text\">Photo de mon snorkeling \u00e0 Koh Taen\u00a0 par mes propres moyens. Du coup, je n&#8217;ai fait que \u00e7a et un peu de plage)<\/figcaption><\/figure>\n<p>Ils ont d&#8217;autres tours. Vous retrouverez tout ce qu&#8217;ils proposent sur leur site : <a href=\"https:\/\/samui-insolite.com\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><strong>https:\/\/samui-insolite.com\/<\/strong><\/a>. Si vous \u00eates int\u00e9ress\u00e9s ou voulez plus d&#8217;infos, je vous invite \u00e0 les contacter via leur site ou\u00a0<a href=\"https:\/\/www.facebook.com\/ecotoursamui\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">leur page Facebook<\/a>.<\/p>\n<p><em>Je tiens \u00e0 pr\u00e9ciser que c&#8217;est moi qui les ai sollicit\u00e9s apr\u00e8s avoir regard\u00e9 ce qu&#8217;ils proposaient et leur philosophie qui est de vous faire d\u00e9couvrir Koh Samui diff\u00e9remment en faisant travailler les locaux. Si je\u00a0me suis greff\u00e9 \u00e0 un de leurs tours sans payer ma place, je n&#8217;ai touch\u00e9 aucun argent de leur\u00a0part\u00a0et ne toucherai bien \u00e9videmment\u00a0aucune commission si jamais vous d\u00e9cidez de faire un tour avec eux. Je les recommande parce que c&#8217;est vraiment bien, en Fran\u00e7ais et diff\u00e9rent des tours de tourisme de masse qu&#8217;on trouve \u00e0 la pelle dans les agences de Samui.<\/em><\/p>\n<p><strong><em>Samui Insolite<\/em><\/strong><br \/>\n<i>Toutes leurs excursions \u00e0 Koh Samui et contact via cette page: <a href=\"\/excursions-activites\/compagnie-samui-insolite-2\">https:\/\/www.thailandee.com\/excursions-activites\/compagnie-samui-insolite-2<\/a><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand on pense \u00e0 Koh Samui, on pense plage, cocotiers, Big Buddha mais on ne<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-11665","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Koh Samui hors des sentiers battus<\/title>\n<meta name=\"description\" content=\"Koh Samui ce n&#039;est pas que des plages et un Big Buddha. Je vous emm\u00e8ne d\u00e9couvrir une Samui hors des sentiers battus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Koh Samui hors des sentiers battus\" \/>\n<meta property=\"og:description\" content=\"Koh Samui ce n&#039;est pas que des plages et un Big Buddha. Je vous emm\u00e8ne d\u00e9couvrir une Samui hors des sentiers battus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-27T03:05:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-02T07:18:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Koh Samui hors des sentiers battus","description":"Koh Samui ce n'est pas que des plages et un Big Buddha. Je vous emm\u00e8ne d\u00e9couvrir une Samui hors des sentiers battus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus","og_locale":"fr_FR","og_type":"article","og_title":"Koh Samui hors des sentiers battus","og_description":"Koh Samui ce n'est pas que des plages et un Big Buddha. Je vous emm\u00e8ne d\u00e9couvrir une Samui hors des sentiers battus","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-09-27T03:05:48+00:00","article_modified_time":"2022-10-02T07:18:23+00:00","og_image":[{"url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Koh Samui hors des sentiers battus","datePublished":"2017-09-27T03:05:48+00:00","dateModified":"2022-10-02T07:18:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus"},"wordCount":1677,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus","url":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus","name":"Koh Samui hors des sentiers battus","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile.jpg","datePublished":"2017-09-27T03:05:48+00:00","dateModified":"2022-10-02T07:18:23+00:00","description":"Koh Samui ce n'est pas que des plages et un Big Buddha. Je vous emm\u00e8ne d\u00e9couvrir une Samui hors des sentiers battus","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus#primaryimage","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/koh-samui-interieur-ile.jpg","width":750,"height":422,"caption":"Vue du sommet de Koh Samui"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11665-koh-samui-hors-des-sentiers-battus#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Koh Samui hors des sentiers battus"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=11665"}],"version-history":[{"count":15,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11665\/revisions"}],"predecessor-version":[{"id":18677,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11665\/revisions\/18677"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=11665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=11665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=11665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}