{"id":11642,"date":"2017-09-24T13:20:42","date_gmt":"2017-09-24T11:20:42","guid":{"rendered":"https:\/\/www.thailandee.com\/blog\/?p=11642"},"modified":"2017-09-24T14:59:43","modified_gmt":"2017-09-24T12:59:43","slug":"chiang-mai-koh-samui-en-avion-via-surat-thani","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani","title":{"rendered":"Chiang Mai &#8211; Koh Samui en avion via Surat Thani"},"content":{"rendered":"<p>De Chiang Mai, on a parfois envie d&#8217;aller directement sur une \u00eele, un \u00eele du Golfe de Tha\u00eflande comme <a href=\"\/villes\/koh-samui\"><strong>Koh Samui<\/strong><\/a> par exemple. La solution la plus simple est de prendre un vol direct de Bangkok Airways mais une solution souvent plus populaire car 2 \u00e0 3\u00a0fois moins ch\u00e8re selon les opportunit\u00e9s, c&#8217;est de prendre l&#8217;avion jusqu&#8217;\u00e0 Surat Thani et ensuite de continuer en bus puis bateau jusqu\u2019\u00e0 Koh Samui. C&#8217;est ce que j&#8217;ai fait hier. Je vous explique ce trajet en d\u00e9tails. Evidemment, <strong>on peut faire de m\u00eame et aller jusqu\u2019\u00e0 Koh Phangan ou Koh Tao.<\/strong><\/p>\n<figure id=\"attachment_10644\" aria-describedby=\"caption-attachment-10644\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10644\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha.jpg\" alt=\"ko samui\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-10644\" class=\"wp-caption-text\">Le Big Buddha de Koh Samui<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>1\u00e8re \u00e9tape : vol Chiang Mai &#8211; Surat Thani<\/h2>\n<p>Air Asia est la seule compagnie \u00e0 l&#8217;heure actuelle \u00e0 proposer des <strong>vols directs entre Chiang Mai et Surat Thani<\/strong>. Cela dure un peu moins de 2 heures. Il y a 2 vols par jour.<\/p>\n<p>Moi, j&#8217;ai pris le vol de 13h05 mais il semble qu&#8217;il changera d&#8217;horaire dans quelques semaines et passera \u00e0 11h10 ce qui est encore plus pratique, pour aller \u00e0 Koh Samui, Koh Phangan et Koh Tao sans arriver trop tard (surtout pour Koh Tao).<\/p>\n<figure id=\"attachment_11646\" aria-describedby=\"caption-attachment-11646\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11646\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-surat-samui-vol-direct.jpg\" alt=\"vol chiang mai surat thani\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-surat-samui-vol-direct.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-surat-samui-vol-direct-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-surat-samui-vol-direct-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11646\" class=\"wp-caption-text\">Air Asia est la seule compagnie a proposer des vols directs entre Chiang Mai et Surat Thani<\/figcaption><\/figure>\n<p><strong>Pour obtenir un bon prix, je vous conseille de r\u00e9server \u00e0 l&#8217;avance\u00a0<\/strong>sur le site de la compagnie\u00a0minimum 1 mois avant. En derni\u00e8re minute, c&#8217;est sensiblement plus cher. A 2 avec un bagage en soute de 20 kilos pour 2 (+2 bagages cabines autoris\u00e9s jusqu&#8217;\u00e0 7 kilos chacun), on a pay\u00e9 2024 THB chacun pour tout le voyage avion + bus jusqu&#8217;\u00e0 l&#8217;embarcad\u00e8re + ferry jusqu&#8217;\u00e0 Samui. Car oui, vous pouvez directement au moment de la r\u00e9servation sur le site d\u2019Air Asia, choisir <strong>&#8220;Koh Samui&#8221;<\/strong> comme destination finale.<\/p>\n<figure id=\"attachment_11647\" aria-describedby=\"caption-attachment-11647\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11647\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/reservation-avion-chiang-mai-surat-thani.jpg\" alt=\"avion chiang mai surat\" width=\"750\" height=\"529\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/reservation-avion-chiang-mai-surat-thani.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/reservation-avion-chiang-mai-surat-thani-569x401.jpg 569w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/reservation-avion-chiang-mai-surat-thani-624x440.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11647\" class=\"wp-caption-text\">Il suffit de taper &#8220;Samui&#8221; dans le champs d&#8217;arriv\u00e9e<\/figcaption><\/figure>\n<p>J&#8217;ai compar\u00e9 le prix du package complet Air Asia avec le prix d&#8217;un vol + package bus + ferry achet\u00e9 s\u00e9par\u00e9ment, et Air Asia n&#8217;\u00e9tait pas plus cher. Cela ne veux pas dire que c&#8217;est forc\u00e9ment toujours le cas, fa\u00eetes des simulations.<\/p>\n<p>Vous pouvez retrouver les <a href=\"http:\/\/12go.asia\/fr\/travel\/surat-thani\/koh-samui?z=1332\" target=\"_blank\" rel=\"nofollow\"><strong>prix et horaires des formules bus + ferry pour Samui depuis l&#8217;a\u00e9roport de Surat Thani ici<\/strong><\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2>2\u00e8me \u00e9tape : bus pour Donsak<\/h2>\n<p>Une fois \u00e0 l&#8217;a\u00e9roport de Surat Thani, la r\u00e9cup\u00e9ration des bagages se passe tr\u00e8s tr\u00e8s vite. Il n&#8217;y a qu&#8217;un seul tapis et les premi\u00e8res valises (enfin le 1er bagage \u00e9tait une caisse de Chang mais bon ;)) sont arriv\u00e9s moins de 5 minutes. Difficile de faire plus rapide !<\/p>\n<p>En sortant dans le hall, vous allez voir tous les guichets des diff\u00e9rentes agences qui proposent toutes des transferts vers Koh Samui, Koh Phangan et Koh Tao et vers la ville de Surat Thani. Si vous n&#8217;avez pas d\u00e9j\u00e0 achet\u00e9 votre billet pour la suite du voyage, fa\u00eetes le tour des guichets et prenez celui qui vous convient le mieux en fonction du prix, de l&#8217;heure de d\u00e9part ect&#8230;<\/p>\n<p>Si vous avez comme moi, tout pris sur le site d&#8217;Air Asia, vous verrez un guichet avec de gros fanions rouges <em>&#8220;Check-in Here&#8221;<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11648\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-surat-samui-air-asia.jpg\" alt=\"surat thani air asia\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-surat-samui-air-asia.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-surat-samui-air-asia-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-surat-samui-air-asia-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Vous leur tendez votre billet d&#8217;avion et ils vous remettent un autocollant \u00e0 coller sur votre chemise et votre billet pour le bus pour <strong>Donsak<\/strong>, c&#8217;est de l\u00e0 que partent les ferry pour les \u00eeles. Vous pouvez aussi acheter un transfert en minivan vers votre h\u00f4tel une fois \u00e0 Koh Samui pour 200 THB. Je vous le recommande, c&#8217;est pratique et un taxi co\u00fbtera probablement plus cher (je n&#8217;en ai d&#8217;ailleurs pas vu pr\u00e8s de l&#8217;embarcad\u00e8re d&#8217;arriv\u00e9e).<\/p>\n<figure id=\"attachment_11649\" aria-describedby=\"caption-attachment-11649\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11649\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chianfg-mai-surat-samui-9.jpg\" alt=\"Le petit autocollant que l'on vous met pour continuer vers Donsak\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chianfg-mai-surat-samui-9.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chianfg-mai-surat-samui-9-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chianfg-mai-surat-samui-9-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11649\" class=\"wp-caption-text\">Le petit autocollant que l&#8217;on vous met pour continuer vers Donsak<\/figcaption><\/figure>\n<p>Vous sortez de l&#8217;a\u00e9roport et on vous dirige vers votre bus. Montre en main entre mon arriv\u00e9e devant le tapis pour r\u00e9cup\u00e9rer ma valise et le moment o\u00f9 je suis mont\u00e9 dans le bus, il s&#8217;est \u00e0 peine \u00e9coul\u00e9 plus de 10 minutes. Apr\u00e8s il y a eu un peu d&#8217;attente le temps que le bus se remplisse. Il a d\u00e9marr\u00e9 \u00e0 15h30 (j&#8217;ai atterri \u00e0 14h55). Direction Donsak, l\u00e0 o\u00f9 se trouve les embarcad\u00e8res des diff\u00e9rentes compagnies de ferry. Air Asia travaille avec Raja Ferry.<\/p>\n<figure id=\"attachment_11650\" aria-describedby=\"caption-attachment-11650\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11650\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-surat-thani-airport-donsak.jpg\" alt=\"bus pour donsak\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-surat-thani-airport-donsak.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-surat-thani-airport-donsak-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-surat-thani-airport-donsak-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11650\" class=\"wp-caption-text\">Voici mon bus pour Donsak<\/figcaption><\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11652\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-pour-donsak.jpg\" alt=\"bus-pour-donsak\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-pour-donsak.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-pour-donsak-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-pour-donsak-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>3\u00e8me \u00e9tape : ferry Donsak &#8211; Koh Samui<\/h2>\n<p>Apr\u00e8s 1h30 de route avec quelques slaloms pas toujours rassurants pour \u00e9viter les branches d&#8217;arbre qui ne posent aucun souci aux voitures mais ab\u00eemeraient le bus, arriv\u00e9e \u00e0 l\u2019embarcad\u00e8re de Raja Ferry. La encore, dans les bureaux, un comptoir d\u00e9di\u00e9 \u00e0 Air Asia \u00e0 qui on montre nos billets d&#8217;avion pour recevoir nos tickets de ferry. Bien organis\u00e9 !<\/p>\n<p>Il y a juste apr\u00e8s un comptoir pour les bagages &#8220;encombrants&#8221; qu&#8217;ils peuvent vous prendre en charge moyennant 30 bahts. Mais vous pouvez vous en passer et monter vous-m\u00eame votre valise \u00e0 bord. A vous de voir. 30 THB c&#8217;est moins d&#8217;un euro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11654\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-donsak-koh-samui.jpg\" alt=\"ferry donsak samui phangan\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-donsak-koh-samui.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-donsak-koh-samui-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-donsak-koh-samui-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<figure id=\"attachment_11653\" aria-describedby=\"caption-attachment-11653\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11653\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-surat-thani-samui.jpg\" alt=\"ferry donsak samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-surat-thani-samui.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-surat-thani-samui-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-surat-thani-samui-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11653\" class=\"wp-caption-text\">Le ferry, Raja Ferry<\/figcaption><\/figure>\n<p>A cette \u00e9tape, si vous \u00eates rapides et un peu chanceux vous pourrez peut-\u00eatre attraper le ferry plus t\u00f4t. Pour ma part celui de 17h ayant un peu de retard, j&#8217;ai pu monter dedans au lieu de prendre celui de 18h comme initialement pr\u00e9vu. \u00a0On est le seuls du bus d\u2019ailleurs \u00e0 avoir pu prendre le ferry pr\u00e9c\u00e9dent, les autres ont gentillement attendu dans la salle d&#8217;attente \ud83d\ude09<\/p>\n<p>Sur le ferry vous avez un petit magasin pour acheter de quoi boire et grignoter (chips et nouilles instantan\u00e9es).<\/p>\n<p>En route, petit coucher de soleil et arriv\u00e9e de nuit \u00e0 Koh Samui, \u00e0 Lipa No\u00ef, l\u00e0 o\u00f9 se trouve le Raja Ferry Pier apr\u00e8s 1h30 de travers\u00e9e.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11655\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/sunset-donsak-samui.jpg\" alt=\"coucher soleil donsak\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/sunset-donsak-samui.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/sunset-donsak-samui-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/sunset-donsak-samui-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11656\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-nuit-donsak-samui.jpg\" alt=\"ferry nuit samui\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-nuit-donsak-samui.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-nuit-donsak-samui-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/ferry-nuit-donsak-samui-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Reste \u00e0 descendre du bateau et monter dans le minivan qui vous emm\u00e8nera \u00e0 votre h\u00f4tel apr\u00e8s lui avoir remis les billets (achet\u00e9s au comptoir \u00e0 l&#8217;a\u00e9roport de <a href=\"\/villes\/surat-thani\">Surat Thani<\/a>) en lui expliquant o\u00f9 se trouve votre h\u00f4tel \u00a0et vous voil\u00e0 install\u00e9s \u00e0\u00a0Koh Samui.<\/p>\n<p>Tout ceci est une options parmi beaucoup d&#8217;autres pour rejoindre Koh Slaui et les \u00eeles voisines mais c&#8217;est une des plus populaires et un bon compromis temps de trajet\/ prix. \u00a0Vous pouvez retrouver d&#8217;autres fa\u00e7ons de venir \u00e0 Samui sur la page <a href=\"\/villes\/arriver-partir-koh-samui\"><em>&#8220;Arriver\/partir&#8221;<\/em><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De Chiang Mai, on a parfois envie d&#8217;aller directement sur une \u00eele, un \u00eele du<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-11642","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiang Mai - Koh Samui en avion via Surat Thani<\/title>\n<meta name=\"description\" content=\"Pour aller de Chiang Mai \u00e0 Koh Samui, une solution, c&#039;est de prendre l&#039;avion jusqu&#039;\u00e0 Surat Thani et ensuite de continuer en bus puis bateau jusqu\u2019\u00e0 Samui\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiang Mai - Koh Samui en avion via Surat Thani\" \/>\n<meta property=\"og:description\" content=\"Pour aller de Chiang Mai \u00e0 Koh Samui, une solution, c&#039;est de prendre l&#039;avion jusqu&#039;\u00e0 Surat Thani et ensuite de continuer en bus puis bateau jusqu\u2019\u00e0 Samui\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-24T11:20:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-24T12:59:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiang Mai - Koh Samui en avion via Surat Thani","description":"Pour aller de Chiang Mai \u00e0 Koh Samui, une solution, c'est de prendre l'avion jusqu'\u00e0 Surat Thani et ensuite de continuer en bus puis bateau jusqu\u2019\u00e0 Samui","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani","og_locale":"fr_FR","og_type":"article","og_title":"Chiang Mai - Koh Samui en avion via Surat Thani","og_description":"Pour aller de Chiang Mai \u00e0 Koh Samui, une solution, c'est de prendre l'avion jusqu'\u00e0 Surat Thani et ensuite de continuer en bus puis bateau jusqu\u2019\u00e0 Samui","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-09-24T11:20:42+00:00","article_modified_time":"2017-09-24T12:59:43+00:00","og_image":[{"url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Chiang Mai &#8211; Koh Samui en avion via Surat Thani","datePublished":"2017-09-24T11:20:42+00:00","dateModified":"2017-09-24T12:59:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani"},"wordCount":1085,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani","url":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani","name":"Chiang Mai - Koh Samui en avion via Surat Thani","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha.jpg","datePublished":"2017-09-24T11:20:42+00:00","dateModified":"2017-09-24T12:59:43+00:00","description":"Pour aller de Chiang Mai \u00e0 Koh Samui, une solution, c'est de prendre l'avion jusqu'\u00e0 Surat Thani et ensuite de continuer en bus puis bateau jusqu\u2019\u00e0 Samui","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani#primaryimage","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/big-buddha.jpg","width":750,"height":500,"caption":"Le Big Buddha de Koh Samui"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11642-chiang-mai-koh-samui-en-avion-via-surat-thani#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Chiang Mai &#8211; Koh Samui en avion via Surat Thani"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=11642"}],"version-history":[{"count":5,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11642\/revisions"}],"predecessor-version":[{"id":11660,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11642\/revisions\/11660"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=11642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=11642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=11642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}