{"id":11126,"date":"2017-06-27T16:20:03","date_gmt":"2017-06-27T14:20:03","guid":{"rendered":"https:\/\/www.thailandee.com\/blog\/?p=11126"},"modified":"2025-01-17T06:35:03","modified_gmt":"2025-01-17T04:35:03","slug":"rendez-vous-en-terre-inconnue-thailande","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande","title":{"rendered":"Rendez-vous en terre inconnue en Tha\u00eflande"},"content":{"rendered":"<p>Je pense que comme moi vous \u00eates nombreux \u00e0 avoir regard\u00e9 la superbe \u00e9mission de Fr\u00e9d\u00e9ric Lopez<em><strong> &#8220;Rendez-vous en terre inconnue&#8221;<\/strong><\/em> et \u00e0 avoir eu envie de vivre une exp\u00e9rience comme \u00e7a. Et bien en Tha\u00eflande, c&#8217;est possible ! Je viens de passer le week-end <a href=\"\/excursions-activites\/bytype\/sejours-en-immersion-en-thailande-15\">en immersion dans un village Karen<\/a> perch\u00e9 dans les montagnes de la province de Chiang Mai \u00e0 partager pour ce (trop) court s\u00e9jour, la vie des habitants. Une belle exp\u00e9rience que je ne vous raconterai volontairement pas trop en d\u00e9tails car chaque s\u00e9jour l\u00e0-haut est unique. Le mien comme le v\u00f4tre si vous d\u00e9cidez de vivre la m\u00eame exp\u00e9rience Ce que je vous recommande chaudement de faire ! \ud83d\ude09<\/p>\n<figure id=\"attachment_11129\" aria-describedby=\"caption-attachment-11129\" style=\"width: 1080px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11129\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande.jpg\" alt=\"rendez vous terre inconnue thailande\" width=\"1080\" height=\"608\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande.jpg 1080w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande-712x401.jpg 712w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande-1024x576.jpg 1024w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande-800x450.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption id=\"caption-attachment-11129\" class=\"wp-caption-text\">Vous n&#8217;avez jamais r\u00eav\u00e9 de vivre &#8220;Rendez-vous en terre inconnue ?&#8221;<\/figcaption><\/figure>\n<h2>Partager la vie\u00a0d&#8217;un village Karen<\/h2>\n<p>Pour ce week-end, j&#8217;ai \u00e9t\u00e9 invit\u00e9 par Pauline, une fran\u00e7aise qui avec son mari, Tham qui est Karen a cr\u00e9\u00e9 <a href=\"\/excursions-activites\/sejour-en-immersion-dans-un-village-karen-de-chiang-mai-154\">Evasion Karen<\/a> et vous propose de venir vivre quelques jours dans le village de son mari et de partager leur vie et leurs activit\u00e9s.<\/p>\n<p>Vous \u00eates plong\u00e9s dans la vie d&#8217;un village des montagnes authentique et accueillis comme des amis voire des membres de la famille. Et malgr\u00e9 la barri\u00e8re de la langue, vous arrivez \u00e0 \u00e9changer\u00a0et \u00e0 partager des moments \u00e9tonnants avec eux pour peu que vous osiez car ils sont tr\u00e8s ouverts et\u00a0heureux de vous faire d\u00e9couvrir leur quotidien\u00a0et de vous y int\u00e9grer un petit peu. D&#8217;ailleurs, je vous donne un petit mot en\u00a0langue karen bien utile que Pauline vous rappellera : <em>&#8220;tableu&#8221;<\/em> qui sert \u00e0 dire bonjour, au revoir et merci. Ca vous aidera \u00e0 faire le 1er pas. Si vous connaissez un peu le Tha\u00ef, la jeune g\u00e9n\u00e9ration le parle. Avec Pee Pee, la grand-m\u00e8re de Tham, le Tha\u00ef ne vous sera pas d&#8217;une grande utilit\u00e9\u00a0car elle ne parle que karen mais elle exprime beaucoup de choses rien qu&#8217;avec les expressions de son visage ou son regard.<\/p>\n<figure id=\"attachment_11130\" aria-describedby=\"caption-attachment-11130\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11130\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-109.jpg\" alt=\"karen chiang mai\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-109.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-109-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-109-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-11130\" class=\"wp-caption-text\">Tham et sa grand-m\u00e8re<\/figcaption><\/figure>\n<h2>Au rythme de la nature et des culture<\/h2>\n<p>Les karens de ce village vivent essentiellement de la culture du riz, du chou et des oignons qui rythment l&#8217;ann\u00e9e et changent le paysage en fonction des saisons. Qui dit culture du riz dans les montagnes, dit rizi\u00e8res en terasses. Les rizi\u00e8res qui demandent le plus de travail pour \u00eatre cultiv\u00e9es mais qui offrent les plus beaux paysages.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11131\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-217.jpg\" alt=\"rizieres chiang mai\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-217.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-217-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-217-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Moi, j&#8217;avais volontairement choisi le moment de la <strong>repique du riz<\/strong> pour venir. Elle a lieu en g\u00e9n\u00e9ral autour de d\u00e9but juillet (cette ann\u00e9e on est un peu en avance car la saison des pluies a d\u00e9marr\u00e9 plus t\u00f4t et plus fort que d&#8217;ordinaire). C&#8217;est quelque chose que j&#8217;ai toujours voulu faire dans ce type de d\u00e9cor. Evidemment, pour moi, c&#8217;est amusant \u00e0 faire mais pour eux, c&#8217;est un travail fatigant mais fait dans une ambiance de bonne humeur et d&#8217;entre-aide \u00e9tonnante. Et ma pr\u00e9sence, et il faut bien le dire mon peu de dext\u00e9rit\u00e9 dans le geste pour repiquer les plants dans la terre et la <em>&#8220;refermer&#8221;<\/em> dessus, ont d\u00e9clench\u00e9 beaucoup de fous rires.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/uL89PEKDGQA\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>J&#8217;ai \u00e9galement particip\u00e9 \u00e0 la r\u00e9colte des choux, fait un petit trek dans la montagne, suis parti chercher des pousses de bambou pour le repas du soir et les ai cuisin\u00e9s avec Tham, ai jou\u00e9 les \u00e9quilibristes sur les petites s\u00e9paration en terre des rizi\u00e8res, suis all\u00e9 voir un moine tr\u00e8s int\u00e9ressant dans un temple pour lui poser plein de questions sur le bouddhisme&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11132\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-298.jpg\" alt=\"champs chiang mai\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-298.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-298-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/evasion-karen-298-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Et c&#8217;est une toute petite partie de ce qu&#8217;on peut faire l\u00e0-haut. Pauline et Tham s&#8217;adaptent \u00e0 vos envies. C&#8217;est vraiment du sur mesure mais pas du sur mesure immuable. Tout est spontan\u00e9, rien n&#8217;est fig\u00e9 parce que c&#8217;est comme \u00e7a que l&#8217;on vit dans la montagne et comme \u00e7a qu&#8217;on appr\u00e9cie au mieux ce s\u00e9jour hors du commun.<\/p>\n<h2>Tham et Pauline, Evasion Karen<\/h2>\n<p>Je ne vous ai volontairement pas trop dit ce que vous ferez si vous venez parce qu&#8217;il n&#8217;y a pas de programme, formule ou autre mot pour d\u00e9signer une organisation r\u00e9gl\u00e9e comme du papier \u00e0 musique. Et c&#8217;est tant mieux ! Le principe de Pauline et Tham est justement de vous permettre de profiter du cadre exceptionnel de ce petit coin de montagne et de vous laisser vivre spontan\u00e9ment et choisir (en pouvant changer d&#8217;avis) les moments de vie et activit\u00e9s que vous voulez mettre dans votre s\u00e9jour qui sera unique. Vous seuls l&#8217;aurez v\u00e9cu.<\/p>\n<p><em>Si vous choisissez de venir, on viendra vous chercher \u00e0 votre guesthouse en voiture et vous y ram\u00e8nera en fin de s\u00e9jour.<\/em><\/p>\n<p>Si l&#8217;exp\u00e9rience vous tente, et franchement, je vous le recommande, <a href=\"\/excursions-activites\/sejour-en-immersion-dans-un-village-karen-de-chiang-mai-154\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><strong>contactez Pauline<\/strong> <\/a>pour discutez avec elle car chaque s\u00e9jour se fait apr\u00e8s une \u00e9change personnalis\u00e9 avec vous. Pour ma part, je reviendrai s\u00fbrement un jour car 2 jours c&#8217;est court. Peut-\u00eatre fin octobre ou d\u00e9but novembre, cette fois, pour la r\u00e9colte du riz.<\/p>\n<p><em><strong>Evasion Karen<\/strong><\/em><br \/>\n<em>Pr\u00e8s de Chiang Mai.<\/em><br \/>\n<em>Contact via le formulaire au bas de <strong>cette page<\/strong> : <a href=\"https:\/\/www.thailandee.com\/excursions-activites\/sejour-en-immersion-dans-un-village-karen-de-chiang-mai-154\" rel=\"nofollow\">www.thailandee.com\/excursions-activites\/sejour-en-immersion-dans-un-village-karen-de-chiang-mai-154<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je pense que comme moi vous \u00eates nombreux \u00e0 avoir regard\u00e9 la superbe \u00e9mission de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-11126","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rendez-vous en terre inconnue en Tha\u00eflande<\/title>\n<meta name=\"description\" content=\"Comme moi vous \u00eates nombreux \u00e0 avoir regard\u00e9 &quot;Rendez-vous en terre inconnue&quot; et avoir eu envie de vivre la m\u00eame chose ? En Tha\u00eflande, c&#039;est possible !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rendez-vous en terre inconnue en Tha\u00eflande\" \/>\n<meta property=\"og:description\" content=\"Comme moi vous \u00eates nombreux \u00e0 avoir regard\u00e9 &quot;Rendez-vous en terre inconnue&quot; et avoir eu envie de vivre la m\u00eame chose ? En Tha\u00eflande, c&#039;est possible !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-27T14:20:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-17T04:35:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rendez-vous en terre inconnue en Tha\u00eflande","description":"Comme moi vous \u00eates nombreux \u00e0 avoir regard\u00e9 \"Rendez-vous en terre inconnue\" et avoir eu envie de vivre la m\u00eame chose ? En Tha\u00eflande, c'est possible !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande","og_locale":"fr_FR","og_type":"article","og_title":"Rendez-vous en terre inconnue en Tha\u00eflande","og_description":"Comme moi vous \u00eates nombreux \u00e0 avoir regard\u00e9 \"Rendez-vous en terre inconnue\" et avoir eu envie de vivre la m\u00eame chose ? En Tha\u00eflande, c'est possible !","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-06-27T14:20:03+00:00","article_modified_time":"2025-01-17T04:35:03+00:00","og_image":[{"url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Rendez-vous en terre inconnue en Tha\u00eflande","datePublished":"2017-06-27T14:20:03+00:00","dateModified":"2025-01-17T04:35:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande"},"wordCount":897,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande","url":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande","name":"Rendez-vous en terre inconnue en Tha\u00eflande","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande.jpg","datePublished":"2017-06-27T14:20:03+00:00","dateModified":"2025-01-17T04:35:03+00:00","description":"Comme moi vous \u00eates nombreux \u00e0 avoir regard\u00e9 \"Rendez-vous en terre inconnue\" et avoir eu envie de vivre la m\u00eame chose ? En Tha\u00eflande, c'est possible !","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande#primaryimage","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/rendez-vous-en-terre-inconnue-thailande.jpg","width":1080,"height":608,"caption":"Vous n'avez jamais r\u00eav\u00e9 de vivre \"Rendez-vous en terre inconnue ?\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11126-rendez-vous-en-terre-inconnue-thailande#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Rendez-vous en terre inconnue en Tha\u00eflande"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=11126"}],"version-history":[{"count":14,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11126\/revisions"}],"predecessor-version":[{"id":19980,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11126\/revisions\/19980"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=11126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=11126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=11126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}