{"id":11016,"date":"2017-06-20T02:55:58","date_gmt":"2017-06-20T00:55:58","guid":{"rendered":"https:\/\/www.thailandee.com\/blog\/?p=11016"},"modified":"2017-06-21T02:57:18","modified_gmt":"2017-06-21T00:57:18","slug":"preparez-votre-voyage-en-thailande-en-videos","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos","title":{"rendered":"Pr\u00e9parez votre voyage en Tha\u00eflande en vid\u00e9os"},"content":{"rendered":"<p>Depuis que j&#8217;ai lanc\u00e9 le site, je me suis rendu compte que malgr\u00e9 des explications que j&#8217;essaie de rendre le\u00a0plus d\u00e9taill\u00e9es et le plus pr\u00e9cises possible, ce n&#8217;est pas toujours \u00e9vident de vraiment comprendre ou savoir quoi faire une fois sur le terrain. Le mieux, c&#8217;\u00e9tait de vous monter\u00a0tout \u00e7a en vid\u00e9o. C&#8217;est pour \u00e7a que j&#8217;ai lanc\u00e9 ma cha\u00eene Youtube, il y a presque un an. Pour ceux qui ne l&#8217;a connaissent pas encore, <a href=\"https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ\/videos\" target=\"_blank\" rel=\"nofollow\"><strong>cliquez ici pour la d\u00e9couvrir<\/strong><\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11017\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video.jpg\" alt=\"videos thailande\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Des vid\u00e9os pratiques qui vous expliquent pas \u00e0 pas\u00a0<\/h2>\n<p>En un an, je n&#8217;ai pas ch\u00f4m\u00e9 avec <strong>d\u00e9j\u00e0 plus de 70 vid\u00e9os publi\u00e9es<\/strong> dans lesquelles, je vous pr\u00e9sentent des lieux \u00e0 visiter en vous expliquant comment venir, les diff\u00e9rents transports \u00e0 Bangkok, des march\u00e9s de nuit, des \u00eeles, le meilleur de plusieurs destinations et m\u00eame la fabrication des traditionnels radeaux pour la f\u00eate de Loy Krathong en novembre.<\/p>\n<p>J&#8217;essaie \u00e0 chaque fois d&#8217;\u00eatre le plus complet possible et de vous montrer, cam\u00e9ra GoPro \u00e0 la main, comment les choses se passent, comment \u00e7a marche, ce qu&#8217;il faut faire et \u00e0 quoi \u00e7a ressemble. Pour vous rendre les choses plus faciles une fois sur place.\u00a0<\/p>\n<p>Et s&#8217;il y a d\u00e9j\u00e0 beaucoup beaucoup de sujets abord\u00e9s, j&#8217;ai encore du stock et vais continuer \u00e0 aller filmer sur le terrain et vais donc tr\u00e8s r\u00e9guli\u00e8rement ajouter d&#8217;autres vid\u00e9os. Le meilleur moyen de n&#8217;en rater aucune (et accessoirement de m&#8217;encourager \u00e0 continuer ;)), c&#8217;est de vous <strong>abonner \u00e0 ma cha\u00eene Youtube en <a href=\"https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ\/videos\" target=\"_blank\" rel=\"nofollow\">cliquant sur ce lien<\/a><\/strong> puis sur le bouton rouge\u00a0<em>&#8220;S&#8217;abonner&#8221;<\/em>\u00a0en haut \u00e0 droite et pour \u00eatre s\u00fbr d&#8217;\u00eatre averti \u00e0 chaque nouvelle vid\u00e9o vous pouvez m\u00eame cliquer sur la cloche \u00e0 c\u00f4t\u00e9 ensuite.<\/p>\n<p>&nbsp;<\/p>\n<h2>Vid\u00e9os les plus vues<\/h2>\n<ul>\n<li>Ma vid\u00e9o pratique la plus regard\u00e9e est celle qui vous explique <strong>comment \u00e7a se passe une fois arriv\u00e9 \u00e0 l&#8217;a\u00e9roport de Bangkok<\/strong> (Immigration, visa, bagages, changer de l&#8217;argent, rejoindre la ville&#8230;). Qualitativement, j&#8217;ai fait bien mieux apr\u00e8s mais le contenu de la vid\u00e9o aidera ceux qui viennent pour la 1\u00e8re fois.<br \/><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/4vmfC_0zTxU\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>\n<\/li>\n<li><strong>Le fameux trail de Krabi<\/strong> qui offre une des vues les plus incroyables qu&#8217;il m&#8217;ait \u00e9t\u00e9 donn\u00e9 de voir a aussi \u00e9t\u00e9\u00a0tr\u00e8s appr\u00e9ci\u00e9 et ma vid\u00e9o a donn\u00e9 envie \u00e0 plusieurs personnes d&#8217;y aller. Ils sont\u00a0tous revenus ravis \ud83d\ude09<br \/><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/SzlHmLvmZmw\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>\n<\/li>\n<li>J&#8217;ai \u00e9galement mis en ligne des vid\u00e9os explicatives sur tous les types de <a href=\"\/transports\/transports-a-bangkok\"><strong>transports en communs \u00e0 Bangkok<\/strong><\/a>. La plus vue \u00e9tant celle consacr\u00e9e au BTS, le m\u00e9tro a\u00e9rien de la ville. Une excellent fa\u00e7on de se d\u00e9placer en \u00e9vitant les bouchons. Mais il y a d&#8217;autres options pour se d\u00e9placer \u00e0 Bangkok<br \/><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/a8VyzUA5NuE\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>\n<\/li>\n<\/ul>\n<p>Je vous laisse aller d\u00e9couvrir le reste sur <a href=\"https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ\/videos\"><strong>YOUTUBE<\/strong><\/a>&#8230;<\/p>\n<p>&nbsp;<\/p>\n<h2>Des vid\u00e9os en plus des explications du site<\/h2>\n<p>Le site <em>Thailandee.com<\/em> regorge d&#8217;informations que je travaille quotidiennement \u00e0 \u00e9toffer et mettre \u00e0 jour. J&#8217;y ai maintenant int\u00e9gr\u00e9 les vid\u00e9os sur les pages de chaque destinations et sur les pages de d\u00e9tail des lieux \u00e0 visiter pour lesquels j&#8217;ai d\u00e9j\u00e0 fait une vid\u00e9o pratique.<\/p>\n<p>Elles sont \u00e9galement pr\u00e9sentes dans la rubrique <a href=\"\/videos\/\"><strong><em>&#8220;Vid\u00e9os&#8221;<\/em><\/strong><\/a> du site avec la possibilit\u00e9 de les filtrer par ville. Je vous invite \u00e0 prendre le temps de visionner les vid\u00e9os des destinations de votre prochain voyage, vous serez plus \u00e0 l&#8217;aise sur place et peut-\u00eatre m\u00eame qu&#8217;elles vous donneront des id\u00e9es\u00a0pour am\u00e9liorer votre programme. Elles pourront m\u00eame vous faire \u00e9conomiser de l&#8217;argent en vous expliquant comment emprunter les transports locaux. Une exp\u00e9rience souvent plus amusante que juste prendre un taxi ou un tuk-tuk.<\/p>\n<p>Oui, je sais, cet article ressemble un peu \u00e0 de l&#8217;auto-promotion mais faire ces vid\u00e9os, c&#8217;est beaucoup de travail, bien plus que de juste \u00e9crire un article et actuellement mes articles \u00e9crits restent beaucoup plus consult\u00e9s et partag\u00e9s. Pourtant je suis persuad\u00e9 que ces vid\u00e9os sont bien plus utiles car plus concr\u00e8tes.<\/p>\n<p>Et piti\u00e9, ne m&#8217;accusez pas de courir apr\u00e8s de la <em>&#8220;Youtube money&#8221;<\/em>, je ne suis pas Pierre Croce, je n&#8217;aspire pas en vivre et heureusement car sinon je serais dans la panade ! En 1 an, j&#8217;ai cumul\u00e9 60 dollars pour plus de 70 vid\u00e9os qui repr\u00e9sente en moyenne 3 heures de boulot chacune sans parler des\u00a0frais d\u00e9pens\u00e9s pour faire ce que je vous y montre. Bref, si je faisais \u00e7a pour l&#8217;argent de Youtube, j&#8217;aurais arr\u00eat\u00e9 depuis longtemps \ud83d\ude09 Apr\u00e8s si \u00e7a me permet un jour d&#8217;investir dans un peu plus de matos pour monter en qualit\u00e9, tant mieux !<\/p>\n<p><em>N&#8217;h\u00e9sitez pas \u00e0 partager mes vid\u00e9o ou ma cha\u00eene \u00e0 tous ceux qui pr\u00e9parent un voyage en Tha\u00eflande ou sur les r\u00e9seaux sociaux. <strong>Kho Khun Krap !<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis que j&#8217;ai lanc\u00e9 le site, je me suis rendu compte que malgr\u00e9 des explications<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-11016","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e9parez votre voyage en Tha\u00eflande en vid\u00e9os<\/title>\n<meta name=\"description\" content=\"Rien de mieux que des vid\u00e9os explicatives pour pr\u00e9parer son voyage en Tha\u00eflande. Checkez celles-ci.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9parez votre voyage en Tha\u00eflande en vid\u00e9os\" \/>\n<meta property=\"og:description\" content=\"Rien de mieux que des vid\u00e9os explicatives pour pr\u00e9parer son voyage en Tha\u00eflande. Checkez celles-ci.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-20T00:55:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-21T00:57:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9parez votre voyage en Tha\u00eflande en vid\u00e9os","description":"Rien de mieux que des vid\u00e9os explicatives pour pr\u00e9parer son voyage en Tha\u00eflande. Checkez celles-ci.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9parez votre voyage en Tha\u00eflande en vid\u00e9os","og_description":"Rien de mieux que des vid\u00e9os explicatives pour pr\u00e9parer son voyage en Tha\u00eflande. Checkez celles-ci.","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-06-20T00:55:58+00:00","article_modified_time":"2017-06-21T00:57:18+00:00","og_image":[{"url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Pr\u00e9parez votre voyage en Tha\u00eflande en vid\u00e9os","datePublished":"2017-06-20T00:55:58+00:00","dateModified":"2017-06-21T00:57:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos"},"wordCount":819,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos","url":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos","name":"Pr\u00e9parez votre voyage en Tha\u00eflande en vid\u00e9os","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video.jpg","datePublished":"2017-06-20T00:55:58+00:00","dateModified":"2017-06-21T00:57:18+00:00","description":"Rien de mieux que des vid\u00e9os explicatives pour pr\u00e9parer son voyage en Tha\u00eflande. Checkez celles-ci.","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos#primaryimage","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/thailande-en-video.jpg","width":750,"height":500,"caption":"videos thailande"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11016-preparez-votre-voyage-en-thailande-en-videos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Pr\u00e9parez votre voyage en Tha\u00eflande en vid\u00e9os"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=11016"}],"version-history":[{"count":2,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11016\/revisions"}],"predecessor-version":[{"id":11090,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11016\/revisions\/11090"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=11016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=11016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=11016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}