{"id":11002,"date":"2017-06-04T11:31:51","date_gmt":"2017-06-04T09:31:51","guid":{"rendered":"https:\/\/www.thailandee.com\/blog\/?p=11002"},"modified":"2017-06-18T05:13:24","modified_gmt":"2017-06-18T03:13:24","slug":"escapades-en-train-depuis-bangkok","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok","title":{"rendered":"3 escapades en train depuis Bangkok"},"content":{"rendered":"<p>J&rsquo;aime beaucoup <a href=\"\/transports\/train-thailande\">voyager en train en Tha\u00eflande<\/a> et m\u00eame si la modernisation des rames emportera probablement une partie du charme de cette exp\u00e9rience, elle prendra encore un peu de temps. J&rsquo;en profite donc pour vous recommander 3<strong>\u00a0escapades en trains au d\u00e9part de\u00a0Bangkok<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11003\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok.jpg\" alt=\"escapades train bangkok\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok-713x401.jpg 713w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok-624x351.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Escapade au Mae Klong Railway Market<\/h2>\n<p>C&rsquo;est s\u00fbrement\u00a0l&rsquo;escapade en train la plus \u00e9tonnante que l&rsquo;on puisse faire en partant de Bangkok. Le\u00a0<a href=\"\/a-voir\/marche-sur-la-voie-ferree-de-mae-klong-amphawa-62\">Mae Klong Railway Market<\/a> est un march\u00e9 install\u00e9 sur une voie de chemin de fer en activit\u00e9 qui voit chaque jour passer\u00a04 trains dans chaque sens. Et donc forc\u00e9ment, il a fallu s&rsquo;organiser pour pouvoir rapidement plier les \u00e9tales\u00a0pour\u00a0laisser passer le train. Le ballet des hauts-vents qui\u00a0se plient et des pr\u00e9sentoirs sur rails et roulettes qui se r\u00e9tractent puis se remettent en place d\u00e9s que l&rsquo;arri\u00e8re du train est pass\u00e9 est amusant \u00e0 voir.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10950\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/mae-klong-railway-market-rom-hup.jpg\" alt=\"mae-klong-railway-market-rom-hup\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/mae-klong-railway-market-rom-hup.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/mae-klong-railway-market-rom-hup-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/mae-klong-railway-market-rom-hup-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Si ce march\u00e9 est de plus en plus connu, l&rsquo;immense majorit\u00e9 des voyageurs le visitent depuis la voie mais c&rsquo;est encore mieux de se trouver dans le train qui passe au milieu du march\u00e9, d&rsquo;en descendre et puis de se d\u00e9p\u00eacher d&rsquo;aller au coeur du march\u00e9 pour le revoir passer dans l&rsquo;autre sens (pour \u00e7a il faut prendre le train qui arrive \u00e0 11h10, il repart \u00e0 11h30). C&rsquo;est ce que je vous propsoe de faire avec cette escapade. En plus, c&rsquo;est toute une aventure puisqu&rsquo;il faut prendre un 1er train, changer de gare en\u00a0traversant une rivi\u00e8re en bateau et reprendre un second train.<\/p>\n<p>Je vous explique tout \u00e7a en d\u00e9tail <a href=\"\/blog\/index.php\/10949-visiter-le-mae-klong-railway-market-en-train-depuis-\">dans cet article<\/a>\u00a0et franchement m\u00eame si \u00e7a \u00e0 l&rsquo;air compliqu\u00e9 comme \u00e7a, si vous voulez vivre une journ\u00e9e diff\u00e9rente, je vous le recommande. En suivant mes instructions et<a href=\"https:\/\/www.youtube.com\/watch?v=V8vmPwNeohk\"><strong> regardant cette vid\u00e9o<\/strong><\/a> dans laquelle je vous montre tout,\u00a0ce sera facile.<\/p>\n<p><strong>Budget \u00e0 pr\u00e9voir :<\/strong>\u00a052 bahts (aller\/retour) par personne pour le train et le bateau.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/V8vmPwNeohk\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2>Visiter Ayutthaya depuis Bangkok \u00e0 la journ\u00e9e<\/h2>\n<p>Ayutthaya, ancienne capitale du Royaume de Siam, poss\u00e8de encore beaucoup de ruines de temples datant de son apog\u00e9e. C&rsquo;est une vraie plong\u00e9e dans l&rsquo;histoire de la Tha\u00eflande dans une petite ville de province encercl\u00e9e d&rsquo;une rivi\u00e8re.\u00a0<\/p>\n<p>L\u00e0 aussi, venir ici en train \u00e0 la journ\u00e9e depuis Bangkok est facile et vous promet de passer une belle journ\u00e9e de visites. Le matin, prenez le <a href=\"\/transports\/train\/trains-de-bangkok-a-ayutthaya\">train\u00a0Bangkok &#8211; Ayutthaya<\/a> de 7h ou celui de 8h30 <em>(<a href=\"\/transports\/train\/trains-de-bangkok-a-ayutthaya\" target=\"_blank\" rel=\"nofollow\">horaires complets ici<\/a>). <\/em>Les billets s&rsquo;ach\u00e8tent au comptoir de la gare Hua Lamphong pas besoin de les prendre \u00e0 l&rsquo;avance. Une fois arriv\u00e9s \u00e0 destination, louez des v\u00e9los (entre 30 et 50 THB la journ\u00e9e) ou un tuk-tuk pour la journ\u00e9e (400-600 THB) et partez \u00e0 la d\u00e9couverte des temples d&rsquo;Ayutthaya, en ville et en p\u00e9riph\u00e9rie. Et le soir, retour en train (ou en van si vous pr\u00e9f\u00e9rez) sur Bangkok avec le train de 18h10 par exemple ou un train un peu plus plus t\u00f4t.<\/p>\n<p><strong>Budget \u00e0 pr\u00e9voir :<\/strong>\u00a030 bahts (aller\/retour en train) &#8211; 30 \u00e0\u00a050 THB (location de v\u00e9lo) &#8211; de l&rsquo;ordre de 200-300 bahts pour les prix d&rsquo;entr\u00e9e de certains temples.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/koF9RNTn9WU\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/><em>Vous retrouvez toutes les explications dans cette vid\u00e9o pratique sur la visite d&rsquo;Ayutthaya depuis Bangkok et dans la partie principale du\u00a0site sur la page consacr\u00e9e \u00e0 Ayutthaya la liste des temples \u00e0 visiter.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Aller voir le grand Chedi de Nakhon Pathom<\/h2>\n<p>La ville de Nakhon Pathom se trouve \u00e0 une cinquantaine de kilom\u00e8tres de Bangkok. Elle n&rsquo;est pas souvent au programme des touristes \u00e9trangers pourtant, on y trouve le\u00a0<a href=\"\/a-voir\/phra-pathom-chedi-nakhon-pathom-210\">Wat Phra Pathom Chedi<\/a> avec son immense chedi r\u00e9put\u00e9 plus grand monument bouddhiste du monde. Et il est superbe !<\/p>\n<p>La ville poss\u00e8de aussi un palais royal qui n&rsquo;est certes pas le plus int\u00e9ressant du pays mais que vous pouvez combiner \u00e0 votre visite du temple.<\/p>\n<p>Pour venir en train, il faut aller \u00e0 la gare de Thonburi \u00e0 Bangkok <em>(<a href=\"\/transports\/train\/trains-de-thonburi-a-nakhon-pathom\">horaires ICI<\/a>). <\/em>Une\u00a0demie-journ\u00e9e suffit car outre le temple et son grand chedi et le Sanam Chan Palace, le palais royal, il n&rsquo;y a pas grand chose d&rsquo;autre \u00e0 voir \u00e0 Nakhon Pathom m\u00eame. M\u00eame si le soir un sympathique march\u00e9 de nuit s&rsquo;installe sur le parking du temple. Vu les horaires des trains si vous retournez sur la capitale en train, vous n&rsquo;aurez pas le temps d&rsquo;en profiter.<\/p>\n<figure id=\"attachment_9420\" aria-describedby=\"caption-attachment-9420\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9420\" src=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nakhon-pathom-thailande.jpg\" alt=\"nakhon pathom\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nakhon-pathom-thailande.jpg 700w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nakhon-pathom-thailande-601x401.jpg 601w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/nakhon-pathom-thailande-624x416.jpg 624w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-9420\" class=\"wp-caption-text\">Le grand chedi de Nakhon Pathom<\/figcaption><\/figure>\n<p><em>Cette escapade int\u00e9ressera\u00a0surtout les passionn\u00e9s de temple car le chedi de Nakhon Pathom est unique en son genre.<\/em><\/p>\n<p>Evidemment, il est possible d&rsquo;aller visiter ces endroits en prenant un bus ou un minivan mais je vous assure que l&rsquo;exp\u00e9rience n&rsquo;est pas la m\u00eame ! Mais ces escapades en train ne s&rsquo;adressent peut-\u00eatre pas aux voyageurs press\u00e9s \ud83d\ude09<\/p>\n<p><em>Pour\u00a0d&rsquo;autres id\u00e9es de visites expliqu\u00e9es en vid\u00e9o, abonnez-vous \u00e0 \u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ\"><strong>ma cha\u00eene Youtube<\/strong><\/a>.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;aime beaucoup voyager en train en Tha\u00eflande et m\u00eame si la modernisation des rames emportera<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-11002","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 escapades en train depuis Bangkok<\/title>\n<meta name=\"description\" content=\"Voici 3 escapades en trains au d\u00e9part de Bangkok tr\u00e8s int\u00e9ressantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 escapades en train depuis Bangkok\" \/>\n<meta property=\"og:description\" content=\"Voici 3 escapades en trains au d\u00e9part de Bangkok tr\u00e8s int\u00e9ressantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-04T09:31:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-18T03:13:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok\"},\"author\":{\"name\":\"Mike Thailandee\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#\\\/schema\\\/person\\\/81de2c00b06eafce517ef9c7ce602274\"},\"headline\":\"3 escapades en train depuis Bangkok\",\"datePublished\":\"2017-06-04T09:31:51+00:00\",\"dateModified\":\"2017-06-18T03:13:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok\"},\"wordCount\":829,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/escapades-train-bangkok.jpg\",\"articleSection\":[\"Voyager en Tha\u00eflande\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok\",\"name\":\"3 escapades en train depuis Bangkok\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/escapades-train-bangkok.jpg\",\"datePublished\":\"2017-06-04T09:31:51+00:00\",\"dateModified\":\"2017-06-18T03:13:24+00:00\",\"description\":\"Voici 3 escapades en trains au d\u00e9part de Bangkok tr\u00e8s int\u00e9ressantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok#primaryimage\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/escapades-train-bangkok.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/escapades-train-bangkok.jpg\",\"width\":750,\"height\":422,\"caption\":\"escapades train bangkok\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/11002-escapades-en-train-depuis-bangkok#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.thailandee.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 escapades en train depuis Bangkok\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/\",\"name\":\"Le blog de Thailandee.com\",\"description\":\"voyage, conseils et informations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#organization\",\"name\":\"Le blog de Thailandee.com\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/voyage-thailande.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/wp-content\\\/uploads\\\/voyage-thailande.jpg\",\"width\":450,\"height\":248,\"caption\":\"Le blog de Thailandee.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ThailandeeFR\\\/\",\"https:\\\/\\\/x.com\\\/Thailandee_com\",\"http:\\\/\\\/instagram.com\\\/mikethailandee\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtClWMihNeyM_LhAXloywZQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/#\\\/schema\\\/person\\\/81de2c00b06eafce517ef9c7ce602274\",\"name\":\"Mike Thailandee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g\",\"caption\":\"Mike Thailandee\"},\"description\":\"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.\",\"sameAs\":[\"http:\\\/\\\/www.thailandee.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/ThailandeeFR\",\"https:\\\/\\\/x.com\\\/http:\\\/\\\/twitter.com\\\/Thailandee_com\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtClWMihNeyM_LhAXloywZQ\"],\"url\":\"https:\\\/\\\/www.thailandee.com\\\/blog\\\/index.php\\\/author\\\/asianmike\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 escapades en train depuis Bangkok","description":"Voici 3 escapades en trains au d\u00e9part de Bangkok tr\u00e8s int\u00e9ressantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok","og_locale":"fr_FR","og_type":"article","og_title":"3 escapades en train depuis Bangkok","og_description":"Voici 3 escapades en trains au d\u00e9part de Bangkok tr\u00e8s int\u00e9ressantes.","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-06-04T09:31:51+00:00","article_modified_time":"2017-06-18T03:13:24+00:00","og_image":[{"url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"3 escapades en train depuis Bangkok","datePublished":"2017-06-04T09:31:51+00:00","dateModified":"2017-06-18T03:13:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok"},"wordCount":829,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok","url":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok","name":"3 escapades en train depuis Bangkok","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok.jpg","datePublished":"2017-06-04T09:31:51+00:00","dateModified":"2017-06-18T03:13:24+00:00","description":"Voici 3 escapades en trains au d\u00e9part de Bangkok tr\u00e8s int\u00e9ressantes.","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok#primaryimage","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/escapades-train-bangkok.jpg","width":750,"height":422,"caption":"escapades train bangkok"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/11002-escapades-en-train-depuis-bangkok#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"3 escapades en train depuis Bangkok"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=11002"}],"version-history":[{"count":2,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11002\/revisions"}],"predecessor-version":[{"id":11019,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/11002\/revisions\/11019"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=11002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=11002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=11002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}