{"id":10312,"date":"2017-02-01T11:01:17","date_gmt":"2017-02-01T09:01:17","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=10312"},"modified":"2017-02-01T11:01:17","modified_gmt":"2017-02-01T09:01:17","slug":"vers-une-hausse-du-prix-des-vols-interieurs-en-thailande","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande","title":{"rendered":"Vers une hausse du prix des vols int\u00e9rieurs en Tha\u00eflande"},"content":{"rendered":"<p>Je vous le dis souvent, les prix des vols int\u00e9rieurs en Tha\u00eflande sont particuli\u00e8rement attractifs mais ce sera un peu moins le cas dans quelques jours . La faute \u00e0 une hausse tr\u00e8s importante (pr\u00e8s de 2000%) de la taxe d&#8217;accise sur le k\u00e9ros\u00e8ne&#8230;<\/p>\n<figure id=\"attachment_10314\" aria-describedby=\"caption-attachment-10314\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10314\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871.jpg\" alt=\"augmentation prix vols thailande\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871-602x401.jpg 602w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-10314\" class=\"wp-caption-text\">Les compagnies annoncent une augmentation de 150 THB par passager sur les vols int\u00e9rieurs en Tha\u00eflande<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Billets d&#8217;avion 150 THB\u00a0plus chers<\/h2>\n<p>Le gouvernement tha\u00eflandais a augment\u00e9 la taxe sur le carburant sur tous les vols int\u00e9rieurs de 20 satang \u00e0 4 bahts par litre soit une hausse record de +1900%, pour la rapprocher des 6 bahts par litre sur le carburant diesel.<\/p>\n<p>Nok Air, Thai Lion Air et Thai Air Asia ont publi\u00e9 des d\u00e9clarations hier, indiquant qu&#8217;ils augmenteraient les tarifs sur les vols int\u00e9rieurs en Tha\u00eflande pour refl\u00e9ter cette augmentation ce qui correspondra \u00e0 <strong>un surco\u00fbt de 150 bahts par passager<\/strong>\u00a0et donc \u00e0 300 THB pour un aller-retour.<\/p>\n<p>Ce co\u00fbt suppl\u00e9mentaire sera inclus dans tous les tarifs affich\u00e9s sur le site internet\u00a0de Nok Air et Lion Air \u00e0 compter du 6 f\u00e9vrier 2017. Tandis qu&#8217;Air Asia l&#8217;applique d\u00e9s aujourd&#8217;hui.<\/p>\n<p><span style=\"background-color: #ffff99;\"><strong>\u00a0Je ne saurais donc trop vous conseiller de r\u00e9server vos billets d&#8217;avion avant cette date car apr\u00e8s ce sera plus cher.<\/strong><\/span><\/p>\n<p>D&#8217;ailleurs <strong>en ce moment Nok Air \u00e0 une promotion avec des vols \u00e0 830 bahts (22\u20ac)<\/strong>. Probablement la derni\u00e8re en-dessous des 900 THB.<\/p>\n<p><a href=\"http:\/\/www.nokair.com\/content\/en\/promotion\/Special-Deal.aspx\" target=\"_blank\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10313\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vols-thailande-promo-nok-air.jpg\" alt=\"promo vols interieurs thailande\" width=\"750\" height=\"335\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vols-thailande-promo-nok-air.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/vols-thailande-promo-nok-air-624x279.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p>Pour l&#8217;instant Bangkok Airways et Thai Smile n&#8217;ont pas communiqu\u00e9 sur le sujet mais devraient suivre le mouvement.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<h2>Pourquoi cette hausse des billets d&#8217;avion ?<\/h2>\n<p>Les compagnies de transport terrestre paient 6 bahts par litre de diesel de taxe d&#8217;accise, tandis que les compagnies a\u00e9riennes ont b\u00e9n\u00e9fici\u00e9 d&#8217;une taxe de 20 satang (100 satangs = 1 baht) pendant des ann\u00e9es. Ce qui cr\u00e9ait une concurrence d\u00e9loyale.<\/p>\n<p>Il est vrai que la diff\u00e9rence de prix entre un long trajet en bus et un vol domestique en Tha\u00eflande \u00e9tait jusque l\u00e0 d\u00e9risoire. Et m\u00eame dans certains cas, l&#8217;avion revenait moins cher.<\/p>\n<p>La taxe n&#8217;est pas appliqu\u00e9e aux vols internationaux originaires ou en transit en Tha\u00eflande.<\/p>\n<p>Ces 150 bahts suppl\u00e9mentaires par billet \u00e9quivalent quasiment \u00e0 4 euros\u00a0et seront int\u00e9gr\u00e9s directement au prix du billet.<\/p>\n<p>L&#8217;Association du Voyage Domestique en Tha\u00eflande craint\u00a0que l&#8217;augmentation de la taxe ait un impact n\u00e9gatif sur le tourisme int\u00e9rieur. Les vols \u00e9tant plus chers, ils seront moins attractifs. Les compagnies low-cost sont, selon lui, le principal moteur permettant aux Tha\u00eflandais urbains d&#8217;explorer leur pays en toute s\u00e9curit\u00e9 et \u00e0 des prix comp\u00e9titifs.<\/p>\n<p><a href=\"\/transports\/avion-thailande\">Voyager en avion en Tha\u00eflande<\/a> co\u00fbtera plus cher dans quelques jours mais <strong>vous avez encore jusqu&#8217;au 6 f\u00e9vrier pour b\u00e9n\u00e9ficier des prix sans augmentation chez <a href=\"http:\/\/www.nokair.com\/content\/en\/promotion\/Special-Deal.aspx\" target=\"_blank\" rel=\"nofollow\">Nok Air<\/a> et <a href=\"http:\/\/lionairthai.com\/en\/\" target=\"_blank\" rel=\"nofollow\">Lion Air<\/a>.<\/strong><\/p>\n<p><em><a href=\"http:\/\/twitter.com\/Thailandee_com\"><strong>Suivez-moi sur Twitter<\/strong> <\/a>pour ne manquer aucune information, bon plan ou nouveaut\u00e9 pour pr\u00e9parer votre voyage en Tha\u00eflande.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je vous le dis souvent, les prix des vols int\u00e9rieurs en Tha\u00eflande sont particuli\u00e8rement attractifs<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10312","post","type-post","status-publish","format-standard","hentry","category-fiches-pratiques-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vers une hausse du prix des vols int\u00e9rieurs en Tha\u00eflande<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vers une hausse du prix des vols int\u00e9rieurs en Tha\u00eflande\" \/>\n<meta property=\"og:description\" content=\"Je vous le dis souvent, les prix des vols int\u00e9rieurs en Tha\u00eflande sont particuli\u00e8rement attractifs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-01T09:01:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vers une hausse du prix des vols int\u00e9rieurs en Tha\u00eflande","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande","og_locale":"fr_FR","og_type":"article","og_title":"Vers une hausse du prix des vols int\u00e9rieurs en Tha\u00eflande","og_description":"Je vous le dis souvent, les prix des vols int\u00e9rieurs en Tha\u00eflande sont particuli\u00e8rement attractifs","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-02-01T09:01:17+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Vers une hausse du prix des vols int\u00e9rieurs en Tha\u00eflande","datePublished":"2017-02-01T09:01:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande"},"wordCount":505,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871.jpg","articleSection":["La Tha\u00eflande pratique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande","url":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande","name":"Vers une hausse du prix des vols int\u00e9rieurs en Tha\u00eflande","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871.jpg","datePublished":"2017-02-01T09:01:17+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/DSC02871.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10312-vers-une-hausse-du-prix-des-vols-interieurs-en-thailande#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Vers une hausse du prix des vols int\u00e9rieurs en Tha\u00eflande"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10312"}],"version-history":[{"count":1,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10312\/revisions"}],"predecessor-version":[{"id":10315,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10312\/revisions\/10315"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}