{"id":10297,"date":"2017-01-29T12:03:55","date_gmt":"2017-01-29T10:03:55","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=10297"},"modified":"2017-01-29T12:03:55","modified_gmt":"2017-01-29T10:03:55","slug":"chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie","title":{"rendered":"Chiang Mai \u00e9lue destination de golf 2017 en Asie et Australasie"},"content":{"rendered":"<p><a href=\"\/villes\/chiang-mai\"><strong>Chiang Mai<\/strong><\/a> est une ville qui offre de nombreuses opportunit\u00e9s et activit\u00e9s aux visiteurs : temples, cours de cuisine, treks dans la montagne, retraites yoga ou m\u00e9ditation, accrobranches&#8230; et aussi golf. La &#8220;Rose du Nord&#8221; a m\u00eame \u00e9t\u00e9 d\u00e9sign\u00e9e\u00a0\u00ab Destination de golf 2017 en Asie et Australasie \u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10299\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses.jpg\" alt=\"golf chiang mai\" width=\"925\" height=\"225\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses.jpg 925w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses-750x182.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses-624x152.jpg 624w\" sizes=\"auto, (max-width: 925px) 100vw, 925px\" \/><\/p>\n<p>La Tha\u00eflande compte plusieurs golfs parmi les plus r\u00e9put\u00e9s du monde et \u00e9videmment d&#8217;Asie. On cite souvent celui d&#8217;<a href=\"\/villes\/hua-hin\">Hua Hin<\/a> qui se trouve juste en face de la gare mais cette fois-ci, c&#8217;est celui de Chiang Mai qui a \u00e9t\u00e9 r\u00e9compens\u00e9.<\/p>\n<p>Apr\u00e8s Pattaya nomm\u00e9e en 2006 et 2010, Hua Hin recevant ce prix en 2012 et Prachuap Khiri Khan et son golf sur la base a\u00e9rienne en 2014, c&#8217;est la cinqui\u00e8me ann\u00e9e qu&#8217;une ville de Tha\u00eflande est\u00a0reconnue par l\u2019association internationale des voyagistes du golf (IAGTO).<\/p>\n<p>Ca fera donc une raison suppl\u00e9mentaire de venir das al capitale du Nord de la Tha\u00eflande mais de bonnes raisons de venir visiter\u00a0Chiang Mai, il en exstait d\u00e9j\u00e0 beaucoup ! \ud83d\ude09<\/p>\n<figure id=\"attachment_10298\" aria-describedby=\"caption-attachment-10298\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10298\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-best-golf-destination.jpg\" alt=\"chiang mai golf\" width=\"600\" height=\"401\" \/><figcaption id=\"caption-attachment-10298\" class=\"wp-caption-text\">Tanes Petsuwan &#8211; Deputy Director de la TAT re\u00e7oit la r\u00e9compense<\/figcaption><\/figure>\n<p>A noter que le Laguna Phuket Golf Club a \u00e9galement remport\u00e9 le prix 2017 du \u00ab Parcours de golf durable de l&#8217;ann\u00e9e pour la r\u00e9gion asiatique \u00bb.<\/p>\n<p>L\u2019IAGTO a \u00e9t\u00e9 cr\u00e9\u00e9e en 1997 pour repr\u00e9senter les int\u00e9r\u00eats de l\u2019industrie du golf dans le tourisme mondial. Elle compte maintenant 2 522 membres (tour-op\u00e9rateurs de golf accr\u00e9dit\u00e9s, centres de vill\u00e9giature et h\u00f4tels, compagnies a\u00e9riennes, offices de tourisme et partenaires commerciaux) dans 96 pays. Au total, 654 d&#8217;entre eux sont des tour-op\u00e9rateurs sp\u00e9cialis\u00e9s dans le golf et repr\u00e9sentent 61 pays.<\/p>\n<p>Les prix annuels de l&#8217;IAGTO existent depuis plus de 16 ans et repr\u00e9sentent le summum de la reconnaissance et de la r\u00e9ussite pour les destinations et resorts de golf.<\/p>\n<p><strong>Bravo \u00e0 Chiang Mai pour ce titre !<\/strong><\/p>\n<p>Vous pouvez retrouvez la liste des golfs de Chiang Mai <a href=\"http:\/\/www.chiangmaigolf.com\/golf-courses\/\" target=\"_blank\" rel=\"nofollow\"><strong>ICI<\/strong><\/a>.<\/p>\n<p><em>Palmar\u00e8s complet sur le site\u00a0<a href=\"http:\/\/www.iagto.com\">www.iagto.com<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chiang Mai est une ville qui offre de nombreuses opportunit\u00e9s et activit\u00e9s aux visiteurs :<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10297","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiang Mai \u00e9lue destination de golf 2017 en Asie et Australasie<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s Pattaya en 2006 et 2010, Hua Hin en 2012 et Prachuap Khiri Khan en 2014, Chiang Mai a \u00e9t\u00e9 d\u00e9sign\u00e9e &quot;Destination de golf 2017 en Asie et Australasie&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiang Mai \u00e9lue destination de golf 2017 en Asie et Australasie\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s Pattaya en 2006 et 2010, Hua Hin en 2012 et Prachuap Khiri Khan en 2014, Chiang Mai a \u00e9t\u00e9 d\u00e9sign\u00e9e &quot;Destination de golf 2017 en Asie et Australasie&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-29T10:03:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiang Mai \u00e9lue destination de golf 2017 en Asie et Australasie","description":"Apr\u00e8s Pattaya en 2006 et 2010, Hua Hin en 2012 et Prachuap Khiri Khan en 2014, Chiang Mai a \u00e9t\u00e9 d\u00e9sign\u00e9e \"Destination de golf 2017 en Asie et Australasie\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie","og_locale":"fr_FR","og_type":"article","og_title":"Chiang Mai \u00e9lue destination de golf 2017 en Asie et Australasie","og_description":"Apr\u00e8s Pattaya en 2006 et 2010, Hua Hin en 2012 et Prachuap Khiri Khan en 2014, Chiang Mai a \u00e9t\u00e9 d\u00e9sign\u00e9e \"Destination de golf 2017 en Asie et Australasie\"","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-01-29T10:03:55+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Chiang Mai \u00e9lue destination de golf 2017 en Asie et Australasie","datePublished":"2017-01-29T10:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie"},"wordCount":359,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie","url":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie","name":"Chiang Mai \u00e9lue destination de golf 2017 en Asie et Australasie","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses.jpg","datePublished":"2017-01-29T10:03:55+00:00","description":"Apr\u00e8s Pattaya en 2006 et 2010, Hua Hin en 2012 et Prachuap Khiri Khan en 2014, Chiang Mai a \u00e9t\u00e9 d\u00e9sign\u00e9e \"Destination de golf 2017 en Asie et Australasie\"","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-mai-golf-courses.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10297-chiang-mai-elue-destination-de-golf-2017-en-asie-et-australasie#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Chiang Mai \u00e9lue destination de golf 2017 en Asie et Australasie"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10297"}],"version-history":[{"count":1,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10297\/revisions"}],"predecessor-version":[{"id":10300,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10297\/revisions\/10300"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}