{"id":10280,"date":"2017-01-26T11:38:21","date_gmt":"2017-01-26T09:38:21","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=10280"},"modified":"2017-01-26T11:38:21","modified_gmt":"2017-01-26T09:38:21","slug":"ou-feter-le-nouvel-an-chinois-2017-a-bangkok","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok","title":{"rendered":"O\u00f9 f\u00eater le Nouvel An Chinois 2017 \u00e0 Bangkok ?"},"content":{"rendered":"<p>Apr\u00e8s l&#8217;annonce de l&#8217;annulation des c\u00e9l\u00e9brations dans le quartier chinois de Bangkok, il y a 2 jours, je me devais de refaire le point sur ce qu&#8217;il y aura effectivement \u00e0 dans la capitale tha\u00eflandaise cette ann\u00e9e pour marquer le <a href=\"\/evenements-thailande\/nouvel-an-chinois-124\"><strong>Nouvel An chinois 2017<\/strong><\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5385\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1.jpg\" alt=\"Nouvel An Chinois\" width=\"749\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1.jpg 749w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1-624x416.jpg 624w\" sizes=\"auto, (max-width: 749px) 100vw, 749px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>C\u00e9l\u00e9bration \u00e0 Chinatown annul\u00e9e<\/h2>\n<p>En raison de la p\u00e9riode de deuil suite au d\u00e9c\u00e8s du\u00a0Roi Bhumibol, le festival de rue qui se tient habituellement \u00a0\u00e0 Yaowarat a \u00e9t\u00e9 annul\u00e9. Cette d\u00e9cision est intervenue que tr\u00e8s tard (le 23 janvier). Je vous l&#8217;indiquais le jour-m\u00eame sur Facebook et Twitter.<\/p>\n<p>Mais ce n&#8217;est pas pour autant que l&#8217;entr\u00e9e dans l&#8217;ann\u00e9e du Coq ne sera pas f\u00eat\u00e9e \u00e0 <a href=\"\/villes\/bangkok\">Bangkok<\/a>.<\/p>\n<h2>C\u00e9l\u00e9brations du Nouvel An au Parc Lumphini<\/h2>\n<p>Le parc central de la capitale sera probablement le\u00a0lieu o\u00f9 cette ann\u00e9e, l&#8217;\u00e9v\u00e9nement sera le plus marqu\u00e9.<\/p>\n<p>Dans le cadre du grand festival du tourisme organis\u00e9 au Lumphini Park (25-29 janvier), de 14h \u00e0 22h, les visiteurs peuvent d\u00e9couvrir des repr\u00e9sentations chinoises traditionnelles, des plats chinois tout en respectant les dieux chinois.<\/p>\n<p>&nbsp;<\/p>\n<h2>Ateliers caligraphie<\/h2>\n<p>Des ateliers d\u00e9butants sur la calligraphie et l&#8217;aquarelle chinoises auront lieu le samedi et le dimanche (27-28 janvier) \u00e0 14h et \u00e0 17h au Think Space B2S au Central Festival EastVille dans le district de Lat Phrao. <em>\u00a0(300 bahts pour y participer).<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Places de cin\u00e9ma gratuites<\/h2>\n<p>Je vous le partageais ce matin sur <a href=\"https:\/\/twitter.com\/Thailandee_com\" target=\"_blank\" rel=\"nofollow\"><strong>mon compte Twitter<\/strong><\/a>, les cin\u00e9mas Major Cineplex \u00e0 Bangkok mais aussi dans tout le pays auront une grande op\u00e9ration promotionnelle samedi 28 janvier, jour du Nouvel An Chinois. Ils offriront leurs places de cin\u00e9ma aux 30.000 premeirs sectateurs qui se pr\u00e9senteront aux guichets en habits chinois et posteront leurs photos sur\u00a0Instagram.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-10282\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/1080x10808-1024x1024.jpg\" alt=\"cinea gratuit bangkok\" width=\"625\" height=\"625\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/1080x10808-1024x1024.jpg 1024w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/1080x10808-150x150.jpg 150w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/1080x10808-401x401.jpg 401w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/1080x10808-624x624.jpg 624w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/p>\n<h2>F\u00eates dans les bars de Bangkok<\/h2>\n<p>Certains pubs et bars lancent des \u00e9v\u00e9nements sous le th\u00e8me du Nouvel An Chinois.<\/p>\n<p>C&#8217;est le cas notamment du cabaret souterrain de Shanghai de Maggie Choo (<span class=\"td-sml-description\"><strong>Shanghai underground cabaret of Maggie Choo\u2019s<\/strong>)<\/span>\u00a0avec le spectacle de Pangina Heals \u00e0 21h dimanche, suivi par la musique des DJs Yui Truluv et Steven G. Drink\u00a0de 19h \u00e0 21h<em> (500 bahts, plus d&#8217;infos sur la page Facebook)<\/em>.<\/p>\n<p>La<strong> Biblioth\u00e8que Neilson Hays<\/strong> organisera une activit\u00e9 pour enfants de 10h30 \u00e0 12h30 samedi. Storytelling, arts et m\u00e9tiers, danseurs de lion et plus encore seront l\u00e0 avec go\u00fbters et boissons. Les membres peuvent payer 100 bahts par enfant, tandis que les billets pour les enfants des non-membres co\u00fbteront\u00a0200 bahts.<\/p>\n<p>&nbsp;<\/p>\n<h2>Fa\u00eetes du Shopping<\/h2>\n<p>La plupart des grands centres commerciaux de Bangkok organise des grandes promotions et \u00e9v\u00e9nements (surtout marketing) pour l&#8217;occasion.<\/p>\n<p>Le Central World, par exemple, accueillera un march\u00e9 r\u00e9tro \u00e0 th\u00e8me avec\u00a0stands de mode, vendeurs de jouets vintage et vendeurs de nourriture dans un environnement <em>(de vendredi \u00e0\u00a0dimanche).<\/em><\/p>\n<p><strong>Je vous conseille surtout d&#8217;aller \u00e0 Lumphini<\/strong>, outre la partie consacr\u00e9e au Nouvel An Chinois, il y a des dinosaures, des stands de nourriture, des danses, des activit\u00e9s&#8230; Vos enfants seront particuli\u00e8rement ravis et l&#8217;entr\u00e9e est gratuite.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s l&#8217;annonce de l&#8217;annulation des c\u00e9l\u00e9brations dans le quartier chinois de Bangkok, il y a<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-10280","post","type-post","status-publish","format-standard","hentry","category-festivals-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O\u00f9 f\u00eater le Nouvel An Chinois 2017 \u00e0 Bangkok ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O\u00f9 f\u00eater le Nouvel An Chinois 2017 \u00e0 Bangkok ?\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s l&#8217;annonce de l&#8217;annulation des c\u00e9l\u00e9brations dans le quartier chinois de Bangkok, il y a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-26T09:38:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O\u00f9 f\u00eater le Nouvel An Chinois 2017 \u00e0 Bangkok ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok","og_locale":"fr_FR","og_type":"article","og_title":"O\u00f9 f\u00eater le Nouvel An Chinois 2017 \u00e0 Bangkok ?","og_description":"Apr\u00e8s l&#8217;annonce de l&#8217;annulation des c\u00e9l\u00e9brations dans le quartier chinois de Bangkok, il y a","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-01-26T09:38:21+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"O\u00f9 f\u00eater le Nouvel An Chinois 2017 \u00e0 Bangkok ?","datePublished":"2017-01-26T09:38:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok"},"wordCount":525,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1.jpg","articleSection":["Ev\u00e9nements et Festivals"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok","url":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok","name":"O\u00f9 f\u00eater le Nouvel An Chinois 2017 \u00e0 Bangkok ?","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1.jpg","datePublished":"2017-01-26T09:38:21+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chinese-temple-nakhon-ratchasima1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10280-ou-feter-le-nouvel-an-chinois-2017-a-bangkok#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"O\u00f9 f\u00eater le Nouvel An Chinois 2017 \u00e0 Bangkok ?"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10280"}],"version-history":[{"count":3,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10280\/revisions"}],"predecessor-version":[{"id":10284,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10280\/revisions\/10284"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}