{"id":10187,"date":"2017-01-11T11:51:27","date_gmt":"2017-01-11T09:51:27","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=10187"},"modified":"2017-01-11T11:51:27","modified_gmt":"2017-01-11T09:51:27","slug":"lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn","title":{"rendered":"L&#8217;Isan dans les 17 meilleurs endroits \u00e0 visiter en 2017 selon CNN"},"content":{"rendered":"<p>Le <strong>Nord-est de la Tha\u00eflande<\/strong> qu&#8217;on appelle aussi <strong>Isan<\/strong> est la r\u00e9gion r\u00e9put\u00e9e la plus rurale et la plus pauvre du pays. Encore peu de touristes y vont pourtant, il y a beaucoup de choses \u00e0 y d\u00e9couvrir : des temples khmers, des paysages de campagnes superbes, des temples bouddhistes, des sites naturels magnifiques, les bords du M\u00e9kong, des festivals atypiques, ect&#8230;\u00a0<\/p>\n<figure id=\"attachment_7888\" aria-describedby=\"caption-attachment-7888\" style=\"width: 749px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7888\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung.jpg\" alt=\"phanom rung buriram\" width=\"749\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung.jpg 749w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung-624x417.jpg 624w\" sizes=\"auto, (max-width: 749px) 100vw, 749px\" \/><figcaption id=\"caption-attachment-7888\" class=\"wp-caption-text\">L&#8217;all\u00e9e pav\u00e9e du Phanom Rung (province de Buriram<\/figcaption><\/figure>\n<p>CNN ne s&#8217;y est pas tromp\u00e9e en int\u00e9grant la r\u00e9gion dans sa liste des <strong>17 destinations du monde \u00e0 visiter en 2017<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2>En 2017, visiter l&#8217;Isan !<\/h2>\n<p>Pour justifier son choix la cha\u00eene am\u00e9ricaine\u00a0vante notamment <em>&#8220;les anciennes ruines khm\u00e8res en dehors de Buriram&#8221;<\/em>, entendez le <strong><a href=\"\/a-voir\/le-phanom-rung-nang-rong-87\">Phanom Rung<\/a><\/strong> et la Muang Tham, <em>&#8220;les parcs nationaux montagnards\u00a0\u00e0 Loei&#8221;<\/em> et notamment le <strong>parc national de Phu Rua<\/strong>\u00a0et les objets de l&#8217;\u00e2ge du bronze dans le site arch\u00e9ologique de Ban Chiang dans la province d&#8217;Udon Thani, class\u00e9 par l&#8217;UNESCO.<\/p>\n<p>La cuisine de l&#8217;Isan est \u00e9galement r\u00e9put\u00e9e, souvent d\u00e9sign\u00e9e comme la plus go\u00fbteuse de Tha\u00eflande.\u00a0<\/p>\n<p>Personnellement, j&#8217;aime bien le Nord de l&#8217;Isaan, \u00e0 la fronti\u00e8re avec le Laos form\u00e9e par le fleuve M\u00e9kong, et des endroits comme <a href=\"\/villes\/chiang-khan\"><strong>Chiang Khan<\/strong><\/a> ou <strong>Nong Khai<\/strong> ou encore Bueng Khan qui gagne \u00e0 \u00eatre connue pour son impressionnant temple <strong>Wat Phu Tok<\/strong> mais aussi pour ses paysages de montagnes \u00e0 couper le souffle.<\/p>\n<p><figure id=\"attachment_6628\" aria-describedby=\"caption-attachment-6628\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6628\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/monks-alms-giving-thailand-1.jpg\" alt=\"Chiang Khan moines\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/monks-alms-giving-thailand-1.jpg 700w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/monks-alms-giving-thailand-1-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/monks-alms-giving-thailand-1-624x416.jpg 624w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-6628\" class=\"wp-caption-text\">Le tourn\u00e9e des moines \u00e0 Chiang Khan<\/figcaption><\/figure> <figure id=\"attachment_7887\" aria-describedby=\"caption-attachment-7887\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7887\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-khan-sunrise-6.jpg\" alt=\"Chiang Khan\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-khan-sunrise-6.jpg 700w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-khan-sunrise-6-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chiang-khan-sunrise-6-624x416.jpg 624w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7887\" class=\"wp-caption-text\">Lever de soleil \u00e0 Chiang Khan<\/figcaption><\/figure> <figure id=\"attachment_7303\" aria-describedby=\"caption-attachment-7303\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7303 size-full\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phu-tok-bueng-khan-22.jpg\" alt=\"Wat phu Tok Udon\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phu-tok-bueng-khan-22.jpg 700w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phu-tok-bueng-khan-22-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/wat-phu-tok-bueng-khan-22-624x416.jpg 624w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-7303\" class=\"wp-caption-text\">Le Wat Phu Tok pr\u00e8s de Bueng Khan<\/figcaption><\/figure><\/p>\n<p><em>Si vous voulez en savoir, jetez un oeil sur mon article sur <a href=\"\/blog\/index.php\/6668-essentiel-de-la-thailande-isan\"><strong>l&#8217;essentiel de ce qu&#8217;il y a \u00e0 voir en Isan<\/strong><\/a>. Article tr\u00e8s incomplet bien \u00e9videmment mais qui vous donnera des pistes pour une premi\u00e8re approche de cette r\u00e9gion\u00a0attachante.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Liste compl\u00e8te des 17 meilleurs sites \u00e0 voir en 2017 selon\u00a0CNN<\/strong><\/h2>\n<ol>\n<li>\u00a0\u00cele-du-Prince-\u00c9douard, Canada<\/li>\n<li>Penang, Malaisie<\/li>\n<li>Colombie<\/li>\n<li>Bermudes<\/li>\n<li>Katahdin Woods and Waters National Monument<\/li>\n<li><strong>\u00a0Isaan, Tha\u00eflande<\/strong><\/li>\n<li>Bhoutan<\/li>\n<li>Chengdu, Chine<\/li>\n<li>Aarhus, Danemark<\/li>\n<li><strong>Bordeaux, France<\/strong><\/li>\n<li>L&#8217;Islande occidentale<\/li>\n<li>Albanie<\/li>\n<li>Amman, Jordanie<\/li>\n<li>Rwanda<\/li>\n<li>S\u00e9n\u00e9gal<\/li>\n<li>Houston, \u00c9tats-Unis<\/li>\n<li>Australie<\/li>\n<\/ol>\n<p>Je ne commenterai pas le reste de la liste m\u00eame si on note la pr\u00e9sence de Bordeaux en 10\u00e8me position. Cocorico !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Nord-est de la Tha\u00eflande qu&#8217;on appelle aussi Isan est la r\u00e9gion r\u00e9put\u00e9e la plus<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-10187","post","type-post","status-publish","format-standard","hentry","category-fiches-visite-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Isan dans les 17 meilleurs endroits \u00e0 visiter en 2017 selon CNN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Isan dans les 17 meilleurs endroits \u00e0 visiter en 2017 selon CNN\" \/>\n<meta property=\"og:description\" content=\"Le Nord-est de la Tha\u00eflande qu&#8217;on appelle aussi Isan est la r\u00e9gion r\u00e9put\u00e9e la plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-11T09:51:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Isan dans les 17 meilleurs endroits \u00e0 visiter en 2017 selon CNN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn","og_locale":"fr_FR","og_type":"article","og_title":"L'Isan dans les 17 meilleurs endroits \u00e0 visiter en 2017 selon CNN","og_description":"Le Nord-est de la Tha\u00eflande qu&#8217;on appelle aussi Isan est la r\u00e9gion r\u00e9put\u00e9e la plus","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-01-11T09:51:27+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"L&#8217;Isan dans les 17 meilleurs endroits \u00e0 visiter en 2017 selon CNN","datePublished":"2017-01-11T09:51:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn"},"wordCount":412,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung.jpg","articleSection":["Voyager en Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn","url":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn","name":"L'Isan dans les 17 meilleurs endroits \u00e0 visiter en 2017 selon CNN","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung.jpg","datePublished":"2017-01-11T09:51:27+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/phanom-rung.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10187-lisan-dans-les-17-meilleurs-endroits-a-visiter-en-2017-selon-cnn#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"L&#8217;Isan dans les 17 meilleurs endroits \u00e0 visiter en 2017 selon CNN"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10187"}],"version-history":[{"count":1,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10187\/revisions"}],"predecessor-version":[{"id":10189,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10187\/revisions\/10189"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}