{"id":10131,"date":"2017-01-04T12:20:22","date_gmt":"2017-01-04T10:20:22","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=10131"},"modified":"2017-01-04T13:13:39","modified_gmt":"2017-01-04T11:13:39","slug":"transports-en-thailande-les-minivans-les-plus-dangereux","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux","title":{"rendered":"Transports Tha\u00eflande : les minivans les plus dangereux"},"content":{"rendered":"<p><strong>La s\u00e9curit\u00e9 routi\u00e8re en\u00a0<\/strong><b>Tha\u00eflande<\/b>\u00a0a encore beaucoup de progr\u00e8s \u00e0 faire. Les derniers jours tristement baptis\u00e9s<em> &#8220;7 dangerous days&#8221;<\/em> l&#8217;ont encore montr\u00e9. C&#8217;est dans ce contexte que des\u00a0statistiques publi\u00e9s aujourd&#8217;hui montrent que les\u00a0minivans de passager, auxquels je vous conseille de longue date de pr\u00e9f\u00e9rer le bus quand c&#8217;est possible <em>(voir notamment <a href=\"\/blog\/index.php\/9250-voyager-en-thailande-preferer-le-bus-ou-le-minivan\">cet article<\/a>)<\/em>, sont les modes de transports en commun les plus dangereux.<\/p>\n<figure id=\"attachment_3559\" aria-describedby=\"caption-attachment-3559\" style=\"width: 749px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3559 size-full\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand.jpg\" alt=\"minivan thailand\" width=\"749\" height=\"500\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand.jpg 749w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand-560x374.jpg 560w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand-624x416.jpg 624w\" sizes=\"auto, (max-width: 749px) 100vw, 749px\" \/><figcaption id=\"caption-attachment-3559\" class=\"wp-caption-text\">Sans surprise, les vans sont les transports les moins s\u00fbrs de Tha\u00eflande<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Les minivans transport le plus dangereux en Tha\u00eflande !<\/h2>\n<p>A voir la conduite plus que sportive pour ne pas dire irresponsable de certains\u00a0chauffeurs, pas vraiment besoin \u00a0de chiffres pour se rendre compte que les vans sont bien moins s\u00fbrs que les bus.<\/p>\n<p>Ils se\u00a0classent donc sans surprise num\u00e9ro de tous les services de transport public impliqu\u00e9s dans les accidents de la route avec une moyenne mensuelle de 19,5 accidents entra\u00eenant chaque mois en moyenne 9,4 d\u00e9c\u00e8s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10133\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/van-bus-accidents-thailande.jpg\" alt=\"van-bus-accidents-thailande\" width=\"750\" height=\"416\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/van-bus-accidents-thailande.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/van-bus-accidents-thailande-723x401.jpg 723w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/van-bus-accidents-thailande-624x346.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Ces statistiques sur les accidents de la route ci-dessus concernant les camionnettes ont \u00e9t\u00e9 communiqu\u00e9es par M. Kongsak Chuenkrailart, coordinateur du programme de s\u00e9curit\u00e9 des transports publics de la Fondation pour les consommateurs.<\/p>\n<p>La fondation a recueilli, en collaboration avec le Centre de la s\u00e9curit\u00e9 routi\u00e8re, des donn\u00e9es sur les accidents de la route concernant les transports en commun entre janvier et novembre 2016 et a constat\u00e9 que les vans\u00a0\u00e9taient impliqu\u00e9es dans<strong> 215 accidents de la route, soit en moyenne 19,5 accidents par mois. Ces accidents ont fait 103 morts\u00a0et 1102 bless\u00e9s<\/strong>.<\/p>\n<p>La conduite inconsciente\u00a0a \u00e9t\u00e9 point\u00e9e\u00a0comme la cause principale des accidents viennent ensuite\u00a0la mauvaise qualit\u00e9 de route et les\u00a0modifications ill\u00e9gales des v\u00e9hicules.<\/p>\n<p>En comparaison les\u00a0bus r\u00e9guliers sur les itin\u00e9raires fixes ont connu\u00a0sur la m\u00eame p\u00e9riode 141 accidents, avec 56 d\u00e9c\u00e8s et 1252 bless\u00e9s. Ce qui reste \u00e9lev\u00e9 mais confirment que vous \u00eates plus en s\u00e9curit\u00e9 dans un bus en Tha\u00eflande que dans un minivan et en plus souvent plus confortablement install\u00e9s.<\/p>\n<p>Au 31 octobre 2016, il y avait en tout 156.089 transports publics l\u00e9galement enregistr\u00e9\u00a0qui est divis\u00e9 en 42.202 minivans\u00a0de passagers, dont 16.002 fourgonnettes r\u00e9guli\u00e8res et 24.136 fourgonnettes irr\u00e9guli\u00e8res et 1.064 fourgonnettes priv\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<h2>Les raisons de ces mauvais chiffres<\/h2>\n<p>Malgr\u00e9 une obligation l\u00e9gale mise en place, il y a plus de 2 ans, la plupart des <a href=\"\/transports\/\">transports publics en Tha\u00eflande<\/a> ne disposent toujours pas de ceintures de s\u00e9curit\u00e9 fonctionnelles et de l&#8217;\u00e9quipement de s\u00e9curit\u00e9 \u00e0 bord. Et quand elles existent, forc\u00e9 de constater que personne ou presque ne les utilisent malgr\u00e9 le risque d&#8217;amende pour la compagnie et pour le passager. Il faut dire que je n&#8217;ai jamais\u00a0vu de contr\u00f4le sur ce sujet m\u00eame lorsque que le van o\u00f9 je me trouvais a subi une inspection surprise, une fois. La police a regard\u00e9 la pr\u00e9sence des ceintures mais j&#8217;\u00e9tais le seul passager a l&#8217;avoir boucl\u00e9 sans qu&#8217;il y ait la moindre r\u00e9flexion \u00e0 ce sujet.<\/p>\n<p>Parmi les autres raisons de ce mauvais chiffres, de nombreux conducteurs pas physiquement aptes \u00e0 la conduite en raison de sommeil insuffisant, la vitesse et la surcharge.<\/p>\n<p>Avec les 7 jours autour du Nouvel An qui sont chaque ann\u00e9e les plus meurtriers sur les routes de Tha\u00eflande (avec ceux autour de Songkran mi-avril) et\u00a0qui cette ann\u00e9e ont fait un nombre de victimes particuli\u00e8rement \u00e9lev\u00e9, les autorit\u00e9s semblent d\u00e9cid\u00e9es \u00e0 prendre des mesures pour limiter le nombre de vans, augmenter les contr\u00f4les et rendre le test th\u00e9orique du permis de conduire plus dur. Ca va dans le bon sens mais \u00e7a risque de ne pas suffire&#8230;<\/p>\n<figure id=\"attachment_8958\" aria-describedby=\"caption-attachment-8958\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8958\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-terminal-bangkok.jpg\" alt=\"terminaux bus bangkok\" width=\"750\" height=\"501\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-terminal-bangkok.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-terminal-bangkok-600x401.jpg 600w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/bus-terminal-bangkok-624x417.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-8958\" class=\"wp-caption-text\">Le bus transport le plus emprunt\u00e9 en Tha\u00eflande, reste plus s\u00fbr que les minivans&#8230;<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Pr\u00e9f\u00e9rez le bus !<\/h2>\n<p>Je l&#8217;ai d\u00e9j\u00e0 dit \u00e0 maintes reprises et \u00e9crit sur le site, si vous avez le choix, <strong>pr\u00e9f\u00e9rez le bus au minivan pour vos d\u00e9placements en Tha\u00eflande<\/strong>. Et si vous devez en prendre un, attachez votre ceinture et n&#8217;h\u00e9sitez pas \u00e0 faire des remarques si la conduite de votre chauffeur est imprudente. M\u00eame si \u00e7a n&#8217;a\u00a0souvent aucun effet.<\/p>\n<p>Vous pouvez consulter les horaires de bus et <strong>r\u00e9server en ligne ICI<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La s\u00e9curit\u00e9 routi\u00e8re en\u00a0Tha\u00eflande\u00a0a encore beaucoup de progr\u00e8s \u00e0 faire. Les derniers jours tristement baptis\u00e9s<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10131","post","type-post","status-publish","format-standard","hentry","category-thailande-infos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transports Tha\u00eflande : les minivans les plus dangereux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transports Tha\u00eflande : les minivans les plus dangereux\" \/>\n<meta property=\"og:description\" content=\"La s\u00e9curit\u00e9 routi\u00e8re en\u00a0Tha\u00eflande\u00a0a encore beaucoup de progr\u00e8s \u00e0 faire. Les derniers jours tristement baptis\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-04T10:20:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-04T11:13:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transports Tha\u00eflande : les minivans les plus dangereux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux","og_locale":"fr_FR","og_type":"article","og_title":"Transports Tha\u00eflande : les minivans les plus dangereux","og_description":"La s\u00e9curit\u00e9 routi\u00e8re en\u00a0Tha\u00eflande\u00a0a encore beaucoup de progr\u00e8s \u00e0 faire. Les derniers jours tristement baptis\u00e9s","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2017-01-04T10:20:22+00:00","article_modified_time":"2017-01-04T11:13:39+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Transports Tha\u00eflande : les minivans les plus dangereux","datePublished":"2017-01-04T10:20:22+00:00","dateModified":"2017-01-04T11:13:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux"},"wordCount":749,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand.jpg","articleSection":["Actualit\u00e9s Tha\u00eflande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux","url":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux","name":"Transports Tha\u00eflande : les minivans les plus dangereux","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand.jpg","datePublished":"2017-01-04T10:20:22+00:00","dateModified":"2017-01-04T11:13:39+00:00","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/minivan-thailand.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10131-transports-en-thailande-les-minivans-les-plus-dangereux#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Transports Tha\u00eflande : les minivans les plus dangereux"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10131"}],"version-history":[{"count":2,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10131\/revisions"}],"predecessor-version":[{"id":10135,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10131\/revisions\/10135"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}