{"id":10082,"date":"2016-12-30T12:52:38","date_gmt":"2016-12-30T10:52:38","guid":{"rendered":"http:\/\/www.thailandee.com\/blog\/?p=10082"},"modified":"2016-12-30T12:52:38","modified_gmt":"2016-12-30T10:52:38","slug":"programme-du-nouvel-an-2017-a-chiang-mai","status":"publish","type":"post","link":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai","title":{"rendered":"Programme du Nouvel An 2017 \u00e0 Chiang Mai"},"content":{"rendered":"<p>Apr\u00e8s le programme de la soir\u00e9e du Nouvel An au Central World de Bangkok, je vous publie celui des<strong> festivit\u00e9s du 31 d\u00e9cembre \u00e0 <a href=\"\/villes\/chiang-mai\">Chiang Mai<\/a><\/strong>, la capitale du Nord, qui attire beaucoup de monde \u00e0 cette occasion et notamment beaucoup de Tha\u00eflandais venus chercher un peu de fra\u00eecheur.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10083\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai.jpg\" alt=\"nouvel an chiang mai\" width=\"750\" height=\"278\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai-624x231.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Dans cet article, je ne vous parlerai pas des soir\u00e9es organis\u00e9es par les h\u00f4tels, restaurants et bars mais des c\u00e9l\u00e9brations officielles qui auront lieu dans 4\u00a0lieux principaux : le Monument des 3 Rois, le parc\u00a0floral Ratchaphruek\u00a0\u00e0 une quinzaine de kilom\u00e8tres de Chiang Mai et au Central Festival, un grand centre commercial \u00e0 la p\u00e9riph\u00e9rie sans oublier la Thapae Gate lieu incontournable de toute festivit\u00e9 \u00e0 Chiang Mai.<\/p>\n<p>Comme partout en Tha\u00eflande (enfin normalement), il n&#8217;y aura aucun feu d&#8217;artifice \u00e0 Chiang Mai cette ann\u00e9e pour respecter le deuil du pays mais il pourra y avoir quelques lanternes ascensionnelles.<\/p>\n<p>&nbsp;<\/p>\n<h2>Hommage au Roi Bhumibol au Monument des 3 Rois<\/h2>\n<p>Cette ann\u00e9e, un grand \u00e9v\u00e9nement intitul\u00e9 <em>\u00ab The Candle Light of Siam \u00bb<\/em> aura lieu dans plusieurs lieux \u00e0 travers la pays. A Chiang Mai, ce sera au<em> &#8220;Three Kings Monument&#8221;<\/em>\u00a0(\u00e0 Bangkok, ce sera au Sanam Luang devant le Grand Palais). \u00a0Il s&#8217;agit d&#8217;une grande veill\u00e9e aux bougies avec pri\u00e8res en hommage au Roi Rama 9 d\u00e9c\u00e9d\u00e9 le 13 octobre dernier et au nouveau Roi, Rama 10.<\/p>\n<ul>\n<li><strong>18h00<\/strong> : tambours traditionnels Lanna<\/li>\n<li><strong>19h50<\/strong> : spectacle pour sa Majest\u00e9<\/li>\n<li><strong>20h20 :<\/strong> concours de beaut\u00e9\u00a0hommes et femmes<\/li>\n<li><strong>20h50 :<\/strong> pri\u00e8res pour Sa Majest\u00e9 le Roi Bhumibol<\/li>\n<li><strong>21h05 :<\/strong> Orchestre de chambre de l&#8217;Universit\u00e9 de Chiang Mai<\/li>\n<li><strong>22h00 :<\/strong> chansons traditionnelles Lanna<\/li>\n<li><strong>23h00 :<\/strong>\u00a0chanson de jazz compos\u00e9e par\u00a0le d\u00e9funt Roi<\/li>\n<li><strong>23h45 :<\/strong> c\u00e9r\u00e9monie aux bougies et compte \u00e0 reboours avant 2017<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10084\" src=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chaing-mai-central-festival.jpg\" alt=\"central festival chiang mai\" width=\"750\" height=\"354\" srcset=\"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chaing-mai-central-festival.jpg 750w, https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/chaing-mai-central-festival-624x295.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Soir\u00e9e du Nouvel An au Central Festival<\/h2>\n<p>Comme chaque ann\u00e9e le centre commercial organisera son <strong>Chiang Mai Countdown Festival<\/strong> (sans feu d&#8217;artifice cette ann\u00e9e). D\u00e9but des concerts \u00e0 19:30 avec des artistes de The Voice, Blue Shade,\u00a0Tattoo Colour et \u00e9videmment un compte \u00e0 rebours et \u00e0 00h09 comme dans tout le pays illuminations de bougies.<\/p>\n<p>Le centre commercial MAYA organisera lui aussi une soir\u00e9e sur le m\u00eame principe avec des concerts et un compte \u00e0 rebours final.<\/p>\n<p>&nbsp;<\/p>\n<h2>C\u00e9l\u00e9brations dans les temples de Chiang Mai<\/h2>\n<p>Beaucoup de temples organiseront aussi des soir\u00e9es et nuit de pri\u00e8res et recueillement pour ce passage \u00e0 la nouvelle ann\u00e9e. En voici quelques unes&#8230;<\/p>\n<ul>\n<li>\u00a0<a href=\"\/a-voir\/wat-phra-that-doi-suthep-chiang-mai-15\">Wat Phra That Doi Suthep<\/a> (temple sur la colline) \u00e0 22:00<\/li>\n<li>Wat Chedi Luang \u00e0 21:00<\/li>\n<li>Wat Suan Dok \u00e0 22:00<\/li>\n<li>Wat Phra Singh \u00e0 21:00<\/li>\n<li>Wat Phan Tao \u00e0 23:30<\/li>\n<li>Wat lok Molee \u00e0 19:09<\/li>\n<\/ul>\n<p>Je vous souhaite un tr\u00e8s bon r\u00e9veillon et vous donne rendez-vous le 1er pour vous adresser mes voeux pour 2017.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s le programme de la soir\u00e9e du Nouvel An au Central World de Bangkok, je<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-10082","post","type-post","status-publish","format-standard","hentry","category-festivals-thailande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programme du Nouvel An 2017 \u00e0 Chiang Mai<\/title>\n<meta name=\"description\" content=\"Programme des festivit\u00e9s du Nouvel An 2017 \u00e0 Chiang Mai, capitale du Nord de la Tha\u00eflande\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programme du Nouvel An 2017 \u00e0 Chiang Mai\" \/>\n<meta property=\"og:description\" content=\"Programme des festivit\u00e9s du Nouvel An 2017 \u00e0 Chiang Mai, capitale du Nord de la Tha\u00eflande\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai\" \/>\n<meta property=\"og:site_name\" content=\"Le blog de Thailandee.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ThailandeeFR\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-30T10:52:38+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai.jpg\" \/>\n<meta name=\"author\" content=\"Mike Thailandee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/Thailandee_com\" \/>\n<meta name=\"twitter:site\" content=\"@Thailandee_com\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Thailandee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programme du Nouvel An 2017 \u00e0 Chiang Mai","description":"Programme des festivit\u00e9s du Nouvel An 2017 \u00e0 Chiang Mai, capitale du Nord de la Tha\u00eflande","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai","og_locale":"fr_FR","og_type":"article","og_title":"Programme du Nouvel An 2017 \u00e0 Chiang Mai","og_description":"Programme des festivit\u00e9s du Nouvel An 2017 \u00e0 Chiang Mai, capitale du Nord de la Tha\u00eflande","og_url":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai","og_site_name":"Le blog de Thailandee.com","article_publisher":"https:\/\/www.facebook.com\/ThailandeeFR\/","article_author":"https:\/\/www.facebook.com\/ThailandeeFR","article_published_time":"2016-12-30T10:52:38+00:00","og_image":[{"url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai.jpg","type":"","width":"","height":""}],"author":"Mike Thailandee","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/Thailandee_com","twitter_site":"@Thailandee_com","twitter_misc":{"\u00c9crit par":"Mike Thailandee","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai#article","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai"},"author":{"name":"Mike Thailandee","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274"},"headline":"Programme du Nouvel An 2017 \u00e0 Chiang Mai","datePublished":"2016-12-30T10:52:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai"},"wordCount":459,"commentCount":0,"publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai.jpg","articleSection":["Ev\u00e9nements et Festivals"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai","url":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai","name":"Programme du Nouvel An 2017 \u00e0 Chiang Mai","isPartOf":{"@id":"https:\/\/www.thailandee.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai#primaryimage"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai#primaryimage"},"thumbnailUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai.jpg","datePublished":"2016-12-30T10:52:38+00:00","description":"Programme des festivit\u00e9s du Nouvel An 2017 \u00e0 Chiang Mai, capitale du Nord de la Tha\u00eflande","breadcrumb":{"@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai#primaryimage","url":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai.jpg","contentUrl":"http:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/central-festival-chaing-mai.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandee.com\/blog\/index.php\/10082-programme-du-nouvel-an-2017-a-chiang-mai#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thailandee.com\/blog"},{"@type":"ListItem","position":2,"name":"Programme du Nouvel An 2017 \u00e0 Chiang Mai"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandee.com\/blog\/#website","url":"https:\/\/www.thailandee.com\/blog\/","name":"Le blog de Thailandee.com","description":"voyage, conseils et informations","publisher":{"@id":"https:\/\/www.thailandee.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandee.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thailandee.com\/blog\/#organization","name":"Le blog de Thailandee.com","url":"https:\/\/www.thailandee.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","contentUrl":"https:\/\/www.thailandee.com\/blog\/wp-content\/uploads\/voyage-thailande.jpg","width":450,"height":248,"caption":"Le blog de Thailandee.com"},"image":{"@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ThailandeeFR\/","https:\/\/x.com\/Thailandee_com","http:\/\/instagram.com\/mikethailandee","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"]},{"@type":"Person","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/81de2c00b06eafce517ef9c7ce602274","name":"Mike Thailandee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thailandee.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eafdf7d5103c114ea6914650dcf688962fb7a6032d77ecc8c572ba631864799b?s=96&d=mm&r=g","caption":"Mike Thailandee"},"description":"Tomb\u00e9 sous le charme de la Tha\u00eflande d\u00e8s son premier voyage , Mike ne cesse de parcourir le pays dans tous les sens depuis 2009 pour d\u00e9couvrir, tester et partager ses infos, photos, conseils et bons plans qu'il partage sur Thailandee.com.","sameAs":["http:\/\/www.thailandee.com\/","https:\/\/www.facebook.com\/ThailandeeFR","https:\/\/x.com\/http:\/\/twitter.com\/Thailandee_com","https:\/\/www.youtube.com\/channel\/UCtClWMihNeyM_LhAXloywZQ"],"url":"https:\/\/www.thailandee.com\/blog\/index.php\/author\/asianmike"}]}},"_links":{"self":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10082"}],"version-history":[{"count":1,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10082\/revisions"}],"predecessor-version":[{"id":10085,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10082\/revisions\/10085"}],"wp:attachment":[{"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandee.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}